{"id":2593,"date":"2018-02-12T23:51:04","date_gmt":"2018-02-12T22:51:04","guid":{"rendered":"http:\/\/asvpnf.com\/?page_id=2593"},"modified":"2018-03-29T13:13:59","modified_gmt":"2018-03-29T12:13:59","slug":"rechercher","status":"publish","type":"page","link":"https:\/\/asvpnf.com\/index.php\/rechercher\/","title":{"rendered":"Rechercher sur le site"},"content":{"rendered":"<p style=\"text-align: right;\"><em>les options de recherche sont accessibles par la fl\u00e8che devant la loupe<\/em><\/p>\n<h4><div id='ajaxsearchlite1' class=\"wpdreams_asl_container asl_w asl_m asl_m_1\">\r\n<div class=\"probox\">\r\n\r\n    \r\n    <div class='promagnifier'>\r\n                <div class='innericon'>\r\n            <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"512px\" height=\"512px\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\r\n                <path d=\"M460.355,421.59L353.844,315.078c20.041-27.553,31.885-61.437,31.885-98.037\r\n                    C385.729,124.934,310.793,50,218.686,50C126.58,50,51.645,124.934,51.645,217.041c0,92.106,74.936,167.041,167.041,167.041\r\n                    c34.912,0,67.352-10.773,94.184-29.158L419.945,462L460.355,421.59z M100.631,217.041c0-65.096,52.959-118.056,118.055-118.056\r\n                    c65.098,0,118.057,52.959,118.057,118.056c0,65.096-52.959,118.056-118.057,118.056C153.59,335.097,100.631,282.137,100.631,217.041\r\n                    z\"\/>\r\n            <\/svg>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    \r\n    \r\n    <div class='prosettings'  data-opened=0>\r\n                <div class='innericon'>\r\n            <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"512px\" height=\"512px\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\r\n                <polygon transform = \"rotate(90 256 256)\" points=\"142.332,104.886 197.48,50 402.5,256 197.48,462 142.332,407.113 292.727,256 \"\/>\r\n            <\/svg>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    \r\n    \r\n    <div class='proinput'>\r\n        <form autocomplete=\"off\" aria-label='Ajax search form'>\r\n            <input aria-label='Search input' type='search' class='orig' name='phrase' placeholder='Tapez votre recherche ici...' value='' autocomplete=\"off\"\/>\r\n            <input aria-label='Autocomplete input, do not use this' type='text' class='autocomplete' name='phrase' value='' autocomplete=\"off\"\/>\r\n            <input type='submit' value=\"Start search\" style='width:0; height: 0; visibility: hidden;'>\r\n        <\/form>\r\n    <\/div>\r\n\r\n    \r\n    \r\n    <div class='proloading'>\r\n\r\n        <div class=\"asl_loader\"><div class=\"asl_loader-inner asl_simple-circle\"><\/div><\/div>\r\n\r\n            <\/div>\r\n\r\n            <div class='proclose'>\r\n            <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\"\r\n                 y=\"0px\"\r\n                 width=\"512px\" height=\"512px\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\"\r\n                 xml:space=\"preserve\">\r\n            <polygon points=\"438.393,374.595 319.757,255.977 438.378,137.348 374.595,73.607 255.995,192.225 137.375,73.622 73.607,137.352 192.246,255.983 73.622,374.625 137.352,438.393 256.002,319.734 374.652,438.378 \"\/>\r\n        <\/svg>\r\n        <\/div>\r\n    \r\n    \r\n<\/div>\r\n<\/div>\r\n\r\n\r\n<div id='ajaxsearchlitesettings1' class=\"searchsettings wpdreams_asl_settings asl_w asl_s asl_s_1\">\r\n    <form name='options' autocomplete='off'>\r\n\r\n        \r\n        \r\n\t\t<div class=\"asl_option_inner hiddend\">\r\n\t\t\t<input type='hidden' name='qtranslate_lang' id='qtranslate_lang1'\r\n\t\t\t\t   value='0'\/>\r\n\t\t<\/div>\r\n\r\n\t\t\r\n\t\t\r\n        <fieldset class=\"asl_sett_scroll\">\r\n            <legend style=\"display: none;\">Generic selectors<\/legend>\r\n            <div class=\"asl_option\">\r\n                <div class=\"asl_option_inner\">\r\n                    <input type=\"checkbox\" value=\"exact\" id=\"set_exactonly1\"\r\n                           title=\"Termes exacts\"\r\n                           name=\"asl_gen[]\" \/>\r\n                    <label for=\"set_exactonly1\">Termes exacts<\/label>\r\n                <\/div>\r\n                <div class=\"asl_option_label\">\r\n                    Termes exacts                <\/div>\r\n            <\/div>\r\n            <div class=\"asl_option\">\r\n                <div class=\"asl_option_inner\">\r\n                    <input type=\"checkbox\" value=\"title\" id=\"set_intitle1\"\r\n                           title=\"Chercher dans les titres\"\r\n                           name=\"asl_gen[]\"  checked=\"checked\"\/>\r\n                    <label for=\"set_intitle1\">Chercher dans les titres<\/label>\r\n                <\/div>\r\n                <div class=\"asl_option_label\">\r\n                    Chercher dans les titres                <\/div>\r\n            <\/div>\r\n            <div class=\"asl_option\">\r\n                <div class=\"asl_option_inner\">\r\n                    <input type=\"checkbox\" value=\"content\" id=\"set_incontent1\"\r\n                           title=\"Chercher dans le contenu\"\r\n                           name=\"asl_gen[]\"  checked=\"checked\"\/>\r\n                    <label for=\"set_incontent1\">Chercher dans le contenu<\/label>\r\n                <\/div>\r\n                <div class=\"asl_option_label\">\r\n                    Chercher dans le contenu                <\/div>\r\n            <\/div>\r\n            <div class=\"asl_option_inner hiddend\">\r\n                <input type=\"checkbox\" value=\"excerpt\" id=\"set_inexcerpt1\"\r\n                       title=\"Search in excerpt\"\r\n                       name=\"asl_gen[]\" \/>\r\n                <label for=\"set_inexcerpt1\">Search in excerpt<\/label>\r\n            <\/div>\r\n\t\t<\/fieldset>\r\n\t\t<fieldset class=\"asl_sett_scroll\">\r\n            \t\t\t\t<div class=\"asl_option_inner hiddend\">\r\n\t\t\t\t\t<input type=\"checkbox\" value=\"post\"\r\n\t\t\t\t\t\t   id=\"1customset_11\"\r\n\t\t\t\t\t\t   title=\"Hidden option, ignore please\"\r\n\t\t\t\t\t\t   name=\"customset[]\" checked=\"checked\"\/>\r\n\t\t\t\t\t<label for=\"1customset_11\">Hidden<\/label>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"asl_option_label hiddend\"><\/div>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\r\n\t\t\t\t\t<input type=\"checkbox\" value=\"page\"\r\n\t\t\t\t\t\t   id=\"1customset_12\"\r\n\t\t\t\t\t\t   title=\"Hidden option, ignore please\"\r\n\t\t\t\t\t\t   name=\"customset[]\" checked=\"checked\"\/>\r\n\t\t\t\t\t<label for=\"1customset_12\">Hidden<\/label>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"asl_option_label hiddend\"><\/div>\r\n\r\n\t\t\t\t        <\/fieldset>\r\n        \r\n        <fieldset>\r\n                            <legend>Filter par cat\u00e9gories<\/legend>\r\n                        <div class='categoryfilter asl_sett_scroll'>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"11\"\r\n                                   id=\"1categoryset_11\"\r\n                                   title=\"actu\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_11\">actu<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            actu                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"20\"\r\n                                   id=\"1categoryset_20\"\r\n                                   title=\"bizutages\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_20\">bizutages<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            bizutages                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"16\"\r\n                                   id=\"1categoryset_16\"\r\n                                   title=\"cabinet des curiosit\u00e9s\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_16\">cabinet des curiosit\u00e9s<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            cabinet des curiosit\u00e9s                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"19\"\r\n                                   id=\"1categoryset_19\"\r\n                                   title=\"chants normaliens\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_19\">chants normaliens<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            chants normaliens                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"40\"\r\n                                   id=\"1categoryset_40\"\r\n                                   title=\"communiquer\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_40\">communiquer<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            communiquer                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"12\"\r\n                                   id=\"1categoryset_12\"\r\n                                   title=\"coupures de presse\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_12\">coupures de presse<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            coupures de presse                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"23\"\r\n                                   id=\"1categoryset_23\"\r\n                                   title=\"en mixte\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_23\">en mixte<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            en mixte                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"15\"\r\n                                   id=\"1categoryset_15\"\r\n                                   title=\"f\u00eates normaliennes\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_15\">f\u00eates normaliennes<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            f\u00eates normaliennes                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"33\"\r\n                                   id=\"1categoryset_33\"\r\n                                   title=\"formes immat\u00e9rielles\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_33\">formes immat\u00e9rielles<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            formes immat\u00e9rielles                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"32\"\r\n                                   id=\"1categoryset_32\"\r\n                                   title=\"formes mat\u00e9rielles\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_32\">formes mat\u00e9rielles<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            formes mat\u00e9rielles                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"13\"\r\n                                   id=\"1categoryset_13\"\r\n                                   title=\"glanes et perles\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_13\">glanes et perles<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            glanes et perles                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"29\"\r\n                                   id=\"1categoryset_29\"\r\n                                   title=\"inventorier\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_29\">inventorier<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            inventorier                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"31\"\r\n                                   id=\"1categoryset_31\"\r\n                                   title=\"inventorier enf\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_31\">inventorier enf<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            inventorier enf                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"30\"\r\n                                   id=\"1categoryset_30\"\r\n                                   title=\"inventorier eng\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_30\">inventorier eng<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            inventorier eng                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"18\"\r\n                                   id=\"1categoryset_18\"\r\n                                   title=\"la cote\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_18\">la cote<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            la cote                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"37\"\r\n                                   id=\"1categoryset_37\"\r\n                                   title=\"la question\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_37\">la question<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            la question                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"17\"\r\n                                   id=\"1categoryset_17\"\r\n                                   title=\"le p\u00e8re cent\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_17\">le p\u00e8re cent<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            le p\u00e8re cent                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"36\"\r\n                                   id=\"1categoryset_36\"\r\n                                   title=\"lettres aux instituteurs\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_36\">lettres aux instituteurs<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            lettres aux instituteurs                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"14\"\r\n                                   id=\"1categoryset_14\"\r\n                                   title=\"musique et sports\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_14\">musique et sports<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            musique et sports                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option hiddend\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"1\"\r\n                                   id=\"1categoryset_1\"\r\n                                   title=\"Non class\u00e9\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_1\">Non class\u00e9<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            Non class\u00e9                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"39\"\r\n                                   id=\"1categoryset_39\"\r\n                                   title=\"partager\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_39\">partager<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            partager                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"35\"\r\n                                   id=\"1categoryset_35\"\r\n                                   title=\"principes fondateurs\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_35\">principes fondateurs<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            principes fondateurs                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"25\"\r\n                                   id=\"1categoryset_25\"\r\n                                   title=\"promotions enf\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_25\">promotions enf<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            promotions enf                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"24\"\r\n                                   id=\"1categoryset_24\"\r\n                                   title=\"promotions eng\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_24\">promotions eng<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            promotions eng                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"10\"\r\n                                   id=\"1categoryset_10\"\r\n                                   title=\"sauvegarder et valoriser\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_10\">sauvegarder et valoriser<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            sauvegarder et valoriser                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"38\"\r\n                                   id=\"1categoryset_38\"\r\n                                   title=\"traditions ritualis\u00e9es\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_38\">traditions ritualis\u00e9es<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            traditions ritualis\u00e9es                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"asl_option\">\r\n                        <div class=\"asl_option_inner\">\r\n                            <input type=\"checkbox\" value=\"22\"\r\n                                   id=\"1categoryset_22\"\r\n                                   title=\"vie quotidienne\"\r\n                                   name=\"categoryset[]\" checked=\"checked\"\/>\r\n                            <label for=\"1categoryset_22\">vie quotidienne<\/label>\r\n                        <\/div>\r\n                        <div class=\"asl_option_label\">\r\n                            vie quotidienne                        <\/div>\r\n                    <\/div>\r\n                \r\n            <\/div>\r\n        <\/fieldset>\r\n            <\/form>\r\n<\/div>\r\n\r\n<div id='ajaxsearchliteres1' class='vertical wpdreams_asl_results asl_w asl_r asl_r_1'>\r\n\r\n    \r\n    <div class=\"results\">\r\n\r\n        \r\n            <div class=\"resdrg\">\r\n            <\/div>\r\n\r\n        \r\n    <\/div>\r\n\r\n    \r\n                    <p class='showmore'>\r\n            <a>Plus de r\u00e9sultats...<\/a>\r\n        <\/p>\r\n        \r\n<\/div>\r\n\r\n    <div id=\"asl_hidden_data\">\r\n        <svg style=\"position:absolute\" height=\"0\" width=\"0\">\r\n            <filter id=\"aslblur\">\r\n                <feGaussianBlur in=\"SourceGraphic\" stdDeviation=\"4\"\/>\r\n            <\/filter>\r\n        <\/svg>\r\n        <svg style=\"position:absolute\" height=\"0\" width=\"0\">\r\n            <filter id=\"no_aslblur\"><\/filter>\r\n        <\/svg>\r\n\r\n    <\/div>\r\n\r\n<div class=\"asl_init_data wpdreams_asl_data_ct\" style=\"display:none !important;\" id=\"asl_init_id_1\" data-asldata=\"ew0KICAgICAgICAiaG9tZXVybCI6ICJodHRwczovL2FzdnBuZi5jb20vIiwNCiAgICAgICAgInJlc3VsdHN0eXBlIjogInZlcnRpY2FsIiwNCiAgICAicmVzdWx0c3Bvc2l0aW9uIjogImhvdmVyIiwNCiAgICAiaXRlbXNjb3VudCI6IDEwLA0KICAgICJpbWFnZXdpZHRoIjogNzAsDQogICAgImltYWdlaGVpZ2h0IjogNzAsDQogICAgInJlc3VsdGl0ZW1oZWlnaHQiOiAiNzBweCIsDQogICAgInNob3dhdXRob3IiOiAwLA0KICAgICJzaG93ZGF0ZSI6IDAsDQogICAgInNob3dkZXNjcmlwdGlvbiI6IDEsDQogICAgImNoYXJjb3VudCI6ICAzLA0KICAgICJkZWZhdWx0SW1hZ2UiOiAiaHR0cDovL2FzdnBuZi5jb20vd3AtY29udGVudC9wbHVnaW5zL2FqYXgtc2VhcmNoLWxpdGUvaW1nL2RlZmF1bHQuanBnIiwNCiAgICAiaGlnaGxpZ2h0IjogMCwNCiAgICAiaGlnaGxpZ2h0d2hvbGV3b3JkcyI6IDEsDQoJInNpbmdsZUhpZ2hsaWdodCI6IDAsDQogICAgInNjcm9sbFRvUmVzdWx0cyI6IDAsDQogICAgInJlc3VsdGFyZWFjbGlja2FibGUiOiAxLA0KICAgICJhdXRvY29tcGxldGUiOiB7DQogICAgICAgICJlbmFibGVkIiA6IDEsDQogICAgICAgICJsYW5nIiA6ICJmciINCiAgICB9LA0KCSJtb2JpbGUiOiB7DQoJCSJtZW51X3NlbGVjdG9yIjogIiNtZW51LXRvZ2dsZSINCgl9LA0KICAgICJ0cmlnZ2Vyb250eXBlIjogMSwNCiAgICAidHJpZ2dlcl9vbl9jbGljayI6IDEsDQogICAgInRyaWdnZXJfb25fZmFjZXRfY2hhbmdlIjogMSwNCiAgICAic2V0dGluZ3NpbWFnZXBvcyI6ICJyaWdodCIsDQogICAgImhyZXN1bHRhbmltYXRpb24iOiAiZngtbm9uZSIsDQogICAgInZyZXN1bHRhbmltYXRpb24iOiAiZngtbm9uZSIsDQogICAgImhyZXN1bHRoaWRlZGVzYyI6ICIxIiwNCiAgICAicHJlc2NvbnRhaW5lcmhlaWdodCI6ICI0MDBweCIsDQogICAgInBzaG93c3VidGl0bGUiOiAiMCIsDQogICAgInBzaG93ZGVzYyI6ICIxIiwNCiAgICAiY2xvc2VPbkRvY0NsaWNrIjogMSwNCiAgICAiaWlmTm9JbWFnZSI6ICJkZXNjcmlwdGlvbiIsDQogICAgImlpUm93cyI6IDIsDQogICAgImlpdGVtc1dpZHRoIjogMjAwLA0KICAgICJpaXRlbXNIZWlnaHQiOiAyMDAsDQogICAgImlpc2hvd092ZXJsYXkiOiAxLA0KICAgICJpaWJsdXJPdmVybGF5IjogMSwNCiAgICAiaWloaWRlQ29udGVudCI6IDEsDQogICAgImlpYW5pbWF0aW9uIjogIjEiLA0KICAgICJhbmFseXRpY3MiOiAiMCIsDQogICAgImFuYWx5dGljc1N0cmluZyI6ICIiLA0KICAgICJyZWRpcmVjdG9uY2xpY2siOiAwLA0KICAgICJyZWRpcmVjdENsaWNrVG8iOiAiYWpheF9zZWFyY2giLA0KICAgICJyZWRpcmVjdENsaWNrTG9jIjogInNhbWUiLA0KICAgICJyZWRpcmVjdF9vbl9lbnRlciI6IDAsDQogICAgInJlZGlyZWN0RW50ZXJUbyI6ICJhamF4X3NlYXJjaCIsDQogICAgInJlZGlyZWN0RW50ZXJMb2MiOiAic2FtZSIsDQogICAgInJlZGlyZWN0X3VybCI6ICI\/cz17cGhyYXNlfSIsDQogICAgIm92ZXJyaWRld3BkZWZhdWx0IjogMCwNCiAgICAib3ZlcnJpZGVfbWV0aG9kIjogImdldCINCn0NCg==\"><\/div>\r\n<\/h4>\n<p>&nbsp;<\/p>\n<div class=\"wsp-container\"><h2 class=\"wsp-posts-title\">Articles par cat\u00e9gorie<\/h2>\n<ul class=\"wsp-posts-list\">\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/actu\/\">actu<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/07\/07\/la-laicite-republicaine-une-valeur-intangible-non-negociable\/\">La la\u00efcit\u00e9 r\u00e9publicaine;  Une valeur intangible non n\u00e9gociable.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/07\/01\/la-loi-duplomb-ii\/\">La Loi Duplomb II\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/23\/betharram-un-rapport-de-plus\/\">Betharram; un rapport de plus !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/10\/celebration-du-81e-anniversaire-de-la-victoire-de-1945\/\">C\u00e9l\u00e9bration du\u00a081\u00e8 anniversaire de la Victoire de 1945<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/26\/accommodements-preelectoraux-de-circonstance-a-la-definition-de-la-laicite-sous-les-auspices-de-la-republique-francaise\/\">Accommodements pr\u00e9\u00e9lectoraux de circonstance \u00e0 la d\u00e9finition de la La\u00efcit\u00e9 sous les auspices de la R\u00e9publique fran\u00e7aise.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/26\/quand-le-president-de-la-republique-francaise\/\">Quand le Pr\u00e9sident de la R\u00e9publique francaise,<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/03\/08\/appel-solennel-de-lasvpnf\/\">Appel solennel de l\u2019ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/07\/quand-lextreme-droite-vise-lecole\/\">Quand l\u2019extr\u00eame droite vise l\u2019\u00e9cole\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/07\/violette-spillebout-le-courage-contre-lomerta\/\">Violette Spillebout : Le courage contre l\u2019omerta<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/06\/controler-lenseignement-prive-vers-un-changement-de-culture\/\">Contr\u00f4ler l\u2019enseignement priv\u00e9 : vers un changement de culture ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/01\/les-25-ans-de-wikipedia\/\">Les 25 ans de WIKIPEDIA<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/23\/petite-chronique-dapres-ciase-et-betharam-vi\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharam (VI)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/07\/a-propos-de-la-caricature-de-rokhaya-diallo\/\">A propos de la caricature de Rokhaya Diallo<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/03\/voeux-de-lasvpnf\/\">VOEUX DE L&rsquo;ASVPNF\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/12\/23\/petite-chronique-dapres-ciase-et-betharam-v\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharam (V)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/12\/03\/petite-chronique-dapres-ciase-et-betharram-iv\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharram (IV)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/12\/03\/leducation-nationale-au-front-de-la-censure\/\">L\u2019\u00c9ducation nationale au front de la censure<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/26\/les-120-ans-de-la-loi-du-9-decembre-1905\/\">Les 120 ans de la loi du 9 d\u00e9cembre 1905<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/19\/13-novembre-2015-13-novembre-2025\/\">13 novembre 2015 &#8211; 13 novembre 2025<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/16\/celebration-du-107e-anniversaire\/\">C\u00e9l\u00e9bration du 107\u00e8 anniversaire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/08\/le-respect-de-la-laicite-au-sein-des-tribunes-de-lassemblee-nationale\/\">Le respect de la La\u00efcit\u00e9 au sein des tribunes de l\u2019Assembl\u00e9e nationale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/01\/impot-plancher-sur-la-fortune\/\">Imp\u00f4t plancher sur la fortune<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/01\/petite-chronique-dapres-ciase-et-betharram-ii\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharram (II)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/08\/pourquoi-il-faut-reguler-les-jeux-video\/\">POURQUOI IL FAUT REGULER LES JEUX VIDEO<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/02\/turpitudes-et-contreturpitudes-clericales-et-ecclesiales\/\">Turpitudes et contreturpitudes cl\u00e9ricales et eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/13\/appel-de-radio-france\/\">Appel de Radio France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/10\/un-combat-sans-faiblesse\/\">Un combat sans faiblesse\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/05\/turpitudes-et-contreturpitudes-eccesiales-et-clericales\/\">Turpitudes et contreturpitudes ecc\u00e9siales et cl\u00e9ricales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/05\/22\/laffaire-betharram\/\">L\u2019Affaire B\u00e9tharram<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/05\/18\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales-5\/\">Turpitudes et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/05\/11\/le-8-mai-2025\/\">Le  8 mai 2025<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/12\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales-4\/\">Turpitudes et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/12\/ah-le-beau-rameau-davril-2025\/\">Ah!   Le Beau Rameau  d\u2019avril 2025\u2026<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/04\/loi-sur-la-laicite-dans-le-sport\/\">Loi sur la la\u00efcit\u00e9 dans le sport<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/04\/lenseignement-prive-catholique-sous-contrat-hors-de-controle\/\">L\u2019enseignement priv\u00e9  catholique sous contrat  hors de contr\u00f4le<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/02\/le-respect-des-principes-de-laicite-et-de-neutralite-en-milieu-sportif-addendum\/\">Le respect des principes de la\u00efcit\u00e9 et de  neutralit\u00e9 en milieu sportif (Addendum)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/02\/le-respect-des-principes-de-laicite-et-de-neutralite-en-milieu-sportif\/\">Le respect des principes de la\u00efcit\u00e9 et de  neutralit\u00e9  en  milieu sportif<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/30\/la-pratique-de-lomerta-a-betharram\/\">La pratique de l&rsquo;omerta \u00e0 Betharram<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/18\/leglise-face-aux-violences-scolaires-a-la-pedophilie-et-aux-abus-sexuels\/\">L\u2019\u00c9glise face aux violences scolaires, \u00e0 la p\u00e9dophilie et aux abus sexuels.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/07\/8-mars-2025-journee-internationale\/\">8 mars 2025 : Journ\u00e9e internationale des Droits des Femmes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/03\/betharram-et-autres-turpitudessuite\/\">B\u00e9tharram  et autres turpitudes(suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/01\/petite-chronique-non-exhaustive-des-turpitudes-et-exactions-clericales-commises-au-sein-du-college-lycee-notre-dame-de-betharram\/\">Petite chronique non exhaustive des turpitudes et exactions cl\u00e9ricales\u00a0 commises au sein du Coll\u00e8ge-Lyc\u00e9e Notre-Dame de Betharram\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/02\/15\/revelation-dun-nouvel-episode-de-turpitudes-clericales\/\">R\u00e9v\u00e9lation d\u2019un nouvel \u00e9pisode de turpitudes cl\u00e9ricales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/28\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales-3\/\">Turpitudes et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/25\/80-ans-apres-la-liberation-dauschwitz-birkenau\/\">80 ans apr\u00e8s la Lib\u00e9ration d\u2019Auschwitz-Birkenau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/09\/pour-sauver-lecole-publique-laique\/\">Pour sauver l&rsquo;Ecole publique la\u00efque\u00a0\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/05\/chido-le-revelateur-implacable\/\">CHIDO ,le r\u00e9v\u00e9lateur implacable.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/23\/mayotte-devastee-par-le-cyclone-chido\/\">MAYOTTE d\u00e9vast\u00e9e par le cyclone Chido<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/23\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales-suite\/\">Turpitudes\u00a0 et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/11\/les-droits-humains-malmenes-lappel-des-ecrivaines-et-des-ecrivains\/\">Les droits humains malmen\u00e9s !   L&rsquo;appel des \u00e9crivaines et  des \u00e9crivains<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/08\/la-loi-de-separation-des-eglises-et-de-letat-fete-ses-119-ans\/\">La loi de S\u00e9paration des \u00c9glises et de l\u2019\u00c9tat   f\u00eate ses 119 ans :<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/04\/liberez-le-romancier-franco-algerien\/\">Lib\u00e9rez le romancier franco-alg\u00e9rien\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/11\/25\/pour-labrogation-de-la-loi-debre\/\">Pour l&rsquo;abrogation de la Loi Debr\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/11\/25\/25-novembre-2024\/\">25 novembre 2024<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/11\/19\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales-suite-du-15-novembre-2024\/\">Turpitudes et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales (Suite du 15 novembre 2024)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/11\/15\/fleurissement-du-monument-aux-instituteurs-du-finistere-morts-pour-la-france-11-novembre-2024\/\">Fleurissement du Monument aux Instituteurs du Finist\u00e8re Morts pour la France   (11 novembre 2024)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/10\/13\/pour-ne-pas-mourir-denseigner\/\">Pour ne pas mourir d&rsquo;enseigner<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/10\/09\/7-octobre-2024-la-france-discreditee\/\">\u00ab\u00a07 octobre 2024, la France discr\u00e9dit\u00e9e\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/24\/la-lettre-dinformation-n7-de-lasvpnf\/\">La Lettre d&rsquo;Information n\u00b07 de l&rsquo;ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/16\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales-2\/\">Turpitudes et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/08\/quattendre-de-michel-barnier-pour-lecole\/\">Qu\u2019attendre de Michel Barnier pour l\u2019\u00e9cole ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/03\/rentree-scolaire-sous-les-auspices-dune-democratie-aux-abois\/\">Rentr\u00e9e scolaire sous les auspices d\u2019une d\u00e9mocratie aux abois.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/08\/28\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales-suite-d-aout-2024\/\">Turpitudes et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales (suite d\u2019 ao\u00fbt 2024)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/08\/15\/turpitudes-et-contreturpitudes-ecclesiales-et-clericales-suite-de-janvier-2024\/\">Turpitudes et contreturpitudes eccl\u00e9siales et cl\u00e9ricales (suite de janvier 2024)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/08\/15\/turpitudes-et-contre-turpitudes-ecclesiales-et-clericales-suite-aout-2024\/\">Turpitudes et contre turpitudes eccl\u00e9siales et cl\u00e9ricales (suite, ao\u00fbt 2024).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/10\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xxiii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XXIII).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/06\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xxii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XXII).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/06\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xxi\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XXI)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/06\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xx\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XX)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/03\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xvii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XVII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/02\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xvi\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XVI)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/02\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xv\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XV)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/24\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-x\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (X)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/21\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-viii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (VIII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/20\/islamophobie-le-retour-du-delit-de-blaspheme-au-programme-du-pretendu-nouveau-front-populaire\/\">\u00ab Islamophobie \u00bb : le retour du d\u00e9lit de blasph\u00e8me au programme du pr\u00e9tendu \u00ab Nouveau Front populaire \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/20\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-vi\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (VI)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/17\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-iv\/\">Chronique d&rsquo;\u00e9v\u00e8nements initi\u00e9s par le \u00ab\u00a0s\u00e9isme\u00a0\u00bb politique du 9 juin 2024 (IV)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/17\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-iii\/\">Chronique d&rsquo;\u00e9v\u00e8nements initi\u00e9s par le \u00ab\u00a0s\u00e9isme\u00a0\u00bb politique du 9 juin 2024 (III)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/16\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-ii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du  9 juin 2024 (II).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/15\/pour-faire-emerger-du-seisme-politique-un-espoir-republicain-laique-et-fraternel\/\">Pour faire \u00e9merger du s\u00e9isme politique,  un espoir r\u00e9publicain, la\u00efque et fraternel!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/13\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du  9 juin 2024.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/12\/non-a-la-mise-sous-tutelle-du-rn-des-enseignements-et-des-enseignants-de-lecole-publique-laique\/\">NON  \u00e0 la mise sous tutelle du RN  des enseignements et des enseignants  de l&rsquo;Ecole publique la\u00efque !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/05\/19\/celebration-du-79e-anniversaire-de-la-victoire-du-8-mai-1945\/\">C\u00e9l\u00e9bration du 79\u00e8 anniversaire de la Victoire du  8 mai 1945<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/05\/11\/les-ideologues-partisans-dune-laicite-intransigeante\/\">Les id\u00e9ologues partisans d\u2019une la\u00efcit\u00e9 intransigeante<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/04\/15\/les-enfants-du-silence\/\">\u201cLes enfants du silence\u201d<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/04\/15\/apprendre-a-croire-sans-fanatisme\/\">Apprendre \u00e0 croire sans fanatisme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/03\/08\/le-8-mars-2024-journee-internationale-des-droits-des-femmes\/\">Le  8 mars 2024  Journ\u00e9e internationale   des  droits des  femmes.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/02\/18\/a-la-memoire-de-robert-badinter-condorcet-contre-la-peine-de-mort\/\">A la m\u00e9moire de Robert Badinter : Condorcet contre la peine de mort.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/01\/28\/turpitudes-et-contreturpitudes-ecclesiales-et-clericales-suite-janvier-2024\/\">Turpitudes et contreturpitudes eccl\u00e9siales et cl\u00e9ricales (suite ,  janvier 2024)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/01\/15\/israel-la-compassion-perdue\/\">Isra\u00ebl : la compassion perdue<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/01\/14\/limmigration-une-question-economique-ou-culturelle-et-politique\/\">L\u2019immigration: une question \u00e9conomique, ou culturelle et politique?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/01\/08\/les-voeux-de-lasvpnf-pour-2024\/\">Les v\u0153ux de L\u2019ASVPNF pour 2024<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/12\/29\/diane-et-acteon-des-collegiens-offusques-par-un-tableau-sur-la-pudeur\/\">\u00ab Diane et Act\u00e9on \u00bb : des coll\u00e9giens offusqu\u00e9s par un tableau\u2026 sur la pudeur<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/12\/22\/turpitudes-clericales-et-contreturpitudes-ecclesiales-suite\/\">Turpitudes  cl\u00e9ricales et contreturpitudes eccl\u00e9siales  (suite\u2026)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/12\/02\/le-wokisme-un-nouvel-obscurantisme-en-marche\/\">Le wokisme, un nouvel obscurantisme en marche ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/11\/13\/asvpnf-honorer-notre-devoir-de-memoire-11-novembre-2023\/\">ASVPNF :  Honorer notre  devoir de m\u00e9moire 11 novembre 2023<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/11\/10\/pour-notre-republique-laique-et-fraternelle-et-contre-lantisemitisme-sans-barguigner-marchons\/\">Pour notre  R\u00e9publique la\u00efque et fraternelle  et   Contre  l\u2019antis\u00e9mitisme  Sans barguigner, MARCHONS !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/30\/turpitudes-et-contre-turpitudes-clericales-2\/\">Turpitudes  et contre-turpitudes  cl\u00e9ricales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/19\/apres-lassassinat-du-professeur-dominique-bernard-par-un-integriste-islamiste\/\">Apr\u00e8s l\u2019assassinat du Professeur Dominique Bernard  par  un int\u00e9griste islamiste<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/19\/non-a-la-barbarie-a-l-ecole-de-la-republique\/\">Non \u00e0 la barbarie \u00e0  l&rsquo; Ecole de la R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/15\/trois-ans-apres-lassassinat-de-samuel-paty-la-demarche-mortifere-du-hamas-et-lecole-comme-rempart-a-lintegrisme-et-a-la-barbarie\/\">Trois ans apr\u00e8s l&rsquo;assassinat de Samuel Paty;  la d\u00e9marche mortif\u00e8re du hamas  et  l&rsquo;Ecole comme rempart \u00e0 l&rsquo;int\u00e9grisme et \u00e0 la barbarie.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/11\/turpitudes-clericales-et-contre-turpitudes-ecclesiales-en-france-et-ailleurs-suite\/\">Turpitudes cl\u00e9ricales et contre-turpitudes eccl\u00e9siales en France et ailleurs  (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/27\/interdiction-de-labaya-a-lecole\/\">Interdiction de l&rsquo;abaya \u00e0 l&rsquo;Ecole:<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/25\/marseille-et-le-pape-valent-bien-une-messe\/\">Marseille et le pape valent bien une messe !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/18\/bouillabaisses-marseillaises\/\">Bouillabaisses marseillaises<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/18\/le-voyage-imaginaire-du-pape-francois-a-marseille-une-vraie-fausse-incursion-en-republique-francaise\/\">Le voyage imaginaire du pape Fran\u00e7ois \u00e0 Marseille ; une vraie-fausse incursion en R\u00e9publique fran\u00e7aise.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/12\/turpitudes-et-contre-turpitudes-clericales\/\">Turpitudes et contre-turpitudes  cl\u00e9ricales ;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/12\/de-la-simple-chemise-des-canuts-a-labaya-en-passant-par-le-kimono-et-la-soutane\/\">De la simple chemise des canuts, \u00e0 l\u2019abaya  en passant par le kimono et la soutane:<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/03\/une-note-de-service-du-31-08-2023-qui-fera-date\/\">Une note de service du 31  08 2023  qui fera date<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/20\/contre-turpitudes-ecclesiales\/\">Contre-turpitudes  eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/07\/21\/maux-et-mysteres-sous-les-auspices-protecteurs-de-la-republique\/\">Maux et myst\u00e8res  sous les auspices protecteurs de la R\u00e9publique\u2026<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/07\/21\/turpitudes-et-contre-turpitudes-ecclesiales-et-clericales-2\/\">Turpitudes et contre-turpitudes eccl\u00e9siales et cl\u00e9ricales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/07\/16\/apres-les-violences-urbaines-de-2023-repliques-de-celles-de-2005-pourrait-on-enfin-rechercher-et-trouver-la-volonte-et-le-courage-deduquer-notre-jeunesse-2\/\">Apr\u00e8s les violences urbaines de 2023,  r\u00e9pliques de celles de 2005 :  Pourrait-on enfin rechercher et trouver la volont\u00e9 et le courage d\u2019\u00e9duquer notre jeunesse ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/07\/06\/football-feminin-et-laicite\/\">Football f\u00e9minin  et  la\u00efcit\u00e9 :<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/06\/18\/chronique-estivale-des-turpitudes-ciblees-contre-la-laicitede-la-gestion-calamiteuse-du-fonds-marianne-et-des-demeles-de-leglise-face-a-la-pedophilie-et-aux-abus-sexuels\/\">Chronique estivale des turpitudes cibl\u00e9es contre la la\u00efcit\u00e9,de la gestion calamiteuse du Fonds Marianne et des  d\u00e9m\u00eal\u00e9s  de l\u2019Eglise  face \u00e0 la p\u00e9dophilie et aux abus sexuels.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/06\/12\/pourquoi-les-islamistes-sen-prennent-a-lecole-publique-de-la-republique\/\">Pourquoi les islamistes s\u2019en prennent \u00e0 l\u2019Ecole publique de la R\u00e9publique ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/06\/08\/turpitudes-et-contre-turpitudes-ecclesiales-et-clericales-suite-2\/\">Turpitudes et  contre-turpitudes    eccl\u00e9siales et cl\u00e9ricales (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/06\/08\/les-lendemains-de-la-pandemie-de-covid-19-une-nouvelle-affaire-raoult\/\">Les lendemains de la pand\u00e9mie de Covid-19  Une nouvelle \u201caffaire Raoult\u201d<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/05\/29\/petite-chronique-republicaine-dune-delaicisation-programmee-a-marche-forcee-i\/\">Petite chronique r\u00e9publicaine d\u2019une  d\u00e9la\u00efcisation programm\u00e9e \u00e0 marche forc\u00e9e (I)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/05\/12\/le-fleurissement-du-monument-aux-instituteurs-du-finistere-morts-pour-la-france-78e-anniversaire-de-la-victoire-du-8-mai-1945\/\">Le fleurissement du Monument aux Instituteurs du Finist\u00e8re  Morts pour la France  78\u00e8 anniversaire de la Victoire du 8 mai 1945<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/04\/30\/les-petits-accommodements-de-circonstance-au-conseil-des-sages-de-la-laicite\/\">Les petits accommodements de circonstance au Conseil des sages de la la\u00efcit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/04\/30\/turpitudes-et-contre-turpitudes-ecclesiales-et-clericales-suite\/\">Turpitudes et contre-turpitudes eccl\u00e9siales et cl\u00e9ricales (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/04\/30\/la-laicite-un-principe-abime-par-celles-et-ceux-qui-en-font-commerce\/\">La la\u00efcit\u00e9, un principe ab\u00eem\u00e9 par celles et ceux qui en font commerce<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/03\/28\/le-projet-de-reforme-des-retraites\/\">Le projet de  r\u00e9forme des retraites<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/03\/20\/lorsque-madame-hidalgo-quitte-sa-capitale-pour-saluer-le-pape\/\">Lorsque Madame Hidalgo   quitte sa capitale pour saluer le Pape !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/03\/13\/turpitudes-et-contre-turpitudes-ecclesiales-et-clericales\/\">Turpitudes et contre-turpitudes  eccl\u00e9siales et cl\u00e9ricales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/03\/11\/la-question-de-luniforme-a-lecole\/\">La question de l\u2019uniforme \u00e0 l\u2019Ecole<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/03\/07\/journee-internationale-2023-des-droits-des-femmes\/\">Journ\u00e9e Internationale 2023  des Droits des Femmes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/03\/01\/chronique-des-turpitudes-et-contre-turpitudes-ecclesiales-et-clericales-suite\/\">Chronique des turpitudes et contre-turpitudes eccl\u00e9siales et cl\u00e9ricales (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/07\/petite-chronique-des-tribulations-et-turpitudes-ecclesiales-et-clericales-de-2023-suite\/\">Petite chronique des tribulations et turpitudes  eccl\u00e9siales et cl\u00e9ricales  de 2023 (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/05\/un-cabinet-de-conseil-bien-retribue-a-loeuvre-au-ministere-de-leducation-nationale\/\">Un cabinet de conseil bien r\u00e9tribu\u00e9 \u00e0 l\u2019oeuvre  au  Minist\u00e8re de l\u2019Education Nationale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/01\/chronique-des-tribulations-et-turpitudes-clericales-de-2023-suite\/\">Chronique des tribulations et turpitudes cl\u00e9ricales de 2023 (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/01\/18\/un-nouveau-scandale-clerical-au-plus-haut-niveau-laffaire-rupnik\/\">Un nouveau scandale cl\u00e9rical au plus haut niveau     L\u2019affaire RUPNIK<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/01\/08\/le-feuilleton-des-ravis-de-la-creche-et-autres-saintons-de-serviceavent-2022\/\">Le feuilleton des ravis de la cr\u00e8che et autres saintons de service(Avent 2022)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/01\/08\/les-voeux-de-lasvpnf-pour-2023\/\">Les voeux de l\u2019ASVPNF pour 2023<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/21\/chronique-des-tribulations-et-turpitudes-ecclesiales-et-clericales-de-leglise-catholique-avent-2022\/\">Chronique   des    tribulations  et  turpitudes  eccl\u00e9siales et cl\u00e9ricales  de l\u2019\u00e9glise catholique  (Avent  2022)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/30\/turpitudes-clericales-autour-du-celibat-sacerdotal\/\">Turpitudes cl\u00e9ricales autour du c\u00e9libat sacerdotal<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/20\/chez-les-hierarques-mitres-de-france-aller-de-charybde-en-scylla\/\">Chez les hi\u00e9rarques mitr\u00e9s de  France  Aller de Charybde en Scylla<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/15\/turpitudes-clericales-et-episcopales-de-lapres-reunion-de-la-cef-a-lourdes-novembre-2022\/\">Turpitudes cl\u00e9ricales et \u00e9piscopales de l\u2019apr\u00e8s &#8211; r\u00e9union de la CEF \u00e0 Lourdes (novembre 2022)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/13\/commemoration-du-11-novembre-au-pied-des-steles-dun-monument-orphelin\/\">Comm\u00e9moration du 11 novembre.         Au pied des st\u00e8les d\u2019un monument orphelin.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/08\/pedocriminalite-episcopale-la-situation-cataclysmique-au-7-novembre-2022\/\">P\u00e9docriminalit\u00e9 \u00e9piscopale  La situation cataclysmique au  7 novembre 2022<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/04\/turpitudes-clericales-et-episcopales-a-lepreuve-de-la-justice-divine-suites-de-laffaire-santier\/\">Turpitudes cl\u00e9ricales et \u00e9piscopales  \u00e0  l&rsquo;\u00e9preuve de la justice divine  (suites de l&rsquo;affaire Santier)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/31\/atteintes-a-la-laicite-a-lecole\/\">Atteintes \u00e0 la la\u00efcit\u00e9 \u00e0 l\u2019Ecole<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/26\/la-religion-woke-un-nouvel-obscurantisme-a-combattre\/\">La religion  Woke ,  un nouvel obscurantisme \u00e0 combattre !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/26\/turpitudes-clericales-en-milieu-episcopal-la-revelation-de-laffaire-santier\/\">Turpitudes  cl\u00e9ricales en milieu  \u00e9piscopal  La r\u00e9v\u00e9lation de l\u2019affaire Santier<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/21\/decapitation-sauvage-de-samuel-paty-pour-cultiver-notre-indignation-et-faire-reculer-lindifference\/\">D\u00e9capitation sauvage de Samuel Paty  pour  Cultiver notre indignation et faire reculer l&rsquo;indiff\u00e9rence<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/19\/deux-ans-apres-la-decapitation-sauvage-de-samuel-paty-lindifference-a-gagne\/\">Deux ans apr\u00e8s la d\u00e9capitation sauvage     de SAMUEL  PATY,     L&rsquo;indiff\u00e9rence a gagn\u00e9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/09\/rendons-hommage-a-notre-ami-francois-trividic-membre-actif-de-lasvpnf-recemment-decede\/\">Rendons hommage  \u00e0 notre  ami Fran\u00e7ois TRIVIDIC,    membre actif de l&rsquo;ASVPNF, r\u00e9cemment d\u00e9c\u00e9d\u00e9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/08\/soutenir-la-revolte-des-femmes-iraniennes-contre-les-obscurantismes\/\">Soutenir la  r\u00e9volte  des femmes iraniennes contre les obscurantismes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/30\/turpitudes-et-tribulations-episcopales-les-suites-de-laffaire-di-falco\/\">Turpitudes et tribulations \u00e9piscopales    Les suites de l&rsquo;affaire   Di Falco<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/21\/les-bons-petits-livres-de-la-rentree-2022\/\">Les bons petits livres de la rentr\u00e9e 2022 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/21\/pedocriminalite-clericale-suite-laffaire-johannes-rivoire\/\">P\u00e9docriminalit\u00e9 cl\u00e9ricale (suite)  L\u2019affaire Johannes Rivoire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/17\/soutenons-sans-faiblesse-et-avec-enthousiasme-laction-laique-fondatrice-dassociations-amies\/\">Soutenons sans faiblesse et avec enthousiasme            l&rsquo;action la\u00efque fondatrice d&rsquo;associations amies<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/14\/beaucoup-de-bruits-autour-dune-expulsion-ratee\/\">Beaucoup de bruits autour  d&rsquo;une expulsion rat\u00e9e !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/08\/28\/nous-navons-pas-ete-dignes-de-salman-rushdie\/\">Nous n&rsquo;avons pas \u00e9t\u00e9 dignes  de  Salman Rushdie !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/08\/22\/contre-le-fanatisme-pour-la-liberte-dexpression\/\">Contre le fanatisme  pour la libert\u00e9 d&rsquo;expression<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/08\/11\/activites-ecclesiales-estivales-et-papales\/\">Activit\u00e9s eccl\u00e9siales  estivales et papales !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/07\/11\/le-reglement-interieur-des-piscines-de-grenoble-autorisant-le-port-du-burkini-retoque-par-le-conseil-detat\/\">Le r\u00e8glement int\u00e9rieur des piscines de Grenoble  autorisant le port du \u201cburkini\u201d  retoqu\u00e9 par le Conseil d&rsquo;Etat.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/06\/13\/pour-mettre-un-terme-a-lagitation-sur-les-plages-et-aux-remous-dans-les-piscines-en-relation-avec-le-port-du-burkini\/\">Pour mettre un terme \u00e0 l&rsquo;agitation sur les plages et  aux remous dans les piscines en relation avec le port du burkini !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/06\/13\/abus-sexuels-clericaux-leglise-catholique-italienne-fait-de-la-resistance\/\">Abus sexuels  cl\u00e9ricaux;  l&rsquo;\u00e9glise catholique italienne  fait de la r\u00e9sistance.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/06\/10\/lirruption-des-burkinis-agitation-et-remous-provoques-dans-les-piscines-municipales\/\">L&rsquo;irruption des burkinis;  Agitation et remous provoqu\u00e9s dans les piscines municipales.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/31\/tribulations-et-afflictions-ecclesiales-suite\/\">Tribulations et afflictions eccl\u00e9siales (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/21\/le-17-mai-2022-journee-internationale-de-lutte-contre-lhomophobie-la-transphobie-et-la-biphobie\/\">Le 17 mai 2022 journ\u00e9e internationale de lutte contre l\u2019homophobie,   la transphobie et la biphobie.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/10\/77e-anniversaire-de-la-reddition-pure-et-simple-du-3e-reich-du-7-mai-1945-a-reims-fleurissement-du-monument-aux-instituteurs-du-finistere-morts-pour-la-france\/\">77\u00e8 anniversaire de la reddition pure et simple du 3\u00e8 Reich du 7 mai 1945 \u00e0 Reims   Fleurissement du Monument aux Instituteurs du Finist\u00e8re Morts pour la France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/19\/le-port-du-voile-na-jamais-libere-aucune-femme\/\">Le port du voile n&rsquo;a jamais lib\u00e9r\u00e9 aucune femme  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/19\/exactions-clericales-en-amerique-de-nord-les-pensionnats-de-la-honte-pour-tuer-lindien-dans-lenfant\/\">Exactions cl\u00e9ricales en Am\u00e9rique de Nord :          Les pensionnats de la honte   pour        tuer l&rsquo;Indien dans l&rsquo;enfant .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/19\/nouvelles-tribulations-clericales-et-reparations-aux-victimes-dactes-pedo-criminels-commis-au-sein-de-leglise\/\">Nouvelles tribulations cl\u00e9ricales  et r\u00e9parations   aux victimes   d&rsquo;actes p\u00e9do criminels commis au sein de l&rsquo;Eglise<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/03\/tribulations-vaticinations-et-afflictions-ecclesiales-du-printemps-2022\/\">Tribulations, vaticinations et afflictions eccl\u00e9siales   du   printemps 2022<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/03\/le-president-macron-et-la-legitime-defense-poisson-davril-2022\/\">Le Pr\u00e9sident Macron et la l\u00e9gitime d\u00e9fense :    Poisson d&rsquo;avril 2022 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/15\/une-nuit-noire-sabat-sur-la-russie\/\">Une nuit noire s\u2019abat sur la Russie<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/12\/la-guerre-de-poutine-en-ukraine-le-temps-du-courage-et-de-la-lucidite\/\">La guerre de Poutine en Ukraine  Le temps du courage et de la lucidit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/03\/le-cours-ordinaire-de-lhistoire-invasion-de-lukraine-la-paix-netait-quun-armistice\/\">Le cours ordinaire de l\u2019Histoire  Invasion de l\u2019Ukraine; la paix n\u2019\u00e9tait qu\u2019un armistice<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/02\/25\/24-fevrier-2022-un-grand-peril-pour-nos-democraties\/\">24 f\u00e9vrier 2022  Un grand p\u00e9ril pour nos d\u00e9mocraties<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/02\/14\/billets-dactualite-de-golias-suite-golias-newsfevrier-2022\/\">Billets d\u2019actualit\u00e9 de Golias (suite) Golias News,f\u00e9vrier 2022<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/30\/amicale-laique-de-concarneau\/\">Amicale la\u00efque de Concarneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/26\/billets-dactualite-de-golias-janvier-2022\/\">Billets d&rsquo;actualit\u00e9 de Golias  (janvier 2022)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/26\/le-400-e-anniversaire-de-la-naissance-de-moliere\/\">Le 400 \u00e8 anniversaire de la naissance de Moli\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/19\/le-patrimoine-normalien-du-finistere-remis-en-lumiere-par-la-presse-locale\/\">Le Patrimoine Normalien du Finist\u00e8re                     remis en lumi\u00e8re par la presse locale.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/09\/un-irresponsable-nest-plus-un-citoyen-vraiment\/\">\u00ab\u00a0Un irresponsable n&rsquo;est plus un citoyen\u00a0\u00bb, vraiment ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/09\/apres-la-disparition-de-laurent-bouvet-republicain-laique-dont-les-analyses-distillaient-la-lumiere\/\">Apr\u00e8s la disparition de Laurent Bouvet,  r\u00e9publicain la\u00efque  dont les \u00ab\u00a0analyses distillaient la lumi\u00e8re\u00a0\u00bb !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/12\/20\/echos-journalistiques-du-second-conseil-du-comite-interministeriel-de-la-laicite-cil\/\">Echos  journalistiques du second conseil  du  Comit\u00e9  Interminist\u00e9riel de la La\u00efcit\u00e9 (CIL).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/25\/un-pronom-personnel-incongru-plus-impersonnel-et-haissable-que-tous-les-autres-reunis\/\">Un pronom personnel  incongru plus impersonnel et ha\u00efssable     que  tous les autres r\u00e9unis !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/18\/leglise-face-a-ses-crimes-sexuels-qui-va-payer-les-reparations-et-comment\/\">L&rsquo;Eglise face \u00e0 ses crimes sexuels&#8230;     Qui va payer les r\u00e9parations et comment ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/15\/celebration-de-lanniversaire-de-larmistice-du-11-novembre-1918\/\">C\u00e9l\u00e9bration de l&rsquo;anniversaire de l&rsquo;armistice  du  11 novembre 1918<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/13\/de-nouvelles-activites-a-lamicale-laique-de-concarneau\/\">De nouvelles activit\u00e9s  \u00e0 l&rsquo;Amicale la\u00efque de Concarneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/09\/pedocriminalite-au-sein-de-leglise-catholique-conclusions-de-la-conference-episcopale-de-lourdes-novembre-2021\/\">P\u00e9docriminalit\u00e9 au sein de l&rsquo;\u00e9glise catholique     Conclusions de la conf\u00e9rence \u00e9piscopale de Lourdes     (novembre 2021)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/06\/les-miracles-attendus-de-lourdes-pour-reparer-ce-qui-nest-pas-reparable-novembre-2021\/\">Les miracles attendus de Lourdes  pour r\u00e9parer ce qui n\u2019est pas r\u00e9parable. (novembre 2021)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/31\/la-permanence-du-combat-laique-a-concarneau\/\">La permanence du combat la\u00efque \u00e0 Concarneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/31\/leglise-catholique-peut-et-doit-payer-sinon-elle-se-met-en-etat-de-faillite\/\">L&rsquo;Eglise catholique  peut et doit payer  sinon  elle se met en \u00e9tat de faillite !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/31\/polemiques-et-crise-de-confiance-au-sein-de-leglise-catholique-apres-la-publication-du-rapport-sauve-sur-la-pedocriminalite-ecclesiale\/\">Pol\u00e9miques et crise de confiance au sein de l&rsquo;\u00e9glise catholique  apr\u00e8s la publication du rapport Sauv\u00e9  sur la p\u00e9docriminalit\u00e9 eccl\u00e9siale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/20\/les-lendemains-des-travaux-de-la-ciase-les-angles-morts-du-rapport-et-lappel-pour-une-eglise-fiable\/\">Les lendemains  des travaux de la CIASE :  \u00ab\u00a0Les angles morts du rapport\u00a0\u00bb  et  \u00ab\u00a0l&rsquo;appel pour une \u00e9glise fiable !\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/17\/la-commemoration-du-premier-anniversaire-de-la-decapitation-sauvage-de-samuel-paty\/\">La comm\u00e9moration du premier anniversaire  de la d\u00e9capitation sauvage de  Samuel Paty<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/17\/les-laiques-concarnois-a-la-pointe-du-combat\/\">Les  la\u00efques concarnois \u00e0 la pointe du combat !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/14\/apres-la-publication-du-rapport-sauve-mgr-eric-de-moulins-beaufort-invite-a-sexprimer-sur-ses-propos-polemiques-concernant-les-lois-de-la-republique-francaise\/\">Apr\u00e8s la publication du rapport SAUVE ,    Mgr.  Eric de Moulins-Beaufort  invit\u00e9 \u00e0 s&rsquo;exprimer sur ses propos pol\u00e9miques concernant les lois de la R\u00e9publique fran\u00e7aise.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/06\/le-rapport-de-la-ciase-presidee-par-j-m-sauve-groupes-de-travail-et-resume-du-document-final\/\">Le rapport de la Ciase  pr\u00e9sid\u00e9e par J-M. Sauv\u00e9     Groupes de travail et r\u00e9sum\u00e9 du document final<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/04\/la-pedocriminalite-dans-leglise-catholique-le-rapport-sauve\/\">La p\u00e9docriminalit\u00e9 dans l&rsquo;Eglise catholique   le Rapport Sauv\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/03\/nouvelle-reunion-debat-a-lamicale-laique-de-concarneau\/\">Nouvelle r\u00e9union-d\u00e9bat   \u00e0               l&rsquo;Amicale La\u00efque de Concarneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/30\/lassemblee-generale-extraordinaire-des-ami-e-s-de-la-vigie-de-la-laicite\/\">L&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire  des  Ami.e.s de  La Vigie de la La\u00efcit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/18\/reprise-des-activites-a-lamicale-laique-de-concarneau-f-29900\/\">Reprise des activit\u00e9s \u00e0 l&rsquo;Amicale la\u00efque  de  Concarneau (F-29900)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/10\/pourquoi-la-france-a-t-elle-ete-incapable-de-trouver-un-vaccin-contre-la-covid-19\/\">Pourquoi la France a -t-elle \u00e9t\u00e9 incapable  de trouver un vaccin   contre la Covid-19  ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/10\/grandeur-decadence-et-miseres-de-la-rentree-scolaire-2021-elements-de-chronique-extraits-de-la-presse-dechainee\/\">Grandeur, d\u00e9cadence et mis\u00e8res  de la rentr\u00e9e scolaire 2021 !  El\u00e9ments de chronique extraits  de la presse d\u00e9cha\u00een\u00e9e<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/08\/pronote-ou-les-ambiguites-dun-droit-a-la-deconnexion-pour-les-professeurs\/\">\u00abPronote \u00bb ou les ambigu\u00eft\u00e9s d\u2019un \u00ab droit \u00e0 la d\u00e9connexion \u00bb pour les professeurs .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/03\/communiquer-et-penser-selon-les-dernieres-tendances-avec-les-options-linguistiques-djeunn-globish-bougliboulga\/\">Communiquer (et penser) selon les derni\u00e8res tendances  avec les options linguistiques  \u00ab\u00a0djeunn-globish-bougliboulga \u00ab\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/03\/sombres-turpitudes-ecclesiales-au-vatican\/\">Sombres turpitudes eccl\u00e9siales  au Vatican<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/29\/un-florilege-dactualites-brulantes-dans-le-numero-1276-de-rentree-de-marianne-27-aout-2-septembre-2021\/\">Un floril\u00e8ge d&rsquo;actualit\u00e9s br\u00fblantes dans  le num\u00e9ro  1276 de rentr\u00e9e  de  Marianne  (27 ao\u00fbt-2 septembre 2021)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/28\/picorer-des-glanes-de-pour-la-science-4\/\">Picorer des glanes  de  Pour La Science  (4)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/27\/contre-la-dictature-de-la-connerie-le-trop-cons-dindignation-et-dhumeur\/\">Contre la dictature de la connerie :  le \u00ab\u00a0Trop cons!\u00a0\u00bb d&rsquo;indignation et d&rsquo;humeur<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/11\/plaidoyer-embellie-de-la-periode-estivale-pandemique-2021-occupee-par-les-antis\/\">\u00ab\u00a0Plaidoyer-embellie\u00a0\u00bb  de la p\u00e9riode estivale pand\u00e9mique 2021  occup\u00e9e par les \u00ab\u00a0ANTIs&#8230;!\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/09\/limmunite-la-vie-pour-une-autre-immunologie-de-marc-daeron-lu-par-c-kintzler\/\">\u00ab L\u2019Immunit\u00e9, la vie. Pour une autre Immunologie\u201d de Marc Da\u00ebron, lu par C. Kintzler<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/05\/controverses-sur-la-vaccination-anti-covid-19-et-histoire-de-la-resistance-aux-vaccins\/\">Controverses sur la vaccination anti-Covid 19  et  Histoire de la r\u00e9sistance aux vaccins<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/04\/picorer-des-glanes-de-pour-la-science-3\/\">Picorer des glanes de Pour La Science (3)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/04\/penser-ecrire-orthographier-les-points-sur-les-i\/\">Penser, \u00e9crire , orthographier : les points sur les i !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/01\/lassociation-pour-la-sauvegarde-et-la-valorisation-du-patrimoine-normalien-du-finistere-asvpnf-publie-sa-quatrieme-lettre-dinformation\/\">L&rsquo;Association pour la Sauvegarde et la Valorisation du Patrimoine Normalien du Finist\u00e8re  (ASVPNF )  publie sa quatri\u00e8me Lettre d&rsquo;Information<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/20\/seule-la-vaccination-peut-nous-permettre-le-retour-a-la-vie-normale\/\">Seule la vaccination peut nous permettre  le retour \u00e0 la vie normale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/11\/hommage-a-axel-kahn-savant-et-moraliste\/\">Hommage \u00e0 Axel Kahn , savant et moraliste<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/11\/aux-difficultes-de-lecole-publique-laique-fallait-il-ajouter-celles-de-de-la-fcpe-les-cinq-polemiques\/\">Aux  difficult\u00e9s de l&rsquo;Ecole publique la\u00efque fallait-il ajouter celles de   de la FCPE :  Les cinq pol\u00e9miques<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/07\/analyse-de-la-vigie-de-la-laicite-a-propos-du-projet-de-loi-confortant-le-respect-des-principes-de-la-republique\/\">Analyse de la Vigie de la la\u00efcit\u00e9 \u00e0 propos du projet de loi  \u00ab confortant le respect des principes de la R\u00e9publique \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/04\/la-liberte-guidant-mila\/\">La Libert\u00e9 guidant Mila<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/23\/apprendre-ou-reapprendre-a-enseigner-la-laicite-a-lecole-publique-en-2021-revenir-aux-fondamentaux-pour-ne-point-sombrer-dans-le-catechisme-republicain\/\">Apprendre ou r\u00e9apprendre \u00e0 enseigner la la\u00efcit\u00e9 \u00e0 l&rsquo;\u00e9cole publique en  2021  Revenir aux fondamentaux pour ne point sombrer dans le cat\u00e9chisme r\u00e9publicain<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/23\/laicite-le-rapport-obin-et-la-politique-blanquer-par-francois-jarraud-cafe-pedagogique-16-juin-2021\/\">La\u00efcit\u00e9 , le rapport Obin et la politique Blanquer     par     Fran\u00e7ois Jarraud .    Caf\u00e9 p\u00e9dagogique, 16 juin 2021<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/13\/150-ans-apres-rendre-hommage-aux-martyrs-de-la-commune-de-paris-de-1871-dechaine-encore-les-passions\/\">150 ans  apr\u00e8s , rendre hommage aux martyrs de la  Commune de Paris de 1871 d\u00e9cha\u00eene encore les passions<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/07\/amicale-laique-de-concarneau-nouvel-evenement\/\">Amicale la\u00efque de Concarneau        Nouvel \u00e9v\u00e8nement<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/22\/amicale-laique-de-concarneau-reprise-des-activites\/\">Amicale La\u00efque de Concarneau              Reprise des activit\u00e9s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/22\/la-lettre-aux-professeurs-sur-la-liberte-dexpression-de-francois-heran-revisitee-dans-le-detail-par-veronique-taquin\/\">La Lettre aux professeurs sur la libert\u00e9 d\u2019expression  de Fran\u00e7ois H\u00e9ran  revisit\u00e9e dans le d\u00e9tail par V\u00e9ronique Taquin<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/22\/la-raison-deglise-lemporte-sur-la-raison-au-sein-de-la-hierarchie-ecclesiale-pour-traiter-des-abus-sexuels-du-clerge-hexagonal\/\">La raison d&rsquo;Eglise l&#8217;emporte sur la Raison au sein de la hi\u00e9rarchie eccl\u00e9siale  pour traiter des abus sexuels du clerg\u00e9 hexagonal.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/18\/echos-de-turpitudes-criminelles-vaticanes-meurtres-au-saint-siege-laffaire-tornay-estermann\/\">Echos de turpitudes  criminelles vaticanes:  Meurtres au Saint-Si\u00e8ge, l&rsquo;affaire  Tornay-Estermann.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/18\/la-science-a-lepreuve-de-la-defiance\/\">La Science \u00e0 l&rsquo;\u00e9preuve de la d\u00e9fiance<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/08\/pour-eviter-de-deconstruire-lhistoire-des-institutrices-et-instituteurs-du-finistere\/\">Pour \u00e9viter de d\u00e9construire  l&rsquo;histoire  des  Institutrices et Instituteurs du Finist\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/02\/linformation-comme-bien-public-journee-mondiale-de-la-liberte-de-la-presse-3-mai-2021\/\">\u00ab\u00a0L&rsquo;information comme bien public \u00a0\u00bb   Journ\u00e9e mondiale de la Libert\u00e9 de la Presse       3 mai 2021<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/28\/semaine-mondiale-de-leducation-26-30-avril-2021\/\">SEMAINE MONDIALE DE L&rsquo;EDUCATION           (26-30 avril 2021)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/25\/honorer-lhistoire-tragique-du-peuple-armenien-le-communique-president-des-etats-unis-du-du-24-avril-2021-sur-la-reconnaissance-du-genocide-des-armeniens-par-les-ottomans\/\">Honorer l&rsquo;histoire tragique du peuple Arm\u00e9nien. Le communiqu\u00e9\u00a0pr\u00e9sident des Etats-Unis du\u00a0du 24 avril 2021\u00a0sur la reconnaissance du g\u00e9nocide des Arm\u00e9niens par les ottomans.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/23\/etats-generaux-de-la-laicite-trop-de-questions-sans-reponse\/\">\u00ab\u00a0Etats g\u00e9n\u00e9raux\u00a0\u00bb de la La\u00efcit\u00e9&#8230;                      Trop de questions sans r\u00e9ponse  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/19\/pour-le-moral-des-detracteurs-detats-generaux-de-la-laicite-reunis-a-contretemps-le-betisier-laico-sceptique\/\">Pour le moral des d\u00e9tracteurs d&rsquo;\u00e9tats g\u00e9n\u00e9raux de la la\u00efcit\u00e9 r\u00e9unis \u00e0 contretemps:       \u00ab\u00a0Le b\u00eatisier la\u00efco-sceptique\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/18\/la-question-de-confiance-de-pour-la-science-2021-522\/\">La question de confiance de Pour la Science      (2021, 522)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/18\/lannonce-de-la-tenue-inopinee-d-etats-generaux-de-la-laicite-par-le-journal-du-dimanche-le-18-avril-2021-communique-de-lasvpnf\/\">L&rsquo;annonce de la tenue inopin\u00e9e  d&rsquo; \u00e9tats g\u00e9n\u00e9raux  de la la\u00efcit\u00e9  par   le Journal du Dimanche le 18 avril 2021.  Communiqu\u00e9 de l&rsquo;ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/18\/la-pandemie-due-au-sars-cov-2-revelatrice-des-maux-de-notre-societe\/\">La pand\u00e9mie due au Sars-CoV-2,                     r\u00e9v\u00e9latrice des maux de notre soci\u00e9t\u00e9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/06\/des-outils-precieux-pour-comprendre-et-pour-defendre-la-laicite-a-la-francaise-au-moment-ou-elle-est-attaquee-de-toutes-parts\/\">Des outils pr\u00e9cieux pour comprendre et pour d\u00e9fendre la la\u00efcit\u00e9 \u00e0 la fran\u00e7aise   au moment o\u00f9 elle est attaqu\u00e9e de toutes parts  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/04\/sur-les-publications-recentes-de-catherine-kintzler-devolues-a-la-laicite\/\">Sur les publications r\u00e9centes de Catherine Kintzler d\u00e9volues \u00e0 la la\u00efcit\u00e9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/23\/resister-a-lintimidation-des-nouveaux-inquisiteurs\/\">R\u00e9sister \u00e0 l&rsquo;intimidation des nouveaux inquisiteurs  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/03\/celebration-de-la-journee-internationale-pour-les-droits-des-femmes-quimper-6-mars-2021\/\">C\u00e9l\u00e9bration de la Journ\u00e9e Internationale pour les Droits des  Femmes                                            Quimper; 6 mars 2021.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/18\/haro-sur-le-professeur-de-philosophie-defenseur-sans-concession-de-la-laicite-et-de-la-liberte-dexpression\/\">Haro sur le professeur de philosophie, d\u00e9fenseur sans concession de la la\u00efcit\u00e9  et de la libert\u00e9 d&rsquo;expression !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/14\/la-defense-de-la-liberte-de-penser-et-de-celle-de-la-liberte-dexpression-son-corollaire\/\">La d\u00e9fense de la libert\u00e9 de penser  et de celle de  la libert\u00e9  d&rsquo;expression son corollaire.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/11\/a-trappes-f-78190-en-2021-un-professeur-de-philosophie-defenseur-de-la-liberte-de-penser-et-de-la-liberte-dexpression-est-protege-dans-lexercice-de-son-metier-denseignant-par-la-police\/\">A Trappes (F-78190) en 2021, un professeur de philosophie d\u00e9fenseur de la libert\u00e9 de penser et de la libert\u00e9 d&rsquo;expression, est  prot\u00e9g\u00e9 dans l&rsquo;exercice de son m\u00e9tier d&rsquo;enseignant par la police !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/06\/defendre-encore-et-toujours-nos-libertes\/\">D\u00e9fendre ,encore et toujours nos libert\u00e9s !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/01\/adhesions-et-readhesions-2021-a-lassociation-asvpnf\/\">Adh\u00e9sions et r\u00e9adh\u00e9sions  2021 \u00e0 l&rsquo;Association ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/28\/la-proposition-de-loi-relative-aux-principes-de-la-republique-tout-faire-pour-eviter-la-remise-en-cause-de-la-loi-de-separation-de-1905-et-les-cadeaux-royaux-de-letat-aux-cultes\/\">La proposition de loi relative aux principes de la R\u00e9publique :  tout faire pour \u00e9viter  la remise en cause de la loi de s\u00e9paration de 1905  et les cadeaux royaux de l&rsquo;Etat aux cultes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/27\/la-proposition-de-loi-n3452-relative-a-la-securite-globale-debattue-par-les-parlementaires-remet-elle-en-cause-certains-des-fondements-de-la-loi-de-1901-relative-aux-associations\/\">La proposition  de loi n\u00b03452 relative \u00e0 la s\u00e9curit\u00e9  globale, d\u00e9battue par  les parlementaires,  remet-elle en cause  certains des  fondements de  la Loi de 1901 relative aux Associations?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/24\/troisieme-journee-internationale-de-leducation-25-janvier-2021\/\">Troisi\u00e8me journ\u00e9e internationale de l&rsquo;\u00e9ducation  (  25 janvier 2021)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/13\/faire-vivre-la-laicite-et-la-mixite-sociale-a-lecole-publique\/\">Faire vivre la la\u00efcit\u00e9 et la mixit\u00e9 sociale  \u00e0 l&rsquo;\u00e9cole publique !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/12\/faire-face-aux-contestations-de-la-laicite-et-aux-derives-du-separatisme\/\">Faire face aux contestations de la la\u00efcit\u00e9                     et aux d\u00e9rives du s\u00e9paratisme.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/01\/les-voeux-de-lassociation-pour-la-sauvegarde-et-la-valorisation-du-patrimoine-normalien-du-finistere-asvpnf-pour-2021\/\">Les voeux de  l&rsquo;Association pour la Sauvegarde et la Valorisation du Patrimoine Normalien du Finist\u00e8re (ASVPNF) pour 2021.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/18\/regard-de-femme-sur-un-memorial-orphelin\/\">Regard de femme sur un m\u00e9morial orphelin<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/18\/a-propos-de-larticle-24-du-projet-de-loi-securite-globale-novembre-2020\/\">A propos de l&rsquo;article 24 du projet  de loi                              \u00ab s\u00e9curit\u00e9 globale \u00bb                                                                (novembre 2020)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/13\/lorsque-les-accommodements-raisonnables-du-conseil-detat-jettent-le-voile-et-le-doute-sur-la-volonte-politique-dun-elu-de-la-republique\/\">Lorsque  les accommodements raisonnables du Conseil d&rsquo;\u00e9tat  \u00ab\u00a0jettent le voile\u00a0\u00bb et le doute  sur la volont\u00e9 politique d&rsquo;un \u00e9lu de la R\u00e9publique.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/23\/linterview-de-c-kintzler-philosophe-de-leducation-et-de-la-laicite-par-philosophie-magazine-sur-le-terrorisme-islamiste-considere-que-lecole-est-a-sa-disposition-et-entend-lu\/\">L&rsquo;interview de C. KINTZLER , philosophe de l&rsquo;\u00e9ducation et de la la\u00efcit\u00e9,   par Philosophie magazine sur :         \u00a0\u00bb Le terrorisme islamiste  consid\u00e8re que l&rsquo;\u00e9cole est \u00e0 sa disposition et entend lui dicter sa loi\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/21\/la-fronde-des-croises-de-la-messe-contre-les-lois-de-la-republique\/\">La fronde des crois\u00e9s de la messe            contre les lois de la R\u00e9publique.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/20\/20-novembre-2020-journee-internationale-des-droits-de-lenfant\/\">20 novembre 2020 : Journ\u00e9e internationale  des  Droits de l&rsquo;Enfant .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/13\/11-novembre-2020-fleurissement-du-monument-aux-instituteurs-du-finistere-morts-pour-la-france\/\">11 novembre 2020 : Fleurissement  du  Monument aux Instituteurs du Finist\u00e8re   Morts Pour la France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/02\/ne-pas-renoncer-leducation-a-la-liberte-dexpression-reste-larme-la-plus-puissante-pour-changer-le-monde\/\">Ne pas renoncer : l&rsquo;\u00e9ducation  \u00e0 la libert\u00e9 d&rsquo;expression reste \u00ab\u00a0l&rsquo;arme la plus puissante  pour changer le monde\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/31\/le-terrorisme-djihadiste-radical-et-la-fragilite-de-nos-institutions-republicaines-et-celle-de-nos-libertes-fondamentales\/\">Le terrorisme  djihadiste radical et la fragilit\u00e9 de  nos institutions r\u00e9publicaines  et  celle de nos libert\u00e9s fondamentales.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/22\/la-libre-pensee-rend-hommage-a-samuel-paty-et-clame-l-irrefragabilite-de-la-liberte-dexpression-dans-la-republique-francaise-et-ses-institutions\/\">La Libre Pens\u00e9e rend hommage \u00e0 Samuel Paty  et clame l&rsquo; irr\u00e9fragabilit\u00e9 de la libert\u00e9 d&rsquo;expression  dans la R\u00e9publique fran\u00e7aise et ses institutions.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/20\/ce-que-nous-voulons-et-pouvons-savoir-dune-pandemie\/\">\u00a0\u00bb Ce que nous voulons et pouvons savoir d&rsquo;une pand\u00e9mie\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/20\/restons-unis-pour-defendre-et-restaurer-la-laicite-de-notre-republique\/\">Restons unis pour d\u00e9fendre et restaurer la la\u00efcit\u00e9 de notre R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/20\/a-la-memoire-de-samuel-paty-professeur-sauvagement-decapite-pour-avoir-enseigne-la-liberte-dexpression-a-lecole-de-la-republique\/\">A la m\u00e9moire de Samuel Paty,  professeur sauvagement d\u00e9capit\u00e9 pour avoir enseign\u00e9 la libert\u00e9 d&rsquo;expression \u00e0 l&rsquo;Ecole de la R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/17\/apres-lattentat-islamiste-de-conflans-sainte-honorine-communique-de-lasvpnf-17-10-2020\/\">Apr\u00e8s l&rsquo;attentat islamiste de Conflans-Sainte-Honorine.  Communiqu\u00e9 de l&rsquo;ASVPNF (17 10 2020)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/05\/la-memoire-et-lesprit-normaliens-en-action-dans-le-departement-de-la-meuse\/\">La m\u00e9moire et l&rsquo;esprit normaliens en action   dans le    d\u00e9partement de la Meuse !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/22\/crise-sanitaire-oblige-report-de-lassemblee-generale-ordinaire-2020-de-l-asvpnf\/\">Crise sanitaire oblige :  Report de l&rsquo;Assembl\u00e9e G\u00e9n\u00e9rale Ordinaire 2020 de l&rsquo; ASVPNF.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/20\/reprise-des-activites-a-lamicale-laique-de-concarneau-2\/\">Reprise des activit\u00e9s \u00e0 l&rsquo;amicale la\u00efque de Concarneau.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/15\/pour-un-travail-socialement-juste-et-ecologiquement-durable\/\">Pour un travail socialement juste  et  \u00e9cologiquement durable !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/15\/dans-quelle-mesure-les-grandes-pestes-du-passe-peuvent-elles-eclairer-la-pandemie-de-covid-19\/\">Dans quelle mesure les grandes pestes du pass\u00e9  peuvent-elles \u00e9clairer la pand\u00e9mie de Covid-19 ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/04\/quatre-septembre-2020-il-y-a-150-ans-le-4-septembre-1870-fut-proclamee-la-3e-republique\/\">Quatre septembre 2020; il y a 150 ans le 4 septembre 1870 fut proclam\u00e9e la 3\u00e8 R\u00e9publique .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/04\/en-1872-aux-debuts-de-la-toute-jeune-3e-republique-jean-de-quimper-ecrit-a-jean-de-la-fontaine-pour-laver-laffront-du-chartier-embourbe\/\">En 1872, aux d\u00e9buts de la toute  jeune 3\u00e8 R\u00e9publique , Jean de Quimper \u00e9crit \u00e0 Jean de La Fontaine  pour laver l&rsquo;affront  du \u00ab\u00a0Chartier embourb\u00e9\u00a0\u00bb !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/04\/4-septembre-2020-celebration-du-150-e-anniversaire-de-la-republique-francaise\/\">4 septembre 2020    C\u00e9l\u00e9bration du 150 \u00e8 anniversaire  de la R\u00e9publique fran\u00e7aise<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/26\/pour-le-combat-feministe-universaliste-avoir-honte-de-ne-pas-lutter\/\">Pour le combat f\u00e9ministe universaliste, avoir honte de ne pas lutter !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/25\/lappropriation-abusive-de-la-langue-communeune-demarche-antidemocratique\/\">L&rsquo;appropriation abusive de la langue commune;une d\u00e9marche antid\u00e9mocratique  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/31\/deces-de-gisele-halimi\/\">D\u00e9c\u00e8s de Gis\u00e8le HALIMI<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/29\/le-140e-anniversaire-de-la-fete-nationale-du-14-juillet\/\">Le 140\u00e8 anniversaire de la F\u00eate Nationale du 14 juillet .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/26\/la-pandemie-due-au-sars-cov-2-a-lorigine-dun-veritable-genocide-au-bresil-lappel-dun-frere-dominicain-aux-amis-de-letranger\/\">La pand\u00e9mie due au SARS-CoV-2  \u00e0 l&rsquo;origine d&rsquo;un v\u00e9ritable g\u00e9nocide au Br\u00e9sil : l&rsquo;appel d&rsquo;un fr\u00e8re dominicain aux  amis de l&rsquo;\u00e9tranger!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/28\/quelle-est-donc-lurgence-pour-le-jour-dapres\/\">Quelle est donc l&rsquo;urgence pour le jour d&rsquo;apr\u00e8s ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/28\/la-succession-de-lex-cardinal-barbarin-le-gag-sans-precedent-de-anne-soupa-une-affaire-a-suivre\/\">La succession de l&rsquo;ex-cardinal Barbarin &#8211;\u00a0le gag sans pr\u00e9c\u00e9dent de\u00a0 Anne SOUPA ; une affaire \u00e0 suivre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/10-mai-2020-journee-commemorative-de-labolition-de-lesclavage\/\">10 mai 2020 \u00a0&#8211;\u00a0Journ\u00e9e comm\u00e9morative\u00a0de\u00a0l&rsquo;abolition de l&rsquo;esclavage<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/le-monde-hostile-des-virus-une-verite-a-temperer\/\">Le monde hostile des virus ; une v\u00e9rit\u00e9 \u00e0 temp\u00e9rer !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/21\/la-104e-commemoration-du-genocide-des-armeniens-la-pandemie-de-covid-19-en-cours-ne-doit-laisser-place-a-aucune-forme-de-negationnisme\/\">La 104\u00e8 comm\u00e9moration du g\u00e9nocide des Arm\u00e9niens :\u00a0la pand\u00e9mie de Covid 19 en cours ne doit\u00a0 laisser place \u00e0 aucune forme de n\u00e9gationnisme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/21\/quelles-lecons-tirer-de-la-pandemie-mortelle-provoquee-par-le-coronavirus-sars-cov-2-pour-jeter-les-bases-dun-monde-meilleur-pour-notre-planete-et-lhumanite-quelle-porte\/\">Quelles le\u00e7ons\u00a0 tirer de la pand\u00e9mie mortelle provoqu\u00e9e par le coronavirus\u00a0 SARS-CoV-2 pour jeter les bases\u00a0 d&rsquo;un monde meilleur\u00a0 pour notre plan\u00e8te et l&rsquo;humanit\u00e9 qu&rsquo;elle porte ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/21\/la-nature-en-train-de-se-revolter-avec-une-epidemie-de-covid-19-lhumilite-vicieuse-des-adorateurs-du-chagrin\/\">\u00ab\u00a0La nature en train de se r\u00e9volter\u00a0\u00bb\u00a0avec une \u00e9pid\u00e9mie de\u00a0 Covid -19.\u00a0L&rsquo;humilit\u00e9\u00a0 vicieuse\u00a0 des adorateurs du chagrin<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/lirruption-du-sars-cov-2-cruel-revelateur-dune-catastrophe-planetaire-et-le-point-alpha-pour-changer-la-marche-du-monde\/\">L&rsquo;irruption du SARS-CoV-2 cruel r\u00e9v\u00e9lateur\u00a0 d&rsquo;une catastrophe plan\u00e9taire et le \u00ab\u00a0point alpha\u00a0\u00bb pour changer \u00a0la marche\u00a0 du monde&#8230;\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/31\/stupeur-et-indignation-a-la-revelation-des-abus-sexuels-de-jean-vanier-1928-2019-president-fondateur-des-communautes-de-larche\/\">Stupeur et indignation \u00e0 la r\u00e9v\u00e9lation des abus sexuels\u00a0de Jean Vanier (1928-2019), pr\u00e9sident-fondateur des Communaut\u00e9s de l&rsquo;Arche<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/24\/confinement-mode-demploi-pour-sen-sortir-enfermons-nous-et-deconfinons-nos-esprits\/\">Confinement : mode d&#8217;emploi !\u00a0Pour s&rsquo;en sortir, enfermons-nous\u00a0et\u00a0d\u00e9confinons nos esprits !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/08\/promotion-enf-1946-1949-atomick-la-bien-nommee-recemment-remise-a-jour\/\">Promotion ENF 1946-1949\u00a0 ATOMICK, la bien nomm\u00e9e, r\u00e9cemment remise \u00e0 jour !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/22\/pedophilie-dans-leglise-et-clericalisme-aux-abois-codicille-pour-des-confidences\/\">P\u00e9dophilie dans l&rsquo;\u00e9glise et cl\u00e9ricalisme aux abois\u00a0&#8211;\u00a0\u00ab\u00a0Codicille pour des confidences\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/22\/nul-ne-pourra-etre-inquiete-pour-ses-opinions-meme-religieuses\/\">\u00a0\u00bb\u00a0Nul ne pourra\u00a0 \u00eatre inqui\u00e9t\u00e9 pour ses opinions, m\u00eame religieuses\u00a0\u00ab\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/asvpnf-appel-a-cotisation-2020\/\">ASVPNF : Appel \u00e0 cotisation 2020.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/sous-legide-de-la-republique-francaise-le-blaspheme-non-defendu-par-la-loi-se-presente-comme-une-atteinte-a-rien-du-tout-il-ne-peut-donc-faire-lobjet-de-delit\/\">Sous l&rsquo;\u00e9gide de la R\u00e9publique Fran\u00e7aise le blasph\u00e8me,\u00a0non\u00a0 d\u00e9fendu\u00a0 par la loi, se pr\u00e9sente comme\u00a0une atteinte\u00a0\u00e0\u00a0rien du tout. Il ne peut donc faire l&rsquo;objet de d\u00e9lit<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/campagne-des-elections-municipales-de-mars-2020-la-contribution-du-comite-laicite-35\/\">Campagne des \u00e9lections municipales de mars 2020 &#8211;\u00a0La contribution du Comit\u00e9 la\u00efcit\u00e9 35<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/laffaire-mila-et-le-nouveau-delit-de-blaspheme\/\">L&rsquo;affaire Mila et le \u00ab\u00a0nouveau d\u00e9lit\u00a0\u00bb de blasph\u00e8me<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/13\/chronique-anticlericale-suite-une-turpitude-episcopale-a-lencontre-du-devoir-dhumanite\/\">Chronique anticl\u00e9ricale (suite) &#8211;\u00a0Une turpitude \u00e9piscopale\u00a0 \u00e0 l&rsquo;encontre du devoir d&rsquo;humanit\u00e9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/13\/27-janvier-1945-27-janvier-2020-75-ans-apres-la-liberation-du-camp-dextermination-nazi-allemand-dauschwitz-par-larmee-rouge-pourquoi-devient-il-si-difficile-de-nommer-et-de-commemor\/\">27 janvier 1945-27 janvier 2020.\u00a0\u00a0 75 ans apr\u00e8s la lib\u00e9ration du camp d&rsquo;extermination nazi allemand d&rsquo;AUSCHWITZ par l&rsquo;Arm\u00e9e Rouge pourquoi devient-il si difficile de nommer et de comm\u00e9morer ce pass\u00e9 barbare\u00a0si tragique pour l&rsquo;humanit\u00e9 ?\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/01\/12\/encore-du-nouveau-a-lamicale-laique-de-concarneau\/\">Encore du nouveau \u00e0 l&rsquo;Amicale La\u00efque de Concarneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/31\/voeux-pour-2020-des-membres-du-bureau-de-lasvpnf-aux-adherents-donateurs-associations-amies-de-lassociation-ainsi-quaux-collectivites-territoriales-et-institutions-academiques-lassurant-de-l\/\">Voeux pour 2020 des membres du Bureau de l&rsquo;ASVPNF aux adh\u00e9rents, donateurs, associations amies de l&rsquo;Association ainsi qu&rsquo;aux collectivit\u00e9s territoriales et institutions acad\u00e9miques l&rsquo;assurant de leur soutien<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/la-promotion-orpheline-provisoirement-baptisee-1970-les-russes-appellation-hautement-premonitoire-a-recemment-ete-identifiee\/\">La promotion orpheline provisoirement baptis\u00e9e :\u00a01970, Les \u00ab\u00a0Russes\u00a0\u00bb, appellation\u00a0hautement pr\u00e9monitoire,\u00a0a r\u00e9cemment \u00e9t\u00e9 identifi\u00e9e<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/ressources-patrimoniales-normaliennes-suite-des-collecteurs-de-memoire-poursuivent-patiemment-leur-travail\/\">Ressources patrimoniales normaliennes (suite&#8230;) &#8211;\u00a0Des collecteurs de m\u00e9moire poursuivent patiemment leur travail !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/un-additif-important-au-livre-dor-de-la-promotion-belzebuth-1955-1959\/\">Un additif important au \u00ab\u00a0livre d&rsquo;or\u00a0\u00bb de la Promotion Belzebuth (1955-1959)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/chronique-anticlericale-faut-il-sauver-le-soldat-de-leglise-latine-barbarin\/\">Chronique anticl\u00e9ricale. Faut-il sauver le soldat de l&rsquo;\u00e9glise latine BARBARIN\u00a0 ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/commemoration-du-11-novembre-2019-fleurissement-du-monument-des-instituteurs-et-institutrices-du-finistere-mortes-pour-la-france\/\">Comm\u00e9moration du 11 novembre 2019.\u00a0Fleurissement du Monument des Instituteurs et Institutrices\u00a0 du Finist\u00e8re\u00a0 mort(e)s pour la France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/le-port-du-voile-islamique-dans-les-services-publics-et-notamment-a-lecole-publique-cest-laffaire-de-qui\/\">Le port du voile islamique dans les services publics et notamment \u00e0 l&rsquo;Ecole publique; c&rsquo;est l&rsquo;affaire de qui ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/convocation-de-lago-de-lasvpnf-du-18-novembre-2019\/\">Convocation de l&rsquo;AGO de l&rsquo;ASVPNF du 18 novembre 2019.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/amicale-laique-de-concarneau-nouvelles-activites\/\">AMICALE LA\u00cfQUE de CONCARNEAU : Nouvelles activit\u00e9s\u00a0\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/leveque-de-montauban-organise-une-session-de-priere-pour-les-pretres-pedophiles\/\">L&rsquo;\u00e9v\u00eaque de MONTAUBAN\u00a0 organise une session de pri\u00e8re pour les pr\u00eatres p\u00e9dophiles<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/promotions-orphelines-retrouvees-les-menestrels-les-satellites\/\">Promotions \u00ab\u00a0orphelines\u00a0\u00bb retrouv\u00e9es (Les Menestrels, Les Satellites)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/promotions-orphelines-retrouvees-le-pourquoi-pas-les-aiglons-herakles\/\">Promotions orphelines retrouv\u00e9es (Le Pourquoi Pas, Les Aiglons, H\u00e9rakl\u00e8s)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/rechauffement-climatique-les-regrettables-erreurs-et-detournements-du-giec\/\">R\u00e9chauffement climatique ???\u00a0Les regrettables\u00a0 erreurs et d\u00e9tournements du GIEC<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/une-respiration-laique-bien-salutaire-accompagnateurs-des-sorties-scolaires-et-si-on-leur-proposait-la-respiration-laique\/\">Une respiration la\u00efque bien salutaire\u00a0 !\u00a0\u00a0\u00bb Accompagnateurs des sorties scolaires : et si on leur proposait la Respiration La\u00efque\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/10\/17\/amicale-laique-de-concarneau-nouvelle-activite-doctobre-2019\/\">Amicale la\u00efque de CONCARNEAU &#8211;\u00a0Nouvelle activit\u00e9 d&rsquo;octobre 2019<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/10\/03\/le-temps-des-instituteurs-guy-dessauw\/\">\u00ab\u00a0Le temps des\u00a0 instituteurs\u00a0\u00bb (Guy Dessauw)\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/les-oeuvres-inedites-de-pierre-jakez-helias-revelees-a-loccasion-du-vingt-quatrieme-anniversaire-de-son-deces\/\">Les\u00a0oeuvres\u00a0\u00a0in\u00e9dites de Pierre Jakez H\u00e9lias r\u00e9v\u00e9l\u00e9es \u00e0 l&rsquo;occasion du vingt quatri\u00e8me anniversaire de son d\u00e9c\u00e8s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/des-mesures-contre-la-marginalisation-sociale-par-lillectronisme\/\">Des mesures contre la marginalisation sociale par l&rsquo;illectronisme ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/contre-lembrigadement-de-nos-enfants-et-de-notre-jeunesse-au-nom-du-rechauffement-climatique\/\">Contre l&#8217;embrigadement de nos enfants et de notre jeunesse au nom du r\u00e9chauffement climatique !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/13\/amicale-laique-de-concarneau-reprise-des-activites-annee-2019-2020\/\">Amicale la\u00efque de Concarneau : reprise des activit\u00e9s (ann\u00e9e 2019-2020)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/08\/parution-de-la-lettre-dinformation-n3-de-lasvpnf\/\">Parution de la Lettre d&rsquo;Information n\u00b03 de l&rsquo;ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/01\/parution-de-la-3e-lettre-dinformation-de-lassociation-pour-la-sauvegarde-et-la-valorisation-du-patrimoine-normalien-du-finistere-asvpnf\/\">Parution de la 3\u00e8 Lettre d&rsquo;Information\u00a0 de l&rsquo;Association pour la Sauvegarde\u00a0 et la Valorisation du Patrimoine Normalien du Finist\u00e8re (ASVPNF)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/04\/justice-divine-et-justice-humaine\/\">Justice divine et justice humaine<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/04\/credulite-ou-quand-les-croyances-vont-a-lencontre-de-ce-qui-est-prouve-par-toute-la-communaute-scientifique\/\">\u00ab\u00a0Cr\u00e9dulit\u00e9\u00a0\u00bb &#8211;\u00a0ou\u00a0&#8211;\u00a0Quand les croyances\u00a0 vont \u00e0 l&rsquo;encontre de ce qui est prouv\u00e9 par toute la communaut\u00e9 scientifique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/30\/expositions-et-rendez-vous-de-juillet-2019-au-munae-de-rouen\/\">Expositions et rendez-vous de juillet 2019 au MUNAE de Rouen<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/30\/activites-et-expositions-presentees-dans-la-lettre-dinformation-n8-de-lamnepe-amis-du-musee-national-de-leducation-des-musees-de-lecole-et-du-patrimoine-educatif\/\">Activit\u00e9s et expositions pr\u00e9sent\u00e9es dans la lettre d&rsquo;information n\u00b08 de l&rsquo;AMNEPE ( Amis du Mus\u00e9e National de l&rsquo;Education, des Mus\u00e9es de l&rsquo;Ecole et du Patrimoine Educatif ).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/03\/lamicale-laique-de-concarneau-fete-ses-quatre-vingts-ans\/\">L&rsquo;amicale la\u00efque de Concarneau f\u00eate ses quatre-vingts ans<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/28\/celebration-de-la-sixieme-journee-nationale-de-la-resistance\/\">C\u00e9l\u00e9bration de la sixi\u00e8me Journ\u00e9e nationale de la R\u00e9sistance<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/22\/le-musee-de-lecole-cree-par-jules-ferry-et-ferdinand-buisson-celebre-ses-140-ans\/\">Le Mus\u00e9e de l&rsquo;Ecole, cr\u00e9\u00e9 par Jules Ferry et\u00a0Ferdinand Buisson, c\u00e9l\u00e8bre ses 140 ans<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/13\/amicale-laique-de-concarneau-reunion-du-groupe-de-reflexion-le-15-mai-2019\/\">Amicale la\u00efque de Concarneau : R\u00e9union du groupe de r\u00e9flexion le  15 Mai 2019<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/13\/fleurissement-du-monument-aux-instituteurs-du-finistere-morts-pour-la-france\/\">Fleurissement du Monument aux Instituteurs du Finist\u00e8re Morts pour La France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/06\/journee-mondiale-2019-de-la-liberte-de-la-presse\/\">Journ\u00e9e Mondiale (2019) de la Libert\u00e9 de la Presse<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/journee-nationale-du-souvenir-des-victimes-et-des-heros-de-la-deportation-28-avril-2019\/\">Journ\u00e9e nationale du Souvenir des Victimes et des H\u00e9ros de la D\u00e9portation (28 avril 2019)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/lactualite-et-la-sauvegarde-de-nos-patrimoines\/\">L&rsquo;actualit\u00e9 et la sauvegarde de nos patrimoines !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/24-avril-2019-journee-nationale-de-commemoration-du-genocide-des-armeniens-medz-yeghern\/\">24 avril 2019 : Journ\u00e9e nationale de comm\u00e9moration du g\u00e9nocide des Arm\u00e9niens\u00a0 (Medz Yeghern)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/photos-de-promotions-eng\/\">Photos de Promotions ENG<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/25\/chronique-printaniere-des-turpitudes-ecclesiales-recentes-a-suivre\/\">Chronique printani\u00e8re des turpitudes eccl\u00e9siales r\u00e9centes (\u00e0 suivre)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/24\/intangibilite-de-la-loi-de-1905-sur-la-separation-des-eglises-et-de-letat-a-suivre\/\">Intangibilit\u00e9 de la LOI de 1905 sur la\u00a0 s\u00e9paration des \u00e9glises et de l&rsquo;Etat (\u00e0 suivre)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/18\/participons-aux-activites-exemplaires-de-lamicale-laique-de-concarneau\/\">Participons aux activit\u00e9s exemplaires de l&rsquo;Amicale la\u00efque de Concarneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/06\/celebrons-la-journee-internationale-2019-des-droits-des-femmes\/\">C\u00e9l\u00e9brons la Journ\u00e9e Internationale\u00a0 2019 des\u00a0Droits des Femmes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/24\/nouvel-evenement-a-lamicale-laique-de-concarneau-2\/\">Nouvel \u00e9v\u00e8nement \u00e0 l&rsquo;Amicale La\u00efque de Concarneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/20\/resister-sans-concession-a-lantisemitisme-et-a-toutes-les-autres-formes-de-haine-et-de-violence\/\">R\u00e9sister sans concession \u00e0 l&rsquo;antis\u00e9mitisme\u00a0 et \u00e0 toutes les autres formes de haine et de violence<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/17\/lettre-ouverte-4-fevrier-2019-de-la-libre-pensee-au-mouvement-laique-organise-pour-la-defense-de-la-loi-de-separation-de-1905\/\">Lettre ouverte (4 f\u00e9vrier 2019) de\u00a0la Libre Pens\u00e9e au mouvement la\u00efque organis\u00e9\u00a0 pour la d\u00e9fense de la Loi de S\u00e9paration de 1905<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/03\/nouvel-evenement-a-lamicale-laique-de-concarneau\/\">Nouvel \u00e9v\u00e8nement \u00e0 l&rsquo;Amicale La\u00efque de Concarneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/27\/27-janvier-2019-journee-de-la-memoire-des-genocides-et-de-la-prevention-des-crimes-contre-lhumanite\/\">27 janvier 2019 : \u00a0Journ\u00e9e de la M\u00e9moire des G\u00e9nocides et de la Pr\u00e9vention des Crimes contre l&rsquo;Humanit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/22\/nouvelle-reunion-debat-de-lamicale-laique-de-concarneau-mercredi-23-janvier-2019\/\">Nouvelle r\u00e9union-d\u00e9bat de l&rsquo;amicale La\u00efque de Concarneau (mercredi 23 janvier 2019)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/trois-mai-1928-fete-annuelle-des-anciens-eleves-des-ecoles-normales-de-quimper\/\">Trois mai 1928 : F\u00eate annuelle des anciens \u00e9l\u00e8ves des Ecoles Normales de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/pour-la-sauvegarde-de-lintangibilite-de-la-loi-de-separation-des-eglises-et-de-letat-du-9-decembre-1905\/\">POUR la sauvegarde de l&rsquo;intangibilit\u00e9 de la Loi de S\u00e9paration des \u00e9glises et de l&rsquo;Etat du 9 d\u00e9cembre 1905<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/redecouverte-des-associations-danciennes-et-danciens-eleves-des-ecoles-normales-de-quimper-fondees-en-1927\/\">\u00a0\u00ab\u00a0Red\u00e9couverte\u00a0\u00bb des associations\u00a0 d&rsquo;anciennes et\u00a0 d&rsquo;anciens \u00e9l\u00e8ves des Ecoles Normales de Quimper&#8230; fond\u00e9es en 1927<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/10\/la-carte-de-promotion-eng-1928-1931\/\">La carte de promotion ENG, 1928-1931<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/10\/celebration-du-70e-anniversaire-de-la-declaration-universelle-des-droits-de-lhommedudh\/\">C\u00e9l\u00e9bration du 70\u00e8 anniversaire de la D\u00e9claration Universelle des Droits de l&rsquo;Homme (DUDH)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/05\/pour-la-sauvegarde-de-la-loi-de-separation-des-eglises-et-de-letat-de-1905-sous-sa-forme-irrefragable-intangible-et-consolidee\/\">Pour la sauvegarde de la Loi de S\u00e9paration DES \u00e9glises\u00a0 et de l&rsquo;Etat\u00a0 de 1905 sous sa forme irr\u00e9fragable, intangible et consolid\u00e9e<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/11\/28\/promotion-sphynx-1956-1960\/\">Promotion SPHYNX &#8211; 1956-1960<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/11\/28\/collectage-de-notre-petit-patrimoine-a-suivre\/\">Collectage de notre petit patrimoine (\u00e0 suivre)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/11\/24\/la-promotion-armorique-1960-1964-longtemps-absente-de-nos-rubriques-a-ete-retrouvee-grace-aux-recherches-obstinees-de-quelques-amis-et-adherents\/\">La promotion ARMORIQUE (1960-1964), longtemps absente de nos rubriques, a \u00e9t\u00e9 \u00ab retrouv\u00e9e \u00bb gr\u00e2ce aux recherches obstin\u00e9es de quelques amis et adh\u00e9rents<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/11\/24\/amicale-laique-de-concarneau-prendre-date-des-prochaines-activites\/\">Amicale la\u00efque de Concarneau &#8211; Prendre date des prochaines activit\u00e9s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/11\/11\/fleurissement-du-monument-aux-morts-de-lancienne-cour-d-honneur-de-leng-de-quimper-a-l-occasion-de-la-celebration-anticipee-du-centenaire-de-l-armistice-de-la-grande-guerre-11-novembre-190\/\">Fleurissement du Monument aux Morts de l&rsquo;ancienne Cour d &lsquo;Honneur de l&rsquo;ENG de Quimper \u00e0 l&rsquo; occasion de la C\u00e9l\u00e9bration anticip\u00e9e du Centenaire de l &lsquo;Armistice de la Grande Guerre ( 11 novembre 1918 )<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/11\/09\/9-novembre-journee-internationale-contre-le-fascisme-et-lantisemitisme\/\">9 novembre \u2013 Journ\u00e9e internationale contre le fascisme et l\u2019antis\u00e9mitisme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/09\/24\/assemblee-generale-ordinaireag0-de-lasvpnf\/\">Assembl\u00e9e G\u00e9n\u00e9rale Ordinaire(AG0) de l&rsquo;ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/09\/15\/reprise-des-activites-a-lamicale-laique-de-concarneau\/\">Reprise des activit\u00e9s \u00e0 l&rsquo;Amicale La\u00efque de Concarneau&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/09\/12\/la-promotion-herakles-eng-quimper-1968-1972-celebre-le-cinquantenaire-de-son-entree-a-lecole-normale-dinstituteurs-de-quimper\/\">La Promotion H\u00e9rakl\u00e8s  (ENG QUIMPER, 1968-1972) c\u00e9l\u00e8bre le cinquantenaire de son entr\u00e9e \u00e0 l&rsquo;Ecole Normale d&rsquo;Instituteurs de  Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/10\/celestin-perrigault-dit-tintin-ancien-normalien-de-rennes-et-de-quimper-decore-de-la-legion-dhonneur-pour-son-implication-dans-la-resistance\/\">C\u00e9lestin Perrigault (dit Tintin), ancien normalien de Rennes et de Quimper, d\u00e9cor\u00e9 de la L\u00e9gion d&rsquo;Honneur, pour son implication dans la R\u00e9sistance<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/03\/le-nouveau-chanoine-de-latran\/\">Le nouveau chanoine de Latran<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/07\/08\/lenseignement-laique-obligatoire-des-faits-religieux\/\">L&rsquo;enseignement\u00a0 la\u00efque obligatoire des faits religieux<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/06\/15\/parution-du-bulletin-dinformation-n2-de-lasvpnf\/\">Parution du Bulletin d&rsquo;Information n\u00b02 de l&rsquo;ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/29\/appel-a-manifester-pour-dejouer-les-attaques-incessantes-contre-la-loi-de-separation-des-eglises-et-de-letat-loi-du-9-decembre-1905-portee-par-aristide-briand\/\">Appel \u00e0 manifester pour d\u00e9jouer les attaques incessantes contre la Loi de S\u00e9paration des \u00e9glises et de l&rsquo;Etat (Loi du 9 d\u00e9cembre 1905, port\u00e9e par Aristide Briand)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/25\/harmonie-de-leng-de-quimper-souvenirs-appel-a-contributions\/\">Harmonie de l&rsquo;ENG\u00a0 de Quimper&#8230; Souvenirs !\u00a0Appel \u00e0 contributions<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/14\/fleurissement-du-monument-aux-morts-de-leng-en-souvenir-du-8-mai-1945\/\">Fleurissement du Monument aux Morts de l&rsquo;ENG, en souvenir du\u00a0 8 mai 1945<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/10\/les-celebrations-du-10-mai-et-du-23-mai-2018\/\">Les c\u00e9l\u00e9brations\u00a0du 10 mai et du 23 mai 2018<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/ite-non-jam-missa-est-la-messe-nest-plus-dite\/\">Ite, non jam missa est (la messe n&rsquo;est plus dite).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/11\/nouvel-avatar-de-la-laicite-republicaine\/\">Nouvel avatar de la la\u00efcit\u00e9 r\u00e9publicaine<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/04\/4-avril-1968-4-avril-2018-celebration-du-cinquantieme-anniversaire-de-lassassinat-politique-de-martin-luther-king-1929-1968-par-un-segregationniste-blanc\/\">4 avril 1968-4 avril 2018 &#8211; C\u00e9l\u00e9bration du cinquanti\u00e8me anniversaire de\u00a0 l&rsquo;assassinat politique de MARTIN LUTHER KING (1929-1968) par un s\u00e9gr\u00e9gationniste blanc<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/02\/soutenons-lexemplarite-de-nos-amis-concarnois-et-participons-a-leur-prochaine-activite-dediee-a-la-laicite\/\">Soutenons l&rsquo;exemplarit\u00e9 de nos amis concarnois et participons \u00e0 leur prochaine activit\u00e9 d\u00e9di\u00e9e \u00e0 la la\u00efcit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/19\/deces-de-lastrophysicien-et-grand-humaniste-stephen-hawking\/\">D\u00e9c\u00e8s de l&rsquo;astrophysicien et grand humaniste\u00a0 Stephen HAWKING.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/16\/amicale-laique-de-concarneau-vigilante-et-sur-la-breche-nouveau-cycle-de-conferences-sur-la-liberte-de-conscience\/\">Amicale la\u00efque de Concarneau, vigilante et sur la br\u00e8che &#8211; Nouveau cycle de conf\u00e9rences sur la libert\u00e9 de conscience<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/06\/declaration-commune-pour-laide-active-a-mourir\/\">\u00ab\u00a0D\u00e9claration commune pour l&rsquo;Aide Active \u00e0 Mourir\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/06\/8-mars-2018-celebrons-la-journee-internationale-des-droits-des-femmes-journee-internationale-des-femmes\/\">8 Mars 2018: C\u00e9l\u00e9brons la Journ\u00e9e Internationale des Droits des Femmes (Journ\u00e9e internationale des femmes)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/16\/la-permanence-de-laction-laique-au-quotidien-21-fevrier\/\">La permanence de l&rsquo;action la\u00efque au quotidien &#8211; 21 f\u00e9vrier<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/14\/la-guerre-dalgerie-1954-1962-et-les-normaliens\/\">La Guerre d&rsquo;Alg\u00e9rie\u00a0(1954-1962) et les normaliens<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/nouvelle-mise-en-ligne-du-livre-de-jean-nedelec-1920-1980-60-ans-de-vie-militante-dans-le-finistere\/\">NOUVELLE MISE EN LIGNE DU LIVRE DE JEAN NEDELEC : \u00ab\u00a01920-1980 : 60 ans de vie militante dans le Finist\u00e8re\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/01\/30\/lasvpnf-apporte-un-soutien-sans-reserve-a-tous-les-citoyens-en-lutte-pour-la-preservation-et-le-developpement-du-patrimoine-educatif-du-pays-du-cap-sizun\/\">L&rsquo;ASVPNF apporte un soutien\u00a0 sans r\u00e9serve \u00e0 tous les citoyens en lutte pour la pr\u00e9servation et le d\u00e9veloppement du patrimoine \u00e9ducatif\u00a0 du pays du Cap Sizun<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/01\/28\/la-laicite-sexerce-et-se-defend-dans-tous-les-lieux-publics\/\">La la\u00efcit\u00e9 s&rsquo;exerce et se d\u00e9fend dans tous les lieux publics<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/01\/13\/soutenons-nos-fideles-camarades-concarnois-et-disons-non-a-la-stigmatisation-de-notre-laicite-republicaine\/\">Soutenons nos fid\u00e8les camarades concarnois et disons NON \u00e0 la stigmatisation de notre La\u00efcit\u00e9 R\u00e9publicaine.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/01\/12\/non-aux-pamphlets-anti-juifs-de-celine\/\">Non\u00a0aux pamphlets anti-juifs de\u00a0C\u00e9line\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/01\/09\/plus-que-jamais-soyons-charlie\/\">\u00ab\u00a0Plus que jamais, soyons CHARLIE!\u00a0\u00bb\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/12\/08\/laicite\/\">LA\u00cfCITE<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/12\/01\/amicale-laique-de-concarneau-laicite\/\">Amicale la\u00efque de Concarneau &#8211; La\u00efcit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/11\/22\/celebration-du-11-novembre-2017-monument-de-la-cour-dhonneur-de-lespe-bretagne-site-de-quimper\/\">C\u00e9l\u00e9bration du 11 novembre 2017 (Monument de la Cour d&rsquo;honneur de l&rsquo;ESPE Bretagne, site de Quimper)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/11\/12\/20-novembre-2017-28-e-anniversaire-de-la-convention-internationale-des-droits-de-lenfant-sous-legide-de-lunesco\/\">20 novembre 2017 : 28\u00e8 anniversaire de la Convention Internationale des Droits de l&rsquo;Enfant (sous l&rsquo;\u00e9gide de l&rsquo;UNESCO)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/11\/03\/amicale-laique-de-concarneau-agenda-des-prochaines-activites\/\">Amicale la\u00efque de Concarneau :  agenda des prochaines activit\u00e9s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/11\/02\/la-neutralite-de-lespace-public-principe-fondateur-de-la-republique-francaise\/\">La neutralit\u00e9 de l&rsquo;espace public; principe fondateur de la R\u00e9publique fran\u00e7aise.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/10\/31\/lorsquun-physicien-retraite-de-lenseignement-superieurancien-normalien-de-leng-de-quimper-f-29000-et-son-collegue-enseignant-chercheur-concoivent-et-construisent-une-lampe-magi\/\">Lorsqu&rsquo;un physicien retrait\u00e9 de l&rsquo;Enseignement Sup\u00e9rieur, ancien normalien de l&rsquo;ENG de Quimper (F-29000) et son coll\u00e8gue enseignant-chercheur con\u00e7oivent et construisent une \u00ab\u00a0lampe magique\u00a0\u00bb\u00a0(lampe stroboscopique \u00e0 LED) qui permet aux patients souffrant de dyslexie de lire avec un confort am\u00e9lior\u00e9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/10\/21\/les-franchises-universitaires-et-les-libertes-academiques-remises-en-cause\/\">Les franchises universitaires et les \u00ab\u00a0libert\u00e9s\u00a0 acad\u00e9miques\u00a0\u00bb remises en cause ?\u00a0\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/10\/18\/laicite-au-quotidien-en-guyane-francaise-2017\/\">La\u00efcit\u00e9 au quotidien en Guyane  Fran\u00e7aise (2017)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/10\/16\/en-1905-daucuns-pensaient-avoir-gagner-la-guerre-en-realite-112-ans-apres-la-bataille-continue\/\">En 1905, d&rsquo;aucuns pensaient avoir gagner la guerre&#8230;En r\u00e9alit\u00e9, 112 ans apr\u00e8s la bataille continue&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/10\/16\/quand-pouldreuzic-29710-et-le-conseil-regional-de-bretagne-celebrent-la-memoire-de-notre-eminent-professeur-de-francais-a-leng-de-quimper-pierre-helias\/\">Quand Pouldreuzic (29710) et le Conseil R\u00e9gional de Bretagne c\u00e9l\u00e8brent la m\u00e9moire de notre \u00e9minent professeur de fran\u00e7ais \u00e0 l&rsquo;ENG de Quimper , Pierre H\u00e9lias.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/09\/30\/prendre-bonne-note\/\">Prendre bonne note !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/09\/22\/deux-assemblees-generales-de-lasvpnf-ont-ete-convoquees-pour-le-06-octobre-2016-prochain\/\">Deux assembl\u00e9es g\u00e9n\u00e9rales de l&rsquo;ASVPNF ont \u00e9t\u00e9 convoqu\u00e9es pour le 06 octobre 2017 prochain<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/09\/22\/marchons-pour-la-paix\/\">MARCHONS POUR LA PAIX<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/07\/24\/apres-larticle-du-telegramme-du-16-juillet-2017\/\">Apr\u00e8s l&rsquo;article du T\u00e9l\u00e9gramme du 16 juillet 2017<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/07\/21\/quand-le-telegramme-ouvre-ses-colonnes-aux-activites-de-notre-association\/\">Quand le T\u00e9l\u00e9gramme ouvre ses colonnes aux activit\u00e9s de notre association<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/07\/11\/un-traite-dinterdiction-des-armes-nucleaires-a-ete-adopte-a-lonu-le-7-juillet-2017\/\">Un trait\u00e9 d&rsquo;interdiction des armes nucl\u00e9aires a \u00e9t\u00e9 \u00a0adopt\u00e9 \u00e0 l&rsquo;ONU le 7 juillet 2017<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/07\/04\/3eme-conseil-dadministration\/\">3\u00e8me Conseil d&rsquo;administration<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/06\/16\/lettre-dinformation-n1\/\">Lettre d&rsquo;information n\u00b01<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/06\/06\/preparer-la-paix-pour-eviter-la-guerre\/\">Pr\u00e9parer la PAIX pour \u00e9viter la guerre !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/06\/06\/le-militantisme-laique-a-loeuvre-a-concarneau-suivez-aussi-ce-bon-chemin\/\">Le militantisme la\u00efque \u00e0 l&rsquo;oeuvre \u00e0 Concarneau &#8230;Suivez aussi ce bon chemin !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/05\/30\/le-flyer-de-lasvpnf-est-disponible\/\">Le flyer de l&rsquo;ASVPNF est disponible !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/05\/29\/30-mai-2017-journee-mondiale-sans-tabac\/\">30 mai 2017 &#8211; Journ\u00e9e Mondiale sans tabac<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/05\/29\/27-mai-2017-journee-nationale-de-la-resistance\/\">27 mai 2017 : JOURNEE NATIONALE DE LA RESISTANCE .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/05\/10\/10-mai-2017-journee-nationale-des-memoires-de-la-traite-de-lesclavage-et-de-leurs-abolitions\/\">10 mai 2017 &#8211; Journ\u00e9e Nationale des m\u00e9moires de la traite, de l&rsquo;esclavage et de leurs abolitions<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/05\/07\/8-mai-1945-8-mai-2017\/\">8 mai 1945 &#8211; 8 mai 2017<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/04\/21\/necrologie-jean-nedelec\/\">N\u00e9crologie &#8211; Jean N\u00e9d\u00e9lec<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/03\/10\/jif-2017-journee-internationale-des-femmes\/\">JIF 2017 &#8211; Journ\u00e9e Internationale des Femmes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/02\/17\/aphorisme-premonitoire-de-jules-simon-1814-1896\/\">Aphorisme  pr\u00e9monitoire de Jules SIMON (1814-1896)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/02\/13\/lancement-de-la-campagne-dadhesions-2017-a-lasvpnf\/\">Lancement de la campagne d&rsquo;adh\u00e9sions 2017 \u00e0 l&rsquo;ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/02\/11\/entretien-avec-mona-ozouf-in-le-delegue-n-249-decembre-20167-9\/\">Entretien avec MONA OZOUF  in \u00ab\u00a0le d\u00e9l\u00e9gu\u00e9\u00a0\u00bb &#8211; N\u00b0 249-D\u00e9cembre 2016,7-9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/02\/07\/necrologie-christian-le-goualher\/\">N\u00e9crologie &#8211; Christian Le Goualher<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2017\/01\/23\/2017\/\">2017<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/12\/06\/111e-anniversaire-de-la-loi-du-9-decembre-1905\/\">111\u00e8 Anniversaire de la Loi du 9 d\u00e9cembre 1905.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/11\/14\/11-novembre-2016\/\">11 novembre 2016<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/11\/10\/epilogue-de-l-affaire-des-creches\/\">EPILOGUE  de l&rsquo;Affaire des  Cr\u00e8ches<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/11\/05\/laffaire-des-creches-au-conseil-detat-suite\/\">L&rsquo;affaire des cr\u00e8ches au Conseil d&rsquo;Etat (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/10\/30\/et-lecole-laique-de-demain\/\">Et l&rsquo;Ecole La\u00efque de demain  ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/10\/28\/renforcement-du-numerique-a-lecole-et-au-college\/\">Renforcement du num\u00e9rique \u00e0 l&rsquo;Ecole et au Coll\u00e8ge&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/10\/28\/les-projets-dinstallation-de-creches-chretiennes-de-la-nativite-dans-les-batiments-publics-soumis-a-larbitrage-du-conseil-detat\/\">Les projets d&rsquo;installation de cr\u00e8ches chr\u00e9tiennes de la nativit\u00e9 dans les b\u00e2timents publics soumis \u00e0 l&rsquo;arbitrage du Conseil d&rsquo;Etat<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/10\/16\/appel-a-la-vigilance-des-adherents-de-lasvpnf\/\">Appel \u00e0 la vigilance des adh\u00e9rents de l&rsquo;ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/10\/12\/notification-par-mail-aux-actualites\/\">NOTIFICATION PAR MAIL DES ACTUALITES<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/09\/20\/audience-au-vatican-pour-les-familles-des-victimes-de-lattentat-du-14-juillet-2016-a-nice\/\">Audience au Vatican pour les familles des victimes de l&rsquo;attentat du 14 juillet 2016 \u00e0  NICE<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/09\/18\/journees-europeennes-du-patrimoine-17-et-18-septembre-2016\/\">\u00ab\u00a0JOURNEES EUROPEENNES DU PATRIMOINE\u00a0\u00bb (17 et 18 septembre 2016)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/09\/08\/video-revolution-ecole1918-1939-documentaire-de-johanna-grudzinska-a-consulter-gratuitement-avant-le-15-septembre-2016\/\">Vid\u00e9o \u00ab\u00a0REVOLUTION ECOLE,1918-1939\u00a0\u00bb (documentaire de Johanna Grudzinska, \u00e0 consulter gratuitement avant le 15 septembre 2016).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/07\/20\/conference-du-17-juin-2016-sur-lutilisation-rationnelle-des-ressources-documentaires\/\">Conf\u00e9rence du 17 juin 2016 sur l&rsquo;utilisation rationnelle des ressources documentaires<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/05\/30\/convocation-a-lago-de-lasvpnf-du-17-juin-2016\/\">Convocation \u00e0 l&rsquo;AGO de l&rsquo;ASVPNF du 17 juin 2016<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/05\/06\/aux-citoyens-resistants-dhier-et-daujourdhui-chra\/\">Aux Citoyens R\u00e9sistants d\u2019Hier et d\u2019Aujourd\u2019hui !  (CHRA)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/05\/05\/nouvelle-reforme-de-lorthographe\/\">Nouvelle (?) r\u00e9forme de l\u2019orthographe<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/04\/10\/groupes-de-travail\/\">Groupes de travail<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/04\/04\/appel-a-contribution\/\">Appel \u00e0 contributions<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/bizutages\/\">bizutages<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/24\/rites-normaliens-du-bizutage\/\">Rites normaliens : du bizutage \u00e0 l\u2019amiti\u00e9 ind\u00e9fectible ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/20\/lundi-4-octobre-1954-la-rentree-et-ses-suites-des-laureats-du-concours-dadmission-a-leng-de-quimper-racontees-et-illustrees-par-andre-le-goff\/\">Lundi 4 octobre  1954 ; la rentr\u00e9e (et ses suites) des \u00ab\u00a0laur\u00e9ats\u00a0\u00bb du concours d&rsquo;admission \u00e0 l&rsquo;ENG de QUIMPER racont\u00e9es et illustr\u00e9es par Andr\u00e9 Le Goff.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/rituels-dentree-a-lecole-normale-dinstituteursle-regard-de-lanthropologue\/\">Rituels d&rsquo;entr\u00e9e \u00e0 l&rsquo;Ecole Normale d&rsquo;Instituteurs,le regard\u00a0 de l&rsquo;anthropologue<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/22\/lusinage-des-bleus-de-leng-de-quimper-en-1954\/\">L&rsquo;usinage des \u00ab\u00a0bleus\u00a0\u00bb de l&rsquo;ENG de Quimper en 1954 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-bonheur-est-dans-le-pre\/\">Le bonheur\u00a0est dans le pr\u00e9 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/code-du-bleu\/\">Code du bleu<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/cabinet-des-curiosites\/\">cabinet des curiosit\u00e9s<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/26\/turpitudes-et-contre-turpitudes-autour-de-lasvpnf\/\">Turpitudes et contre-turpitudes autour de l\u2019ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/17\/la-lettre-dinformation-n9-de-lasvpnf\/\">La Lettre d\u2019Information n\u00b09  de  L\u2019ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/14\/michel-mazeas-un-normalien-engage-au-service-de-douarnenez\/\">Michel Maz\u00e9as,  un normalien engag\u00e9 au service de Douarnenez<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/14\/lasvpnf-rend-hommage-a-andre-corbique\/\">L&rsquo;ASVPNF rend hommage \u00e0 Andr\u00e9 Corbique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/07\/15\/colonies-de-vacances-formation-des-maitres-et-education-populaire\/\">Colonies de vacances, formation des ma\u00eetres et \u00e9ducation populaire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/17\/andre-le-goff-raconte-enfin-retraite\/\">Andr\u00e9 Le Goff raconte : \u00ab Enfin retrait\u00e9 ! \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/28\/dans-la-serie-andre-le-goff-raconte-2\/\">Dans la s\u00e9rie Andr\u00e9 Le Goff raconte<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/13\/les-nouvelles-agrestes-du-bout-du-mondei\/\">Les nouvelles agrestes du  Bout du Monde(I)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/26\/pour-rendre-hommage-a-joseph-le-poezat-guigner-ancien-directeur-de-leng-de-quimper\/\">Pour rendre hommage \u00e0 Joseph Le Po\u00ebzat-Guigner  ancien Directeur de l&rsquo;ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/04\/charles-peguy-2\/\">Charles P\u00e9guy<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/04\/addendum-a-lhommage-rendu-a\/\">Addendum  \u00e0 l&rsquo;hommage rendu  \u00e0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/02\/apres-le-deces-de-pierre-henaff\/\">Apr\u00e8s le d\u00e9c\u00e8s de Pierre H\u00e9naff<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/07\/02\/charles-peguy-et-les-hussards-noirs-de-la-republique\/\">Charles P\u00e9guy et les Hussards noirs de la R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/07\/02\/etudiant-a-vie-a-lepreuve-du-cabinet-des-curiosites-normaliennes\/\">Etudiant \u00e0 vie  \u00e0 l\u2019\u00e9preuve du cabinet des curiosit\u00e9s normaliennes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/06\/18\/quand-les-photos-de-nos-glorieux-professeurs-ressortent-des-tiroirs\/\">Quand les photos de nos glorieux professeurs ressortent des tiroirs\u00a0!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/06\/02\/la-pie-margot-dans-la-culture-populaire-bretonne\/\">La Pie Margot dans la culture populaire bretonne<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/05\/25\/une-gwerz-facetieuse-de-prosper-proux-barde-breton-1811-1873-et-sa-traduction-en-francais-ii\/\">Une \u00ab\u00a0gwerz\u00a0\u00bb fac\u00e9tieuse de Prosper Proux (barde breton , 1811-1873) et sa traduction en fran\u00e7ais ( II)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/05\/04\/lorsque-lesprit-rebelle-normalien-longtemps-contenu-se-manifeste-dans-un-oulipo-insolite\/\">Lorsque l\u2019esprit rebelle normalien- longtemps contenu- se manifeste dans un oulipo insolite !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/02\/13\/dans-la-serie-andre-le-goff-raconte\/\">Dans la s\u00e9rie Andr\u00e9 Le Goff raconte :<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/16\/fete-des-ecoles-publiques-a-audierne-en-1949\/\">F\u00eate des Ecoles publiques \u00e0 Audierne en 1949<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/09\/les-exploits-sportifs-des-normos-de-la-rue-de-rosmadec-en-1933\/\">Les exploits sportifs des  \u00ab\u00a0NORMOS\u00a0\u00bb  de la rue de Rosmadec  en 1933.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/27\/en-hommage-a-francoise-bosser\/\">En hommage \u00e0 Fran\u00e7oise Bosser<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/27\/la-plus-petite-des-petites-ecoles-de-hameau-du-finistere\/\">La plus petite des petites Ecoles de hameau  du  Finist\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/27\/skol-ar-chapel\/\">Skol ar Chapel<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/25\/le-retablissement-des-ecoles-normales-apres-la-liberation\/\">Le r\u00e9tablissement des Ecoles normales apr\u00e8s la Lib\u00e9ration<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/24\/lorsque-la-promotion-etincelle-eng-quimper-54-58-celebrait-le-soixantenaire-de-son-entree-a-lecole-normale\/\">Lorsque la promotion ETINCELLE,\u00a0 ENG Quimper 54-58, c\u00e9l\u00e9brait le soixantenaire de son entr\u00e9e \u00e0 l&rsquo;Ecole normale&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/16\/la-saga-des-pensionnaires-du-cours-complementaire-de-huelgoat-f-29690\/\">La saga des pensionnaires  du  Cours  Compl\u00e9mentaire de Huelgoat (F-29690)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/12\/en-souvenir-de-jean-gestin\/\">En souvenir de Jean Gestin<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/03\/apprentissage-de-lautonomie-du-sport-chez-les-normaliens-quimperois-addendum\/\">Apprentissage de l&rsquo;autonomie du sport chez les normaliens quimp\u00e9rois (Addendum)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/05\/dans-la-serie-andre-le-goff-raconte-souvenirs-du-birinik-bigouden\/\">Dans la s\u00e9rie \u201cAndr\u00e9 Le Goff raconte\u201d  Souvenirs du Birinik bigouden<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/05\/20\/pierre-jakez-helias-prophete-en-son-pays-de-pouldreuzic-et-au-dela\/\">Pierre-Jakez  H\u00e9lias, proph\u00e8te en son pays  de Pouldreuzic et au-del\u00e0 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/04\/04\/max-raconte-ses-exploits-de-jeunesse-une-relation-precoce-et-momentanee-au-tabac\/\">Max  raconte  ses exploits de jeunesse : Une relation  pr\u00e9coce et momentan\u00e9e au tabac .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/03\/21\/anciens-eleves-maitres-nostalgiques-de-la-petite-reine\/\">Anciens \u00e9l\u00e8ves-ma\u00eetres, nostalgiques de la \u00ab petite reine \u00bb\u2026<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/02\/25\/pierre-jakez-helias-notre-professeur-ethnologue-de-coeur\/\">Pierre-Jakez H\u00e9lias notre Professeur, ethnologue de c\u0153ur.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/02\/14\/les-bons-mots-de-jakez\/\">Les bons mots de Jakez<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/12\/09\/la-peur-un-des-moteurs-de-lhistoire\/\">La peur un des moteurs de l\u2019Histoire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/11\/23\/le-mono-de-la-colo\/\">Le Mono &#8230; de la Colo<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/12\/asvpnf-la-sixieme-lettre-dinformation\/\">ASVPNF :   La sixi\u00e8me Lettre d&rsquo;Information<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/20\/moelan-en-mai\/\">MO\u00cbLAN en MAI<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/13\/des-lecons-de-lhistoire-aux-experiences-de-la-vie\/\">Des le\u00e7ons de l\u2019histoire  aux  exp\u00e9riences de la vie<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/11\/contribution-a-la-connaissance-de-lesprit-normalien-au-milieu-du-20e-siecle\/\">Contribution  \u00e0 la connaissance de l\u2019esprit normalien au milieu du 20\u00e8 si\u00e8cle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/07\/11\/lecole-maternelle-est-elle-necessaire\/\">L&rsquo;ECOLE MATERNELLE EST-ELLE NECESSAIRE ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/05\/29\/memoire-normale-et-esprit-normalien\/\">M\u00e9moire normale et esprit normalien<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/05\/25\/la-petite-histoire-des-ecoles-communales-de-filles-lecole-de-stang-ar-bacol\/\">La petite histoire des Ecoles communales de filles   L\u2019Ecole de Stang ar Bacol<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/04\/11\/en-hommage-a-jo-le-du\/\">En hommage  \u00e0 Jo Le Du<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/04\/02\/jean-savina\/\">Jean Savina<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/03\/26\/andre-le-goff-raconte\/\">Andr\u00e9 Le Goff raconte !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/12\/en-hommage-a-celetin-perrigault-dit-tintin\/\">En hommage  \u00e0 C\u00e9letin Perrigault, dit \u201cTintin\u201d<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/01\/28\/la-saga-des-freres-le-goff-normaliens-quimperois-des-annees-cinquante\/\">La saga des  fr\u00e8res Le Goff,     Normaliens quimp\u00e9rois des ann\u00e9es cinquante<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/15\/daniel-courtin-la-fin-dun-mythe\/\">Daniel Courtin, la fin d&rsquo;un mythe<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/06\/pierre-henaff-doyen-dage-de-lasvpnf-ecrit-a-jean-marc-jancovici\/\">Pierre H\u00e9naff, doyen d\u2019\u00e2ge de l\u2019ASVPNF,  \u00e9crit \u00e0  Jean-Marc Jancovici<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/18\/le-choeur-mixte-des-gaillards-davant-a-ergue-gaberic-f-29500-un-epilogue-dans-la-bonne-humeur\/\">Le choeur mixte des Gaillards d&rsquo;Avant    \u00e0 Ergu\u00e9-Gab\u00e9ric (F-29500):  Un \u00e9pilogue dans la bonne humeur !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/08\/11\/aux-anciens-laureats-du-concours-dentree-a-len-la-procedure-de-nomination-des-eveques-ou-comment-etre-sur-le-podium-de-la-terna-alors-que-le-discatere-concerne-se-feminise\/\">Aux anciens laur\u00e9ats du Concours d&rsquo;entr\u00e9e \u00e0 l&rsquo;EN !     La proc\u00e9dure de nomination des \u00e9v\u00eaques ou  comment \u00eatre sur le podium de la terna  alors que  le discat\u00e8re  concern\u00e9 se f\u00e9minise ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/07\/11\/la-lettre-de-pierre-guervinic-a-monica\/\">La Lettre de Pierre Guervinic \u00e0 Monica<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/07\/11\/quand-on-mettait-la-lumiere-sous-cloche-a-plogastel-saint-germain-f-29710\/\">Quand on mettait la lumi\u00e8re sous cloche  \u00e0  Plogastel-Saint-Germain (F-29710)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/31\/a-notre-ecole-orpheline-et-a-ceux-qui-riches-dideal-lui-donnerent-une-ame-tribulations-electorales-du-printemps-2022\/\">A notre Ecole orpheline  et \u00e0 ceux qui riches d&rsquo;id\u00e9al lui donn\u00e8rent une \u00e2me !     Tribulations \u00e9lectorales du printemps 2022<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/18\/andre-le-goff-raconte-notre-voyage-de-promo\/\">Andr\u00e9 Le Goff raconte :     \u00ab\u00a0Notre voyage de Promo\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/10\/bal-des-norms-58-a-leng-de-quimper-addenda\/\">Bal des norms 58 \u00e0 l&rsquo;ENG de Quimper   Addenda<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/20\/tradition-normalienne-quimperoise-le-bal-des-norms-par-andre-le-goff-addendum\/\">Tradition normalienne quimp\u00e9roise : le Bal des Norms  par  Andr\u00e9 Le Goff     Addendum<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/16\/tradition-normalienne-quimperoise-des-annees-50-le-bal-des-norms\/\">Tradition normalienne quimp\u00e9roise  des ann\u00e9es 50 :  Le Bal des Norms<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/14\/a-la-recherche-des-anciens-directeurs-de-leng-m-ungerer-homme-de-la-laicisation-de-lecole-normale-de-quimper\/\">A la recherche des anciens directeurs de l&rsquo;ENG  M. UNGERER  Homme  de la la\u00efcisation de l&rsquo;Ecole normale  de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/06\/andre-le-goff-raconte-la-savate-a-leng-de-quimper-en-1958-ou-autogestion-du-sport-chez-les-norms\/\">Andr\u00e9 le Goff raconte   la savate \u00e0 l&rsquo;ENG de Quimper en 1958   ou    \u00ab\u00a0Autogestion du sport   chez les Norms\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/03\/pierre-henaff-raconte\/\">Pierre H\u00e9naff raconte\u2026<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/03\/en-hommage-a-jean-kerloch-a-lorigine-de-notre-chorale-danciens-normaliens\/\">En hommage \u00e0 Jean Kerloc&rsquo;h  \u00e0 l&rsquo;origine de notre  chorale d&rsquo;anciens normaliens<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/03\/traditions-normaliennes-quimperoises-lorigine-singuliere-des-surnoms-des-protagonistes-de-la-carte-de-cote\/\">Traditions normaliennes quimp\u00e9roises  L\u2019origine singuli\u00e8re des surnoms des protagonistes de la Carte de Cote<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/10\/la-guerre-dalgerie-a-t-elle-eu-lieu\/\">La guerre d&rsquo;Alg\u00e9rie a-t-elle eu lieu?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/02\/01\/souffrances-et-turpitudes-autour-dun-monument-devenu-memorial-et-la-jeunesse-ensevelie-des-humbles-de-vingt-ans\/\">Souffrances et turpitudes autour d\u2019un monument devenu m\u00e9morial  et  La jeunesse ensevelie des humbles de vingt ans<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/12\/02\/une-photo-darchive-inedite-pour-ouvrir-un-volet-meconnu-de-lhistoire-des-instituteurs-du-finistere\/\">Une photo d&rsquo;archive in\u00e9dite  pour ouvrir  un volet m\u00e9connu de l&rsquo;histoire des Instituteurs du  Finist\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/18\/anciens-normaliens-passeurs-de-memoire-unissez-vous\/\">Anciens normaliens passeurs de m\u00e9moire   Unissez-vous  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/07\/pour-se-souvenir-et-echanger-des-photos-inedites-de-lenf-de-vannes\/\">Pour  se souvenir et \u00e9changer&#8230;  des        photos in\u00e9dites de l&rsquo;ENF de Vannes  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/03\/la-supplique-metaphorique-dun-defenseur-sans-concession-du-patrimoine-normalien\/\">La supplique  m\u00e9taphorique d&rsquo;un d\u00e9fenseur sans concession du patrimoine normalien<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/11\/pierre-jakez-helias-lanniversaire-oublie\/\">Pierre-Jakez H\u00e9lias : l&rsquo;anniversaire oubli\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/21\/dans-la-serie-andre-le-goff-raconte-deux-nouvelles-illustrees-pour-soutenir-le-moral-en-pleine-pandemie-de-coronavirus-2020-2021\/\">Dans la s\u00e9rie  Andr\u00e9 Le Goff raconte ;   deux  nouvelles illustr\u00e9es pour soutenir le moral,  en pleine  pand\u00e9mie  de coronavirus (2020-2021).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/13\/en-hommage-a-madame-bouet1928-2021-ancienne-professeure-deducation-physique-et-sportive-a-lecole-normale-dinstitutrices-de-quimper-f-29000\/\">En hommage \u00e0 Madame BOUET(1928-2021)     ancienne professeure  d&rsquo;\u00e9ducation physique et sportive    \u00e0   l&rsquo;Ecole normale d&rsquo;Institutrices  de QUIMPER (F-29000)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/13\/francois-menez-professeur-de-lettres-et-poete-a-lecole-normale-dinstituteurs-de-quimper\/\">Francois M\u00e9nez, professeur  de lettres et po\u00e8te  \u00e0             l&rsquo;Ecole normale d&rsquo;instituteurs de Quimper .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/24\/premices-de-la-celebration-du-centenaire-de-la-revolution-a-quimper\/\">Pr\u00e9mices de la c\u00e9l\u00e9bration du centenaire de la  R\u00e9volution \u00e0 Quimper&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/21\/les-eleves-maitres-en-formation-professionnelle-a-lecole-dapplication-jules-ferry-de-quimper-etaient-affubles-du-surnom-de-ptits-boucs-par-les-ecoliers-de-la-jules\/\">Les \u00e9l\u00e8ves-ma\u00eetres  en formation professionnelle \u00e0 l&rsquo;\u00e9cole d&rsquo;application Jules Ferry de Quimper \u00e9taient affubl\u00e9s du surnom de  \u00ab\u00a0P&rsquo;tits boucs\u00a0\u00bb par les \u00e9coliers de \u00ab\u00a0La Jules\u00a0\u00bb!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/14\/laureat-du-prix-raymonde-destreicher-decerne-par-lacademie-nationale-de-medecine-en-decembre-2020-le-physicien-albert-le-floch-fut-eleve-maitre-a-leng-de-quimper-en-56-60\/\">Laur\u00e9at du Prix Raymonde Destreicher d\u00e9cern\u00e9 par l&rsquo;Acad\u00e9mie Nationale de M\u00e9decine en d\u00e9cembre 2020,  le  physicien  Albert Le Floc&rsquo;h   fut  \u00e9l\u00e8ve-ma\u00eetre \u00e0 l&rsquo;ENG de Quimper en 56-60.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/14\/souvenir-de-lecole-normale-de-quimper-2e-partie-du-20e-siecle\/\">Souvenir de l&rsquo;Ecole normale de Quimper                               (2\u00e8 partie du 20\u00e8 si\u00e8cle )<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/14\/souvenir-de-la-vie-normalienne-2e-partie-du-20e-siecle-a-leng-de-quimper\/\">Souvenir de la vie normalienne ( 2\u00e8 partie du 20\u00e8 si\u00e8cle  \u00e0 l&rsquo;ENG de Quimper )<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/14\/lecole-normale-pilier-de-la-republique-bernard-poignant-ancien-professeur-a-leng-de-quimper-se-souvient\/\">\u00ab\u00a0L&rsquo;Ecole normale : pilier de la R\u00e9publique\u00a0\u00bb                Bernard Poignant, ancien professeur  \u00e0 l&rsquo;ENG de   Quimper se souvient !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/14\/ecole-normale-de-quimper-il-etait-ecolier-cobaye-des-eleves-maitres-de-formation-professionnelle-1970-1971\/\">Ecole normale de Quimper : il \u00e9tait  \u00e9colier \u00ab\u00a0cobaye\u00a0\u00bb des \u00e9l\u00e8ves-ma\u00eetres  de formation professionnelle (1970-1971) !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/10\/regard-de-femme-sur-un-memorial-orphelin-addendum\/\">Regard de femme sur un m\u00e9morial orphelin  (addendum)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/10\/quy-avait-il-donc-dans-les-bagages-des-normaliens\/\">Qu&rsquo;y avait-il donc dans les bagages des normaliens ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/13\/les-ecoles-normales-primaires-de-la-3e-republique-etaient-elles-vraiment-les-casernes-de-jules-ferry\/\">Les Ecoles normales primaires de  la 3\u00e8 R\u00e9publique \u00e9taient-elles vraiment  les casernes de Jules Ferry ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/28\/quand-andre-le-goff-fait-linventaire-sans-concession-de-ses-anciens-maitres-a-leng-de-quimper-dans-les-annees-50-du-siecle-dernier\/\">Quand Andr\u00e9 Le Goff fait  l&rsquo;inventaire -sans concession-  de ses anciens ma\u00eetres \u00e0 l&rsquo;ENG de  Quimper,  dans les ann\u00e9es 50 du si\u00e8cle dernier !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/10\/a-la-memoire-de-nos-grands-anciens-3-jean-le-du1912-1985-et-daniel-trellu-1919-1998-promotions-eng-29-32-et-35-38\/\">A la m\u00e9moire de nos grands anciens (3):         Jean Le D\u00fb(1912-1985) et Daniel Trellu ( 1919-1998)         Promotions ENG  29-32 et  35-38<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/08\/a-la-memoire-de-nos-grands-anciens-1-daniel-trellu-promo-eng35-38\/\">A la m\u00e9moire de nos grands anciens (1) :  Daniel Trellu (1919-1998)  Promotion ENG 1935-1938<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/08\/a-la-memoire-de-nos-grands-anciens-2-albert-trividic-1909-1990\/\">A la m\u00e9moire de nos grands anciens (2) :  Albert Trividic (1909-1990 ) ; promotion ENG 1927-1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/18\/andre-le-goff-raconte-son-accueil-et-ses-premiers-exploits-a-rosporden-f-29140\/\">Andr\u00e9 le Goff raconte  son accueil et ses premiers  exploits  \u00e0  Rosporden (F-29140)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/05\/quand-jetais-a-commercy-j-le-poezat-guigner\/\">\u00a0\u00bb Quand j&rsquo;\u00e9tais \u00e0 Commercy&#8230;\u00a0\u00bb              ( J. Le Po\u00ebzat-Guigner)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/25\/normaliens-en-blouse-grise-et-ecoliers-en-blouse-noire\/\">Normaliens en blouse grise et \u00e9coliers en blouse noire !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/25\/biographie-dun-ancien-eleve-maitre-de-leng-de-quimper-promotion-54-58\/\">Biographie  d&rsquo;un ancien \u00e9l\u00e8ve-ma\u00eetre de l&rsquo;ENG de QUIMPER       (Promotion 54-58)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/22\/a-la-rencontre-de-nos-camarades-du-departement-de-la-meuse-f-55\/\">A la rencontre de nos camarades     du  d\u00e9partement de la Meuse (F-55 ).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/27\/le-duel-legendaire-entre-jean-de-la-fontaine-et-corentinpremier-eveque-de-quimper-conte-par-l-durocher-1885\/\">Le duel l\u00e9gendaire entre Jean de La Fontaine et Corentin,premier \u00e9v\u00eaque de Quimper,  cont\u00e9 par  L. Durocher . (1885)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/29\/fete-de-la-jeunesse-a-brest-1948-ou-1949-souvenirs-illustres-de-andre-le-goff\/\">F\u00eate de la Jeunesse \u00e0 Brest (1948 ou 1949); souvenirs illustr\u00e9s de Andr\u00e9 Le Goff.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/28\/quimper-corentin-le-cythere-breton\/\">Quimper-Corentin &#8211; le Cyth\u00e8re breton !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/mathematiques-demarche-scientifique-militantisme-associatif-engage-et-communication-entre-les-hommes-de-bonne-volonte-memoires-1-de-pierre-henaff-paysan-bigouden-devenu-normalien-en-1941\/\">Math\u00e9matiques, D\u00e9marche scientifique, Militantisme associatif engag\u00e9 et Communication entre les hommes de bonne volont\u00e9 : M\u00e9moires (1) de Pierre H\u00e9naff , paysan bigouden devenu normalien en 1942<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/pennherez-ar-palud-poeme-de-pierre-jakez-helias-mis-en-lumiere-par-deux-de-ses-anciens-eleves-de-leng-de-quimper\/\">Pennherez ar palud, po\u00e8me de Pierre-Jakez H\u00e9lias\u00a0mis en lumi\u00e8re par deux de\u00a0ses anciens \u00e9l\u00e8ves de l&rsquo;ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/deux-poemes-lyriques-de-jacques-dennielou-illustres-par-andre-le-goff\/\">Deux po\u00e8mes lyriques de Jacques Denni\u00e9lou\u00a0illustr\u00e9s par Andr\u00e9 Le Goff<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/maurice-le-coz-marechal-ferrant-au-lin-en-concarneau-f-29900-ledition-modernisee-dun-conte-illustre-de-andre-le-goff\/\">Maurice LE COZ , mar\u00e9chal-ferrant au LIN\u00a0en Concarneau (F-29900),\u00a0l&rsquo;\u00e9dition \u00ab\u00a0modernis\u00e9e\u00a0\u00bb d&rsquo;un conte illustr\u00e9 de\u00a0 Andr\u00e9 Le Goff<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/le-retour-dun-ancien-eleve-maitre-des-annees-50-du-siecle-dernier-a-son-lire-breton\/\">Le retour d&rsquo;un ancien \u00e9l\u00e8ve-ma\u00eetre\u00a0des ann\u00e9es 50 du si\u00e8cle dernier\u00a0\u00e0 son Lir\u00e9 breton !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/de-linfluence-de-la-theologie-sur-les-errements-dun-eleve-maitre-une-breve-illustree-de-alain-le-goff\/\">De l&rsquo;influence de la th\u00e9ologie sur les errements d&rsquo;un \u00e9l\u00e8ve-ma\u00eetre &#8211;\u00a0Une br\u00e8ve illustr\u00e9e de Alain Le Goff !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/la-poesie-une-composante-mal-connue-de-lesprit-normalien\/\">La po\u00e9sie; une composante mal connue de l&rsquo;esprit normalien<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/18\/a-son-de-trompe-ou-de-tambour-leng-de-quimper-se-profile-enfin-le-1er-mai-1882\/\">A son de trompe ou de tambour, l&rsquo;ENG de Quimper\u00a0se profile enfin\u00a0 le 1er mai 1882<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/18\/le-cesar-2020-des-curiosites-normaliennes\/\">Le \u00ab\u00a0C\u00e9sar\u00a0\u00bb 2020 des curiosit\u00e9s normaliennes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/pour-leur-soixantieme-production-les-choristes-des-gaillards-davant-etrennent-leur-tenue-de-gala-2019\/\">Pour leur soixanti\u00e8me production, les choristes\u00a0 des \u00ab\u00a0Gaillards d&rsquo;avant\u00a0\u00bb\u00a0\u00a0\u00e9trennent leur tenue de gala\u00a0 2019 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/lecusson-de-lenf-a-ete-retrouve\/\">L&rsquo;\u00e9cusson de l&rsquo;ENF a \u00e9t\u00e9 retrouv\u00e9 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/10\/17\/andre-le-goff-raconte-ses-souvenirs-dadolescence\/\">Andr\u00e9 Le Goff raconte ses souvenirs d&rsquo;adolescence !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/10\/03\/andre-le-goff-raconte-les-histoires-de-son-enfance-en-pays-bigouden\/\">Andr\u00e9 Le Goff raconte\u00a0les histoires de son enfance en pays bigouden&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/precieuses-photos-de-la-promotion-albatroseng-58-62mises-a-jour-et-a-disposition-de-lassociation\/\">Pr\u00e9cieuses photos de la promotion\u00a0 ALBATROS(ENG 58-62)mises \u00e0 jour et \u00e0 disposition de l&rsquo;Association<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/rentree-du-lundi-9-octobre-1939-repli-general-vers-stang-ar-choat-suite-a-la-declaration-de-guerre-du-3-septembre\/\">Rentr\u00e9e du lundi 9 octobre 1939 : repli g\u00e9n\u00e9ral vers Stang ar c&rsquo;hoat, suite \u00e0 la d\u00e9claration de guerre\u00a0 du 3 septembre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/08\/breves-normaliennes-des-vacances-de-noel-1938\/\">Br\u00e8ves normaliennes des vacances de No\u00ebl 1938.\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/08\/ar-chaoteriad-la-cotriade-bigoudene-andre-le-goff-raconte-le-retour-du-pecheur\/\">Ar c&rsquo;haoteriad, la cotriade bigoud\u00e8ne !\u00a0Andr\u00e9\u00a0 Le Goff\u00a0 raconte\u00a0 le retour du p\u00eacheur<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/01\/quand-les-freres-le-goff-anciens-eleves-maitres-de-leng-de-quimper-assistaient-a-la-distribution-des-prix-au-lycee-la-tour-dauvergne-de-la-meme-ville\/\">Quand les fr\u00e8res Le Goff ,anciens \u00e9l\u00e8ves-ma\u00eetres de l&rsquo;ENG de Quimper, assistaient \u00e0 la Distribution des Prix au Lyc\u00e9e la Tour d&rsquo;Auvergne\u00a0 de la m\u00eame ville&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/01\/la-conscription-chez-les-normaliens-au-debut-de-la-3e-republique-et-la-loi-des-cures-sac-a-dos-2\/\">La conscription chez les normaliens\u00a0 au d\u00e9but de la 3\u00e8 R\u00e9publique et la loi des \u00ab\u00a0cur\u00e9s sac \u00e0 dos\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/08\/01\/la-symbolique-de-lhirondelle-a-leng-de-quimper-a-linstar-des-poemes-de-marcel-hief-1899-et-de-louise-michel-1871\/\">La symbolique de l&rsquo;hirondelle \u00e0 l&rsquo;ENG de Quimper \u00e0 l&rsquo;instar des po\u00e8mes de Marcel Hief (1899) et de Louise Michel (1871 ?)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/08\/01\/la-conscription-chez-les-normaliens-au-debut-de-la-3e-republique-et-la-loi-des-cures-sac-a-dos\/\">La conscription chez les normaliens\u00a0au d\u00e9but de la 3\u00e8 R\u00e9publique et la loi des \u00ab\u00a0cur\u00e9s sac \u00e0 dos\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/18\/le-nonce-apostolique-luigi-ventura-et-le-droit-de-cuissage-ecclesiastique-implicitement-condamnes-par-le-vaticanjuillet-2019\/\">Le nonce apostolique\u00a0Luigi Ventura et le droit de cuissage eccl\u00e9siastique implicitement condamn\u00e9s par le Vatican(juillet 2019)&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/18\/la-revolte-des-pedagogues\/\">\u00ab\u00a0La r\u00e9volte des p\u00e9dagogues\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/18\/noces-bretonnes-en-haute-cornouaille-a-scrignac-f-29640\/\">Noces bretonnes en Haute Cornouaille \u00e0 Scrignac (F-29640)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/11\/les-echos-de-la-crise-de-1929-a-leng-de-quimper\/\">Les \u00e9chos de la crise de 1929 \u00e0 l&rsquo;ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/11\/changement-de-front-lattaque-en-regle-des-clericaux-contre-les-normaliens-et-les-pedagogues-1905\/\">\u00ab\u00a0Changement de front\u00a0\u00bb : l&rsquo;attaque en r\u00e8gle des cl\u00e9ricaux contre les normaliens et les p\u00e9dagogues (1905)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/30\/derives-de-leglise-catholique-et-mystifications-de-lepiscopat\/\">D\u00e9rives de l&rsquo;\u00e9glise catholique et mystifications de l&rsquo;\u00e9piscopat<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/28\/habemus-papa-une-nouvelle-derive-clericale-mise-a-jour-les-enfants-de-pretres\/\">Habemus papa ! Une nouvelle d\u00e9rive cl\u00e9ricale mise \u00e0 jour : les enfants de pr\u00eatres<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/03\/joyeusete-normalienne-du-milieu-du-20e-siecle-racontee-et-illustree-par-a-le-goff-le-mauvais-coup-de-la-basse-de-coff\/\">Joyeuset\u00e9 normalienne du milieu du 20\u00e8 si\u00e8cle racont\u00e9e et illustr\u00e9e par A. Le Goff :\u00a0 le mauvais coup de la Basse de Coff. !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/le-celibat-des-pretres-de-leglise-catholique\/\">Le c\u00e9libat des pr\u00eatres de l&rsquo;\u00e9glise catholique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/poemes-confidentiels-decouverts-inopinement-dans-les-colonnes-du-periodique-le-flambeau-paru-en-octobre-1931\/\">Po\u00e8mes \u00ab\u00a0confidentiels\u00a0\u00bb d\u00e9couverts inopin\u00e9ment dans les colonnes\u00a0 du p\u00e9riodique Le Flambeau\u00a0paru en octobre 1931<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/la-voix-de-la-raison-texte-fondateur-ecrit-par-anatole-france-1844-1924\/\">La voix de la Raison, texte fondateur \u00e9crit par Anatole FRANCE (1844-1924)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/les-carrefours-de-lhistoire-a-propos-de-la-celebration-du-centenaire-de-la-conquete-de-lalgerie-en-1930\/\">Les carrefours de l&rsquo;histoire : \u00e0 propos de la c\u00e9l\u00e9bration\u00a0du centenaire de la conqu\u00eate de l&rsquo;Alg\u00e9rie en 1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/les-exploits-legendaires-des-normaliens-au-bout-des-quais-fleuris-de-quimper\/\">Les exploits \u00ab\u00a0l\u00e9gendaires\u00a0\u00bb des normaliens&#8230;\u00a0 au bout des quais fleuris de Quimper !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/lorigine-rabelaisienne-du-surnom-picro-attribue-a-un-eleve-maitre-de-la-promotion-etincelle-eng1954-1958\/\">L&rsquo;origine \u00ab\u00a0rabelaisienne\u00a0\u00bb du surnom\u00a0 PICRO\u00a0 attribu\u00e9 \u00e0 un \u00e9l\u00e8ve-ma\u00eetre de la Promotion Etincelle ( ENG,1954-1958)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/en-1928-le-flambeau-organe-periodique-regional-de-la-libre-pensee-publie-a-brest-entretenait-une-chronique-antireligieuse-virulente-accompagnee-dun-livre-dor-des-cures-de\/\">En 1928\u00a0Le \u00a0Flambeau\u00a0organe p\u00e9riodique r\u00e9gional de la Libre Pens\u00e9e, publi\u00e9 \u00e0\u00a0 Brest, entretenait une chronique antireligieuse virulente accompagn\u00e9e d&rsquo;un \u00ab\u00a0Livre d&rsquo;Or des cur\u00e9s de France et de Navarre\u00a0\u00bb !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/24\/a-propos-des-funerailles-de-la-grande-dame-de-roz-avel-demeurant-8-rue-bertrand-de-rosmadec-a-quimper\/\">A propos des fun\u00e9railles de la\u00a0 Grande Dame de Roz Avel demeurant 8 rue Bertrand de Rosmadec \u00e0 Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/18\/lhistoire-dramatique-du-jeune-chevalier-de-la-barre-1745-1766\/\">L&rsquo;histoire dramatique\u00a0 du jeune Chevalier de la Barre (1745-1766)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/18\/apres-la-revelation-des-terribles-egarements-dune-partie-du-clerge-catholique-ne-datant-pas-dhier\/\">Apr\u00e8s la r\u00e9v\u00e9lation des terribles \u00e9garements d&rsquo;une partie du clerg\u00e9 catholique ne datant pas d&rsquo;hier,<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/03\/les-risques-du-metier-en-1930\/\">Les risques du m\u00e9tier en 1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/17\/une-gwerz-facetieuse-de-prosper-proux-barde-breton-1811-1873-et-sa-traduction-en-francais\/\">Une gwerz fac\u00e9tieuse de Prosper Proux (barde breton , 1811-1873) et sa traduction en fran\u00e7ais<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/quand-les-grenouilles-quimperoises-cherchaient-un-aumonier-en-1930\/\">Quand les \u00ab\u00a0grenouilles\u00a0\u00bb quimp\u00e9roises cherchaient un aum\u00f4nier &#8230; en 1930 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/leveque-balade-en-aviso-au-mepris-de-la-loi-de-1905\/\">L&rsquo;\u00e9v\u00eaque balad\u00e9 en aviso au m\u00e9pris de la Loi de 1905<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/laureates-et-laureats-des-concours-dentree-aux-en-de-quimper-de-1930\/\">Laur\u00e9ates et laur\u00e9ats\u00a0 des concours d&rsquo;entr\u00e9e aux EN de Quimper de 1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/litineraire-du-voyage-de-fin-detudes-de-la-promotion-charleston-eng-1927-1930\/\">L&rsquo;itin\u00e9raire du voyage de fin d&rsquo;\u00e9tudes de la\u00a0promotion CHARLESTON (ENG 1927-1930)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/25\/les-caricatures-de-deux-eleves-maitres-de-leng-de-quimper-promotion-armor-1950-1954-effectuees-par-leur-professeur-de-dessin\/\">Les caricatures de deux \u00e9l\u00e8ves-ma\u00eetres de l&rsquo;ENG de Quimper (Promotion ARMOR, 1950-1954) effectu\u00e9es par leur Professeur de Dessin<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/14\/lecole-publique-de-lestonan-de-1967-a-1975\/\">L&rsquo;ECOLE PUBLIQUE de LESTONAN, de 1967 \u00e0 1975<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/14\/photos-oubliees-du-bagad-de-leng\/\">Photos oubli\u00e9es du bagad de l&rsquo;ENG<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/les-echos-de-la-foire-saint-corentin-a-quimper-en-1937\/\">Les \u00e9chos de la Foire\u00a0 Saint-Corentin \u00e0 Quimper en 1937<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/quelques-poesies-de-cornouaille-recemment-mises-a-jour\/\">Quelques po\u00e9sies de Cornouaille r\u00e9cemment mises \u00e0 jour<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/bruits-de-cloches-et-laicite-sous-le-front-populaire-1936\/\">Bruits de cloches et la\u00efcit\u00e9 sous le Front Populaire (1936)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/05\/les-missives-oubliees-jalonnant-la-creation-du-bagad-de-leng\/\">Les missives oubli\u00e9es jalonnant la cr\u00e9ation du bagad de l&rsquo;ENG<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/11\/rapprochement-incongru-delements-de-la-vie-normalienne-quimperoise\/\">Rapprochement incongru d&rsquo;\u00e9l\u00e9ments de la vie (normalienne) quimp\u00e9roise<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/le-marechal-ferrant\/\">Le mar\u00e9chal-ferrant<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/histoire-du-trousseau-normalien\/\">Histoire du trousseau normalien<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/la-malle-verte-dune-normalienne-en-1938\/\">La malle verte d&rsquo;une normalienne en 1938<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/a-la-cuisine-de-bons-petits-moinillons-apres-matines-sen-allaient-faire-reveillon\/\">A la cuisine, de bons petits moinillons,\u00a0Apr\u00e8s matines, s&rsquo;en allaient faire r\u00e9veillon&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/une-benne-bleue-decouverte-dans-la-cour-dhonneur-du-domaine-de-roz-avel\/\">Une benne bleue d\u00e9couverte dans la cour d&rsquo;honneur du domaine de Roz Avel !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/travaux-et-sauvegarde-du-patrimoine-a-stang-ar-choat-mi-novembre-2016\/\">Travaux et sauvegarde du patrimoine \u00e0 Stang ar c&rsquo;Hoat\u00a0(mi-novembre 2016)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/groupe-deleves-maitres-de-leng-de-quimper-promotion-emeraude-en-grande-sortie-a-mousterlin-en-1954\/\">Groupe d&rsquo;\u00e9l\u00e8ves-ma\u00eetres de l&rsquo;ENG de Quimper (Promotion EMERAUDE) en \u00ab\u00a0grande sortie\u00a0\u00bb&#8230; \u00e0 Mousterlin en 1954.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/quand-les-anciens-de-la-promotion-charleston-eng-1927-1930-et-leurs-epouses-se-retrouvaient\/\">Quand les anciens de la Promotion Charleston (ENG, 1927-1930) et leurs \u00e9pouses se retrouvaient&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/du-temps-ou-lecole-normale-dinstituteurs-de-quimper-faisait-valoir-les-qualites-architecturales-de-son-batiment-principal-outre-atlantique\/\">Du temps o\u00f9 l&rsquo;Ecole Normale d&rsquo;Instituteurs de Quimper faisait valoir les qualit\u00e9s architecturales \u00a0de son b\u00e2timent principal, outre-Atlantique&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/detours-et-aleas-ethiques-autour-de-lhistoire-des-instituteurs-publics\/\">DETOURS ET ALEAS ETHIQUES AUTOUR DE l&rsquo;HISTOIRE DES INSTITUTEURS PUBLICS<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/recreation-des-demoiselles-en-robes-noires-le-17-janvier-1909\/\">R\u00e9cr\u00e9ation des demoiselles en robes noires, le 17 janvier 1909<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/implication-des-normaliennes-et-des-normaliens-dans-la-vie-de-la-cite\/\">Implication des normaliennes et des normaliens dans la vie de la cit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/dans-lattente-de-la-cantate-a-la-tour-dauvergne\/\">Dans l&rsquo;attente de la Cantate \u00e0 La Tour d&rsquo;Auvergne&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/une-republicaine-sous-loeil-des-clericaux\/\">UNE REPUBLICAINE &#8211;\u00a0Sous l&rsquo;\u0153il des Cl\u00e9ricaux<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/joseph-gourlay-1906-2005-un-cas-decole\/\">Joseph GOURLAY (1906-2005), un \u00ab\u00a0cas d&rsquo;\u00e9cole\u00a0\u00bb !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/hagiographie-normalienne-de-la-deuxieme-moitie-du-xxe-siecle\/\">Hagiographie normalienne de la deuxi\u00e8me moiti\u00e9 du XX\u00e8 si\u00e8cle \u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/commemoration-en-timbre-poste\/\">Comm\u00e9moration en timbre-poste<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/peregrinations-finisteriennes-dun-normalien-de-rennes-pendant-les-annees-de-plomb-1940-1945\/\">P\u00e9r\u00e9grinations finist\u00e9riennes d\u2019un normalien de Rennes\u00a0pendant\u00a0les \u00ab\u00a0ann\u00e9es de plomb\u00a0\u00bb (1940-1945)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/aux-eleves-des-ecoles-il-est-defendu\/\">\u00ab\u00a0Aux \u00e9l\u00e8ves des \u00e9coles, il est d\u00e9fendu&#8230;\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/gloire-a-lecole\/\">GLOIRE A L&rsquo;ECOLE !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/lhomme-le-plus-hai-de-france\/\">\u00ab\u00a0L&rsquo;homme le plus ha\u00ef de France\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/la-creation-de-lecole-normale-en-martinique\/\">La cr\u00e9ation de l&rsquo;Ecole Normale en Martinique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/normalien-ordinaire-adherant-au-sni-des-1954\/\">Normalien ordinaire adh\u00e9rant au SNI d\u00e8s 1954<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/pierre-le-grand-1792-1839-premier-recteur-laic-de-lacademie-de-rennes\/\">Pierre Le Grand (1792-1839) &#8211; Premier Recteur la\u00efc de l&rsquo;acad\u00e9mie de Rennes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/tribulations-et-cogitations-dun-ecolier-nord-bigouden-devenu-normalien-a-quimper-en-1942\/\">Tribulations et cogitations d\u2019un \u00e9colier nord-bigouden\u2026\u00a0devenu normalien \u00e0 Quimper en 1942<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2016\/04\/09\/cabinet-des-curiosites-normaliennes-2\/\">Cabinet des curiosit\u00e9s normaliennes<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/chants-normaliens\/\">chants normaliens<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-chant-des-norms\/\">Le chant des NORMS<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/communiquer\/\">communiquer<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/23\/picorer-des-glanes-de-pour-la-science-1\/\">Picorer des glanes de Pour La Science (1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/23\/picorer-des-glanes-de-pour-la-science-2-in-pour-la-science-525-juillet-2021\/\">Picorer des glanes de Pour La Science (2)  In Pour La Science  525 , juillet 2021<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/08\/miscellanees-pre-et-post-normaliennes-en-meuse\/\">Miscellan\u00e9es pr\u00e9 et post-normaliennes en Meuse.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/04\/histoire-des-ecoles-normales-du-departement-de-la-meuse\/\">Histoire des \u00e9coles normales du d\u00e9partement de la Meuse<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/04\/la-francafrique-au-prix-du-genocide-tutsi-au-rwanda\/\">La Fran\u00e7afrique au prix du g\u00e9nocide Tutsi au Rwanda.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/04\/les-echos-de-la-succession-difficile-du-cardinal-barbarin\/\">Les \u00e9chos de la succession difficile  du cardinal Barbarin.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/06\/combattre-avec-des-caricatures-surtout-ne-pas-renoncer\/\">Combattre avec des caricatures ; surtout ne pas renoncer !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/06\/les-sciences-nous-rendent-elles-credules\/\">Les sciences nous rendent-elles cr\u00e9dules ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/05\/comment-parler-de-dieu-quand-dieu-ninteresse-plus-personne\/\">Comment \u00ab\u00a0parler de Dieu quand Dieu n&rsquo;int\u00e9resse plus personne \u00a0\u00bb ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/02\/un-memorial-emblematique-confidentiel-et-orphelin\/\">Un m\u00e9morial embl\u00e9matique, confidentiel et orphelin !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/22\/avant-denseigner-la-liberte-dexpression-ses-moyens-et-ses-limites-et-de-la-pratiquer-a-lecole-enseigner-la-liberte-et-enseigner-lexpression-mais-surtout-ne-pas-y-renoncer\/\">Avant d&rsquo;enseigner la libert\u00e9 d&rsquo;expression ses moyens et ses limites et de la pratiquer \u00e0 l&rsquo;Ecole ; enseigner la libert\u00e9 et enseigner l&rsquo;expression.  Mais  surtout ne pas y renoncer !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/22\/m-trudeau-donneur-de-lecons-sur-la-laicite-et-la-liberte-dexpression-a-la-francaise\/\">M. TRUDEAU, donneur de le\u00e7ons  sur la la\u00efcit\u00e9 et la libert\u00e9 d&rsquo;expression \u00e0 la fran\u00e7aise.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/21\/en-vendee-actes-de-repentance-ecclesiale-pour-les-victimes-declarees-de-violences-sexuelles-au-sein-de-leglise\/\">En Vend\u00e9e : actes de \u00ab\u00a0repentance eccl\u00e9siale\u00a0\u00bb  pour les  victimes  d\u00e9clar\u00e9es de  violences sexuelles au sein de l&rsquo;Eglise.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/08\/penser-penser-librement-pour-bien-exercer-sa-liberte-dexpression\/\">Penser, penser librement pour bien exercer sa libert\u00e9 d&rsquo;expression !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/05\/petite-chronique-finisterienne-de-linstruction-publique-davant-loi-goblet-en-1886\/\">Petite  chronique finist\u00e9rienne de l&rsquo;instruction publique  d&rsquo;avant Loi Goblet, en 1886.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/07\/claude-le-coz-pretre-citoyen-de-la-revolution-et-la-gazette-quimperoise-de-1866\/\">Claude Le Coz , pr\u00eatre citoyen de la R\u00e9volution,  et la  gazette quimp\u00e9roise de 1866<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/05\/claude-le-coz-pretre-revolutionnaire-quimperois\/\">Claude LE COZ,  pr\u00eatre r\u00e9volutionnaire quimp\u00e9rois !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/01\/decryptage-dune-omerta-ecclesiale-organisee-sur-les-abus-sexuels-commis-au-sein-de-leglise-et-sur-leurs-consequences-humaines-et-societales\/\">D\u00e9cryptage d&rsquo;une omerta eccl\u00e9siale organis\u00e9e  sur les abus sexuels commis au sein de l&rsquo;Eglise  et  sur leurs cons\u00e9quences humaines et  soci\u00e9tales .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/01\/petite-chronique-finisterienne-de-linstruction-publique-en-1886-suite\/\">Petite chronique finist\u00e9rienne de l&rsquo;instruction publique  en 1886( suite&#8230;)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/27\/en-1885-suite-a-la-perte-de-ses-fonctions-ministerielles-eminentes-jules-ferry-retrouve-son-mandat-de-depute-vosgien-pour-se-preoccuper-de-lagriculture\/\">En 1885, suite \u00e0 la perte de ses  fonctions minist\u00e9rielles \u00e9minentes, Jules Ferry retrouve son mandat de d\u00e9put\u00e9 vosgien   pour se pr\u00e9occuper de l&rsquo;agriculture.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/23\/glanes-de-vendemiaire-1886\/\">Glanes de vend\u00e9miaire 1886 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/06\/terminee-la-culture-du-silence-dans-leglise-et-ailleurs\/\">Termin\u00e9e (?) , la  culture du silence dans l&rsquo;Eglise&#8230;  et ailleurs ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/01\/pierre-jakez-helias-un-anniversaire-oublie\/\">\u00a0\u00bb Pierre-Jakez HELIAS, un anniversaire oubli\u00e9 ! \u00ab\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/29\/en-finir-avec-le-clericalisme-a-propos-de-louvrage-de-loic-de-kerimel\/\">\u00ab\u00a0En finir avec le cl\u00e9ricalisme\u00a0\u00bb A propos de l\u2019ouvrage de  Lo\u00efc de K\u00e9rimel<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/26\/petite-chronique-finisterienne-de-linstruction-publique-en-1885\/\">Petite chronique finist\u00e9rienne de l&rsquo;instruction publique   en 1885.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/25\/assez-doublier-la-colonne-vertebrale-de-la-laicite-la-liberte-de-conscience\/\">ASSEZ !&#8230; D&rsquo;oublier la colonne vert\u00e9brale de la  la\u00efcit\u00e9 ; la libert\u00e9 de conscience.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/29\/fustiger-les-abus-spirituels-et-sexuels-commis-au-sein-de-leglise-catholique-en-2020\/\">Fustiger les  abus spirituels et sexuels   commis au sein de l&rsquo;Eglise catholique  en 2020 .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/29\/ne-plus-avoir-le-vent-ni-en-poupe-ni-en-pourpre-ou-les-peregrinations-du-cardinal-barbarin\/\">Ne plus avoir le vent ni en poupe ni en pourpre  ou les p\u00e9r\u00e9grinations du cardinal  Barbarin.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/25\/la-communication-relative-a-levolution-de-la-crise-sanitaire-covid-19interactions-puissance-publique-expertise-scientifique-et-medicale\/\">La communication relative \u00e0 l&rsquo;\u00e9volution de la crise sanitaire COVID-19:interactions puissance publique &#8211; expertise scientifique et m\u00e9dicale.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/25\/lecole-aux-prises-avec-la-fracture-numerique\/\">L&rsquo;Ecole aux prises avec la  fracture num\u00e9rique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/ecclesial-ou-clerical-en-realite-bonnet-blanc-nest-pas-blanc-bonnet\/\">Eccl\u00e9sial ou cl\u00e9rical !\u00a0En r\u00e9alit\u00e9 bonnet blanc n&rsquo;est pas blanc bonnet\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/larticle-fondateur-retrouve-par-un-adherent-attentif\/\">L&rsquo;article fondateur retrouv\u00e9 par un adh\u00e9rent attentif !<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/coupures-de-presse\/\">coupures de presse<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/20\/quand-une-adherente-de-lasvpnf-recoit-les-honneurs-de-la-presse\/\">Quand une  adh\u00e9rente de l\u2019ASVPNF re\u00e7oit les honneurs de la presse !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/28\/interactions-de-la-juridiction-civile-et-de-la-juridiction-ecclesiale-revelees-au-public-par-les-attendus-et-les-suites-de-laffaire-preynat\/\">Interactions de\u00a0 la juridiction civile et de la juridiction eccl\u00e9siale r\u00e9v\u00e9l\u00e9es au public par les attendus et les suites de l&rsquo;affaire Preynat<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/28\/lorsque-jules-ferry-sadresse-a-ses-contempteurs-pour-justifier-la-politique-coloniale-de-la-france\/\">Lorsque Jules Ferry s&rsquo;adresse \u00e0 ses contempteurs\u00a0pour justifier\u00a0la politique coloniale de la France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/les-costumes-bretons-et-leurs-specificites-avant-1884\/\">\u00a0Les costumes bretons et leurs sp\u00e9cificit\u00e9s\u00a0avant 1884<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/02\/souvenez-vous-lorsquon-assassinait-professeurs-journalistes-ministres-et-autres-defenseurs-de-la-justice-et-de-la-liberte-au-pretexte-de-leurs-originesimpures\/\">Souvenez-vous : lorsqu&rsquo;on assassinait professeurs, journalistes, ministres et autres d\u00e9fenseurs de la justice et de la libert\u00e9, au pr\u00e9texte de leurs origines\u00a0\u00bbimpures\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/la-fete-des-associations-des-anciens-eleves-des-ecoles-normales-de-quimper-en-1930\/\">La F\u00eate des Associations des anciens \u00e9l\u00e8ves des Ecoles Normales de Quimper en 1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/03\/ecole-laique-laicite-et-anticlericalisme-a-la-une-du-citoyen-du-12-mai-1927\/\">Ecole la\u00efque, la\u00efcit\u00e9 et anticl\u00e9ricalisme \u00e0 la UNE du Citoyen\u00a0du 12 mai 1927<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/03\/la-tribune-laique-et-republicaine-du-journal-le-citoyen-de-janvier-1927\/\">La Tribune La\u00efque et R\u00e9publicaine du journal Le Citoyen de janvier 1927<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/25\/les-abus-sexuels-sur-mineurs-des-pretres-de-leglise-catholique-francaise\/\">Les abus sexuels sur mineurs\u00a0 des\u00a0 pr\u00eatres de l&rsquo;\u00e9glise catholique fran\u00e7aise,<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/25\/en-1927-le-president-du-comite-departemental-daction-laique-du-finistere-exhortait-les-finisteriens-a-la-defense-de-lecole-laique-en-danger\/\">En 1927, le Pr\u00e9sident du Comit\u00e9 d\u00e9partemental d&rsquo;action la\u00efque du Finist\u00e8re exhortait les finist\u00e9riens \u00e0 la d\u00e9fense de l&rsquo;\u00e9cole la\u00efque en danger&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/23\/echos-republicains-de-linauguration-de-lecole-chretienne-de-filles-de-plozevet-f-29710-en-1928\/\">Echos r\u00e9publicains\u00a0de l&rsquo;inauguration\u00a0de l&rsquo;\u00e9cole chr\u00e9tienne de filles de Ploz\u00e9vet (F- 29710), en 1928<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/22\/lappel-des-consciences-de-1919\/\">L&rsquo;appel des consciences de 1919<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/22\/quand-le-comite-de-defense-laique-du-finistereprotestait-contre-linstallation-du-garde-champetre-douessant-a-lecole-publique-en-1927\/\">Quand le Comit\u00e9 de d\u00e9fense la\u00efque du Finist\u00e8re,protestait contre l&rsquo;installation du Garde\u00a0 champ\u00eatre d&rsquo;Ouessant \u00e0 l&rsquo;\u00e9cole publique en 1927<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/22\/quand-lhebdomadaire-finisterien-le-citoyen-se-dechainait-en-1929-dans-sa-tribune-laique-son-carillon-republicain-et-son-anticlericalisme\/\">Quand l&rsquo;hebdomadaire finist\u00e9rien\u00a0Le Citoyen se d\u00e9cha\u00eenait\u00a0en 1929, dans sa tribune la\u00efque, son carillon r\u00e9publicain et son anticl\u00e9ricalisme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/17\/quand-les-rubriques-tribune-republicaine-et-sons-de-cloche-font-la-une-de-lhebdomadaire-le-citoyen-de-decembre-1929\/\">Quand les rubriques \u00ab\u00a0TRIBUNE REPUBLICAINE\u00a0\u00bb et\u00a0\u00ab\u00a0SONS de CLOCHE\u00a0\u00bb font la une de l&rsquo;hebdomadaire Le Citoyen de d\u00e9cembre 1929<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/26-ans-apres-le-vote-de-la-loi-de-1901-sur-les-associations-le-depute-groussau-tente-de-remettre-en-cause-le-contenu-de-larticle-6\/\">26 ans apr\u00e8s le vote de la Loi de 1901 sur les Associations, le d\u00e9put\u00e9\u00a0Groussau tente de remettre en cause le contenu de l&rsquo;article 6<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/dernieres-nouvelles-des-ecoles-normales-et-des-instituteurs-en-juillet-et-aout-1927\/\">Derni\u00e8res nouvelles des Ecoles Normales et des Instituteurs en juillet et ao\u00fbt 1927<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/05\/lecole-et-la-patrie-pour-les-instituteurs\/\">L&rsquo;Ecole et la Patrie : Pour les Instituteurs<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/12\/echos-lointains-de-laffaire-du-catechisme-rectifie\/\">Echos lointains de l&rsquo;affaire du \u00ab\u00a0Cat\u00e9chisme rectifi\u00e9\u00a0\u00bb&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/05\/emile-combes-president-du-conseil-artisan-actif-de-la-preparation-de-la-loi-de-separation-de-1905\/\">Emile Combes &#8211;\u00a0Pr\u00e9sident du Conseil, artisan actif de la pr\u00e9paration de la Loi de \u00a0S\u00e9paration de 1905<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/05\/creation-et-turpitudes-de-lephemere-ecole-normale-congreganiste-de-quimper-1872-1880\/\">Cr\u00e9ation et turpitudes\u00a0de l&rsquo;\u00e9ph\u00e9m\u00e8re Ecole Normale congr\u00e9ganiste de Quimper\u00a0(1872-1880)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/25\/carillon-la-bonne-histoire-de-pont-aven-de-albert-bayet1880-1961\/\">Carillon : la bonne\u00a0 histoire de Pont-Aven de Albert BAYET(1880-1961)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/14\/apres-la-mort-de-georges-clemenceau-une-des-plus-grandes-figures-de-la-3e-republique\/\">Apr\u00e8s la mort de Georges Cl\u00e9menceau, une des plus grandes figures de la 3\u00e8 R\u00e9publique&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/14\/combat-contre-la-laicite-de-lecole-en-1929-suite\/\">Combat contre la la\u00efcit\u00e9 de l&rsquo;\u00e9cole en 1929 (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/10\/le-traitement-des-instituteurs-en-1884-la-copie-a-revoir\/\">Le traitement des Instituteurs en 1884 :\u00a0la copie \u00e0 revoir !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/26\/actualites-judiciaires-de-1934-de-lhistoire-des-grands-avocats-et-tribuns-des-debuts-de-la-3e-republique-a-celle-du-tribunal-de-quimper-ou-lon-juge-des-contentieux-entre-eveques-et\/\">Actualit\u00e9s\u00a0 judiciaires de 1934&#8230; De l&rsquo;histoire des grands avocats et tribuns des d\u00e9buts de la 3\u00e8 R\u00e9publique \u00e0 celle du Tribunal de Quimper\u00a0 o\u00f9 l&rsquo;on juge des contentieux entre \u00e9v\u00eaques et enseignants de\u00a0 l&rsquo;\u00e9cole publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/reguiny-commune-du-departement-du-morbihan-56190-fin-de-guerre-scolaire-en-2017\/\">R\u00e9guiny, commune du d\u00e9partement du Morbihan (56190): fin de guerre scolaire en 2017 !\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/instituteurs-normaliennes-et-normaliens-a-lhonneur-dans-le-citoyen-du-31-mai-1934\/\">Instituteurs, normaliennes et normaliens \u00e0 l&rsquo;honneur dans Le Citoyen du 31 mai 1934.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/lhistoire-est-un-eternel-recommencement\/\">L&rsquo;histoire est un \u00e9ternel recommencement<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/travail-de-memoire-en-pays-catalan-maitres-soldats\/\">Travail de m\u00e9moire \u00a0en pays catalan : \u00ab\u00a0Ma\u00eetres Soldats\u00a0\u00bb\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/3-juin-1969-dernier-defile-de-la-fe%cc%82te-de-la-jeunesse-des-ecoles-publiques\/\">3 Juin 1969 &#8211; Dernier de\u0301file\u0301 de la Fe\u0302te de la jeunesse des e\u0301coles publiques<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/stage-de-voile-a-lecole-de-treboul\/\">Stage de voile \u00e0 l&rsquo;\u00e9cole de Tr\u00e9boul<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/quimper-nos-scolaires-sur-les-stades\/\">Quimper &#8211; Nos scolaires sur les stades<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/les-normaliens-de-quimper-ont-occupe-le-bureau-de-linspecteur-dacademie\/\">Les normaliens de quimper ont occup\u00e9 le bureau de l&rsquo;inspecteur d&rsquo;acad\u00e9mie<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/ecoles-normales-retrouvailles-des-anciens\/\">Ecoles normales &#8211; Retrouvailles des anciens<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/08\/aux-anciens-combattants\/\">Aux anciens combattants<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/en-mixte\/\">en mixte<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/1965-68\/\">1965-68<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/1968-69\/\">1968-69<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/1969\/\">1969<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/fetes-normaliennes\/\">f\u00eates normaliennes<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/au-bal-des-normaliens-du-16-mars-1957\/\">Au bal des normaliens du 16 mars 1957 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/normaliennes-romantiques-2\/\">Normaliennes romantiques<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/ballet-royal-chez-les-normaliennes\/\">Ballet royal chez les normaliennes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/danseuses-normaliennes-a-diademe\/\">Danseuses normaliennes \u00e0 diad\u00e8me<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/activite-theatrale-chez-les-normaliennes\/\">Activit\u00e9 th\u00e9\u00e2trale chez les normaliennes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/repetition-dun-groupe-de-danseurs-normaliens-vers-1930-dans-le-jardin-du-theatre-de-quimper\/\">R\u00e9p\u00e9tition d&rsquo;un groupe de danseurs normaliens (vers 1930) dans le jardin du th\u00e9\u00e2tre de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/troupe-theatrale-mixte-enf-eng-vers-1930\/\">Troupe th\u00e9\u00e2trale mixte (ENF + ENG) vers 1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/sept-vestales-normaliennes-lors-dune-seance-de-maniement-darmes\/\">Sept vestales normaliennes lors d&rsquo;une s\u00e9ance de maniement d&rsquo;armes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/normaliennes-romantiques\/\">Normaliennes romantiques\u2026<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/jeunes-artistes-au-pompon-rouge-sous-la-bonne-garde-de-la-marechaussee\/\">Jeunes artistes au pompon rouge sous la bonne garde de la mar\u00e9chauss\u00e9e<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/normaliennes-se-preparant-a-la-danse-ou-est-la-ou-le-choregraphe\/\">Normaliennes se pr\u00e9parant \u00e0 la danse\u00a0: o\u00f9 est la (ou le) chor\u00e9graphe\u00a0?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/les-baladins-de-lecole-normale-dinstitutrices\/\">Les baladins de l\u2019Ecole Normale d\u2019Institutrices<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/quand-normaliens-et-normaliennes-de-1924-jouaient-la-comedie-la-poudre-aux-yeux-deugene-labiche-a-lodet-palace\/\">Quand normaliens et normaliennes de 1924 jouaient la com\u00e9die \u00a0\u00bb La Poudre aux Yeux\u00a0\u00bb d&rsquo;Eug\u00e8ne Labiche, \u00e0 l&rsquo;ODET PALACE !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/fe%cc%82te-a-len\/\">Fe\u0302te a\u0300 l&rsquo;EN<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/fete-normalienne-ballet-russe\/\">F\u00eate normalienne &#8211; ballet russe<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/fe%cc%82te-normalienne-ballet-chinois\/\">Fe\u0302te normalienne &#8211; Ballet Chinois<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/formes-immaterielles\/\">formes immat\u00e9rielles<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/12\/27\/les-lendemains-de-lannee-terrible-et-de-linsurrection-de-la-commune-de-paris-1871\/\">Les lendemains de l&rsquo;ann\u00e9e terrible  et de        l&rsquo;insurrection de la Commune de Paris 1871<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/12\/20\/le-substantif-laicite-et-le-triptyque-emblematique-de-la-devise-republicaine\/\">Le substantif la\u00efcit\u00e9  et le  triptyque  embl\u00e9matique  de la  devise r\u00e9publicaine.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/12\/05\/la-journee-de-la-laicite-a-lecole-le-9-decembre-2021-ne-doit-pas-occulter-la-celebration-du-116e-anniversaire-de-la-loi-de-separation-des-eglises-et-de-letat-du-9-decembre-1905\/\">La journ\u00e9e de la La\u00efcit\u00e9 \u00e0 l&rsquo;Ecole le 9 d\u00e9cembre 2021  ne doit pas occulter  la c\u00e9l\u00e9bration  du 116\u00e8 anniversaire  de  la Loi de s\u00e9paration des Eglises et de l&rsquo;Etat du 9 d\u00e9cembre 1905.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/08\/rentree-scolaire-2021-la-campagne-du-m-e-n-sur-la-laicite\/\">Rentr\u00e9e scolaire 2021 : la campagne du M.E.N.  sur la La\u00efcit\u00e9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/08\/chronique-dune-destruction-programmee-de-lecole-et-de-linstruction-publique-au-nom-de-la-democratie\/\">Chronique d&rsquo;une  destruction programm\u00e9e  de l&rsquo;Ecole et de l&rsquo;Instruction publique  au nom de la d\u00e9mocratie<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/04\/mila-armer-les-esprits-et-les-coeurs-pour-retrouver-la-boussole-de-la-liberte-de-conscience\/\">MILA :  Armer les esprits et les coeurs  pour retrouver la boussole de la libert\u00e9 de conscience<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/03\/savoir-nommer-les-choses-essentielles-definition-de-la-laicite-par-ferdinand-buisson-1911\/\">Savoir nommer les choses essentielles :               D\u00e9finition de la la\u00efcit\u00e9  par Ferdinand Buisson         (1911)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/23\/le-decret-et-larrete-berthelot-du-18-janvier-1887\/\">Le d\u00e9cret et l&rsquo;arr\u00eat\u00e9  Berthelot du 18 janvier 1887 .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/21\/loi-goblet-loi-de-laicisation-du-personnel-enseignant-loi-de-separation-de-leglise-et-de-lecole-publique-30-octobre-1886\/\">Loi Goblet : loi  de la\u00efcisation  du personnel enseignant, loi de s\u00e9paration de l&rsquo;\u00e9glise et de l&rsquo;\u00e9cole publique.  (30 octobre 1886)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/15\/lecole-jules-ferry-ejf-ecole-normale-de-lenseignement-colonial-1902-1912\/\">L&rsquo;Ecole Jules-Ferry (EJF):  Ecole normale de l&rsquo;Enseignement colonial  (1902-1912)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/10\/reconstruire-la-republique-laique\/\">Reconstruire la R\u00e9publique la\u00efque!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/09\/la-declaration-internationale-sur-la-laicite-au-21e-siecle\/\">La d\u00e9claration internationale sur la la\u00efcit\u00e9 au 21\u00e8 si\u00e8cle !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/08\/9-decembre-2020-celebrons-le-115-e-anniversaire-de-la-loi-de-separation-des-eglises-et-de-letat-et-exigeons-sa-mise-en-application-sur-tout-le-territoire-de-la-republique\/\">9 d\u00e9cembre 2020            C\u00e9l\u00e9brons le 115 \u00e8 anniversaire de la Loi de  S\u00e9paration des Eglises et de l&rsquo;Etat  et             Exigeons sa mise en application  sur tout le territoire de la R\u00e9publique.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/15\/la-reponse-indignee-et-pleine-dhumanisme-de-notre-doyen-pierre-henaff-a-la-decapitation-sauvage-de-samuel-paty\/\">La r\u00e9ponse indign\u00e9e et pleine d&rsquo;humanisme    de notre Doyen Pierre H\u00e9naff \u00e0 la        d\u00e9capitation sauvage de Samuel PATY<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/30\/ferdinand-buisson-lapotre-de-la-laicite-et-de-lecole-laique\/\">Ferdinand Buisson , l&rsquo;ap\u00f4tre de la La\u00efcit\u00e9 et de l&rsquo;Ecole la\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/28\/louverture-du-premier-congres-pedagogique-des-instituteurs-et-institutrices-de-france-1881\/\">L&rsquo;ouverture du Premier Congr\u00e8s P\u00e9dagogique des Instituteurs et Institutrices de France (1881).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/25\/une-lettre-de-ferdinand-buisson-a-victor-hugo-sur-la-laicite-1869\/\">Une lettre de  Ferdinand Buisson \u00e0 Victor Hugo   sur la  La\u00efcit\u00e9 (1869)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/25\/la-lettre-de-jean-jaures-aux-instituteurs-et-institutrices-1888\/\">La Lettre de Jean Jaur\u00e8s aux Instituteurs et Institutrices (1888)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/06\/apres-le-livre-choc-de-j-p-obin-2020-sur-les-atteintes-a-la-laicite-et-lentree-du-communautarisme-a-lecole-refaire-de-lecole-un-sanctuaire\/\">Apr\u00e8s le livre choc de J-P. OBIN (2020) sur  les   atteintes \u00e0  la la\u00efcit\u00e9 et l&rsquo;entr\u00e9e du communautarisme \u00e0 l&rsquo;\u00e9cole; refaire de l&rsquo;\u00e9cole un sanctuaire !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/02\/loeuvre-pionniere-du-baron-boulle-prefet-du-finistere-dans-la-mise-en-application-de-la-loi-guizot-sur-linstruction-primaire-sous-la-monarchie-de-juillet1830-1848\/\">L&rsquo;oeuvre pionni\u00e8re  du Baron Boull\u00e9, pr\u00e9fet du Finist\u00e8re,  dans la mise en application  de la loi Guizot sur l&rsquo;instruction primaire  sous la Monarchie de Juillet(1830-1848).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/29\/premices-normaliennes-quimperoises-sous-le-regime-de-la-loi-guizot-le-cours-normal-de-la-pension-orsibal\/\">Pr\u00e9mices normaliennes quimp\u00e9roises          sous le r\u00e9gime de la loi Guizot:              le Cours normal de la pension ORSIBAL<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/26\/les-creationnismes-contre-la-liberte\/\">Les cr\u00e9ationnismes contre la libert\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/08\/le-code-noir-de-colbert-1685\/\">Le Code Noir de Colbert &#8211; 1685<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/28\/linstruction-du-peuple-sous-divers-gouvernements-racontee-en-1885\/\">L&rsquo;instruction du peuple sous divers gouvernements racont\u00e9e en 1885<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/08\/loi-du-28-mars-1882-portant-sur-lorganisation-de-lenseignement-primaire-en-france\/\">Loi du 28 mars 1882 portant sur l&rsquo;organisation\u00a0de\u00a0l&rsquo;enseignement primaire en France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/linstitutrice-conseils-pratiques\/\">L&rsquo;INSTITUTRICE. Conseils pratiques<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/22\/la-belle-aventure-du-bagad-des-norm-de-leng-de-quimper\/\">La Belle Aventure du Bagad des Norm&rsquo; de l&rsquo;ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/16\/la-loi-portant-etablissement-des-ecoles-normales-primaires-est-restee-en-vigueur-pendant-121-ans\/\">La loi portant \u00e9tablissement des \u00e9coles normales primaires\u00a0 est rest\u00e9e en vigueur pendant 121 ans<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/12\/lesprit-de-promotion-fonde-en-1954-1958-promotion-eng-etincelle-se-transforme-et-participe-a-lesprit-de-corps-qui-se-convertit-au-fil-des-ans-enindefectible-amitie\/\">L&rsquo;esprit de promotion\u00a0fond\u00e9 en 1954-1958 (Promotion ENG Etincelle), se transforme\u00a0 et participe \u00e0 l&rsquo;esprit de corps qui\u00a0se convertit au fil des ans en ind\u00e9fectible amiti\u00e9.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/12\/retour-ineluctable-sur-la-defense-de-loi-de-1905-preparer-les-combats-du-futur-proche-a-laide-de-lectures-de-bon-aloi-pour-un-ete-caniculaire\/\">Retour in\u00e9luctable sur la d\u00e9fense de la loi de 1905 : pr\u00e9parer les combats du futur proche \u00e0 l&rsquo;aide de lectures de bon aloi pour un \u00e9t\u00e9 caniculaire&#8230;\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/07\/03\/parlons-science-la-refutation\/\">Parlons science : la r\u00e9futation<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/14\/notes-anthologiques-de-labbe-joseph-turmel-remises-en-perspectives-par-un-ancien-normalien\/\">Notes anthologiques de l&rsquo;abb\u00e9 Joseph TURMEL remises en perspectives par un ancien normalien<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/les-grands-penseurs-de-leducation\/\">\u00ab\u00a0Les grands penseurs de l&rsquo;EDUCATION\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/daniel-courtin\/\">Daniel COURTIN<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/pierre-helias-etudiant-au-lycee-de-rennes-en-1932-1933\/\">Pierre H\u00e9lias, \u00e9tudiant au Lyc\u00e9e de Rennes en 1932-1933<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/les-eleves-instituteurs-et-institutrices-au-lycee-un-projet-de-lentre-deux-guerres\/\">Les \u00e9l\u00e8ves instituteurs et institutrices au lyc\u00e9e. Un projet de l\u2019entre-deux-guerres<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/ecole-normale-de-quimper-manuscrit-de-1930\/\">Ecole Normale de Quimper &#8211; Manuscrit de 1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/m-courtin-directeur-et-m-beaufils-intendant-un-jour-de-fete-a-leng-dans-les-annees-cinquante\/\">M. Courtin, Directeur et M. Beaufils, Intendant &#8230; un jour de f\u00eate \u00e0 l&rsquo;ENG dans les ann\u00e9es cinquante<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/eminents-professeurs-de-leng-p-keraval-p-j-helias\/\">\u00ab\u00a0Eminents professeurs de l&rsquo;ENG\u00a0\u00bb &#8211; P. Keraval \/ P. J. Helias<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/formes-materielles\/\">formes mat\u00e9rielles<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/28\/apres-lexposition-quimper-les-couleurs-du-temps\/\">Apr\u00e8s l&rsquo;exposition: \u00ab\u00a0Quimper, les couleurs du temps\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/la-facade-nord-du-chateau-de-roz-avel-fut-souvent-photographiee-au-debut-du-20e-siecle\/\">La fa\u00e7ade nord du\u00a0\u00ab\u00a0Ch\u00e2teau de Roz Avel\u00a0\u00bb fut souvent photographi\u00e9e au d\u00e9but du 20\u00e8 si\u00e8cle !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/12\/pour-un-front-unique-republicain-et-laique\/\">Pour un front unique\u00a0 R\u00e9publicain et La\u00efque !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/25\/le-retrait-des-emblemes-religieux-des-locaux-de-lecole-publique-suite-a-la-promulgation-des-lois-scolaires-de-la-3e-republique-et-a-la-laicisation\/\">Le retrait des embl\u00e8mes religieux des\u00a0 locaux de l&rsquo;Ecole publique suite \u00e0 la promulgation des Lois scolaires de la 3\u00e8 R\u00e9publique et \u00e0 la la\u00efcisation<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/tribune-agricole-lenseignement-agricole-dans-les-ecoles-normales\/\">Tribune agricole &#8211; l&rsquo;enseignement agricole dans les Ecoles Normales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/24\/lhistoire-ephemere-du-bagad-de-leng-de-quimper-1949-1980\/\">L&rsquo;histoire \u00e9ph\u00e9m\u00e8re du bagad de l&rsquo;ENG de QUIMPER (1949-1980)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/03\/l-harmonie-de-leng-de-quimper-1954-1971\/\">L&rsquo; Harmonie de l&rsquo;ENG de Quimper (1954-1971)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/03\/souvenirs-de-la-guerre-dalgerie\/\">Souvenirs de la Guerre d&rsquo;Alg\u00e9rie<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/07\/08\/les-hussards-noirs-et-le-monde-paysan\/\">Les hussards noirs et le monde paysan<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/03\/mai-1934-faire-face-aux-difficultes-de-lecole-laique-et-de-ses-maitres-dans-un-contexte-politique-difficile\/\">Mai 1934: faire face aux difficult\u00e9s de l&rsquo;Ecole La\u00efque et de ses Ma\u00eetres dans un contexte politique difficile<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/loi-sur-linstruction-primaire-obligatoire-du-9-aout-1936\/\">Loi sur l\u2019instruction primaire obligatoire du 9 ao\u00fbt 1936<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/merci-pour-tout\/\">MERCI POUR TOUT<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/ens-de-jeunes-filles-de-fontenay-aux-roses-felix-pecaut\/\">ENS de jeunes filles de Fontenay-aux-Roses (F\u00e9lix P\u00e9caut)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/ouvrage-de-reference-chez-les-normaliennes-a-la-fin-des-annees-30\/\">Ouvrage de r\u00e9f\u00e9rence chez \u00a0les normaliennes \u00a0\u00e0 la fin des ann\u00e9es 30<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/poesie-et-recitations-de-la-fin-des-annees-30\/\">Po\u00e9sie et r\u00e9citations de la fin des ann\u00e9es 30<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/apprentissage-du-chant-a-lenf-fin-des-annees-30\/\">Apprentissage du chant \u00e0 l&rsquo;ENF (fin des ann\u00e9es 30)<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/glanes-et-perles\/\">glanes et perles<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/28\/monnaie-de-la-vie-quotidienne-en-pays-bretonnant-2\/\">Monnaie de la vie quotidienne en pays bretonnant.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/06\/clauda-jegou-paysan-de-larree\/\">Clauda JEGOU, paysan de l&rsquo;Arr\u00e9e<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/02\/les-moines-ligueurs-dans-leurs-oeuvres-a-landerneau\/\">Les moines ligueurs dans leurs \u0153uvres \u00e0 Landerneau<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/02\/les-desordres-du-camp-republicain-face-a-lorganisation-clericale-en-1934\/\">Les d\u00e9sordres du camp r\u00e9publicain face \u00e0 l&rsquo;organisation cl\u00e9ricale en 1934<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/26\/1934-sombre-annee-ou-il-fallait-conserver-pour-la-survie-de-lecole-laique-le-sens-de-lhumour\/\">1934&#8230; Sombre ann\u00e9e o\u00f9 il fallait conserver, pour la survie de l&rsquo;\u00e9cole la\u00efque, le sens de l&rsquo;humour<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/mots-de-combat-de-jean-jaures\/\">Mots de combat de Jean Jaur\u00e8s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/le-petit-odet\/\">Le petit ODET<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/clericalismes-et-laicite-les-lecons-de-lhistoire\/\">Cl\u00e9ricalismes et la\u00efcit\u00e9 : les le\u00e7ons de l&rsquo;histoire !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/elements-de-morale-professionnelle-extraits-du-code-de-linstituteur-1751\/\">El\u00e9ments de morale professionnelle \u00a0extraits du Code de l&rsquo;Instituteur\u00a0(1751)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/les-diffamateurs-de-lecole-laique-et-de-ses-maitres-condamnes-au-tribunal\/\">Les diffamateurs de l&rsquo;\u00e9cole la\u00efque et de ses ma\u00eetres condamn\u00e9s au tribunal<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/la-defense-de-lecole-laique-et-des-instituteurs-en-mai-1927\/\">La d\u00e9fense de l&rsquo;Ecole la\u00efque et des instituteurs en mai 1927<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/la-liberte-de-la-presse-ne-suse-que-lorsque-lon-ne-sen-sert-pas\/\">La libert\u00e9 de la presse \u2026\u00a0ne s\u2019use que lorsque l\u2019on ne s\u2019en sert pas\u00a0!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/publication-de-la-terre-des-pretres-1924\/\">Publication de La Terre des Pr\u00eatres (1924)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/la-lettre-dun-jeune-instituteur-mobilise-a-un-ancien-collegue-ayant-participe-aux-combats-de-la-guerre-franco-allemande-de-1870-dapres-le-petit-citoyen-n37-du-21-aout-1914\/\">La lettre d&rsquo;un jeune instituteur mobilis\u00e9 \u00e0 un ancien (coll\u00e8gue) ayant particip\u00e9 aux combats de la guerre franco-allemande de 1870&#8230;\u00a0(D&rsquo;apr\u00e8s Le Petit Citoyen n\u00b037 du 21 ao\u00fbt 1914).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/recompenses-aux-instituteurs-et-ecoles-normales\/\">R\u00e9compenses aux instituteurs et \u00e9coles normales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/la-question-des-inventaires-suite-au-vote-de-la-loi-de-separation-de-1905\/\">La question des inventaires (suite au vote de la loi de s\u00e9paration de 1905)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/le-poids-de-la-loi-de-separation-de-1905-dans-la-campagne-electorale-du-printemps-1906\/\">Le poids de la Loi de S\u00e9paration de 1905 dans la campagne \u00e9lectorale du printemps 1906.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/reglement-concernant-les-ecoles-normales-primaires-14-decembre-1832\/\">R\u00e8glement concernant les Ecoles Normales Primaires (14 d\u00e9cembre 1832).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/les-fideles-juchois-et-juchoises-decouvrent-le-diable-en-soutane-1906\/\">Les fid\u00e8les juchois et juchoises \u00a0d\u00e9couvrent le diable en soutane (1906).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/assertions-de-jules-ferry-1832-1893-les-lecons-de-lhistoire\/\">Assertions \u00a0de Jules Ferry (1832 -1893); les le\u00e7ons de l&rsquo;histoire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/un-citoyen\/\">UN CITOYEN<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/pensee-relevee-dans-le-citoyen-jeudi-6-juin-1929\/\">Pens\u00e9e relev\u00e9e dans le Citoyen\u00a0(jeudi 6 juin 1929)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/echos-du-congres-du-syndicat-national-des-instituteurs-1922\/\">Echos du congr\u00e8s du Syndicat national des Instituteurs (1922)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/laicite-2\/\">La\u00efcit\u00e9&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/varietes-litteraires-linstituteur-dautrefois\/\">Vari\u00e9t\u00e9s litt\u00e9raires : L&rsquo;INSTITUTEUR D&rsquo;AUTREFOIS<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/les-cures-et-la-liberte-de-lecole\/\">Les Cur\u00e9s et la Libert\u00e9 de l&rsquo;Ecole<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/plouhinec-un-exploit\/\">Plouhinec : un exploit.<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/inventorier\/\">inventorier<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/24\/quand-lon-redecouvre-en-2019-que-lecole-normale-des-filles-sise-rue-de-brest-a-quimper-site-de-stang-ar-choat-possedait-une-conciergerie\/\">Quand l&rsquo;on red\u00e9couvre, en 2019, que l&rsquo;Ecole Normale des Filles sise rue de Brest \u00e0 Quimper (Site de Stang ar C&rsquo;hoat) poss\u00e9dait une conciergerie&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/14\/recitation-francaise-livre-du-maitre\/\">R\u00e9citation Fran\u00e7aise\u00a0&#8211; (Livre du Ma\u00eetre)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/11\/nos-vieux-livres-decolier\/\">Nos vieux livres d&rsquo;\u00e9colier<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/jules-ferry\/\">JULES FERRY<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/loi-fondatrice-du-9-aout-1879\/\">Loi fondatrice du 9 ao\u00fbt 1879<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/inventorier-enf\/\">inventorier enf<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/03\/lincendie-de-lecole-normale-dinstitutrices-en-1934\/\">L&rsquo;incendie de l&rsquo;Ecole Normale d&rsquo;Institutrices en 1934<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/mais-ou-sont-donc-cachees-les-normaliennes\/\">Mais o\u00f9 sont donc cach\u00e9es les normaliennes ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/enf-photographies-actuelles\/\">ENF &#8211; Photographies actuelles<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/enf-photographies-anciennes\/\">ENF &#8211; Photographies anciennes<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/inventorier-eng\/\">inventorier eng<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/eng-photographies-actuelles\/\">ENG &#8211; Photographies actuelles<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/exterieurs-emblematiques-de-notre-grande-maison-de-roz-avel-apercus-le-18-novembre-2016-par-un-photographe-anonyme-egare-dans-les-lieux\/\">Ext\u00e9rieurs embl\u00e9matiques de notre grande maison de Roz Avel aper\u00e7us, le 18 novembre 2016, par un photographe anonyme \u00e9gar\u00e9 dans les lieux.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/photos-anciennes-batiments-eng\/\">Photos anciennes &#8211; B\u00e2timents ENG<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/la-cote\/\">la cote<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/la-cote-1969-promotion-les-aiglons-1967-1971\/\">\u00a0La Cote 1969 (promotion Les Aiglons , 1967-1971)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/05\/la-cote-54-a-leng-promotion-aurore-1952-1956\/\">La Cote 54 \u00e0 l&rsquo;ENG (Promotion Aurore, 1952-1956)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/05\/la-cote-1952-a-leng-promotion-armor-50-54\/\">La Cote 1952 \u00e0 l&rsquo;ENG (Promotion ARMOR, 50-54)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/09\/11\/carte-de-cote-promotion-1960-1964\/\">Carte de Cote-Promotion ARMORIQUE -1960-1964<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-aventure-1948-1952\/\">Carte de Cote Promotion Aventure (1948-1952)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-armor-1950-1954\/\">Carte de Cote Promotion ARMOR, 1950-1954<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/cote-56\/\">Cote 56<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-popeye-1957-1961\/\">Carte de cote &#8211; Promotion POPEYE -1957-1961<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-belzebuth-1957\/\">Carte de Cote &#8211; Promotion Belzebuth &#8211; 1957<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/la-cote-1962-premonitoire-dun-grand-cru\/\">La Cote 1962, pr\u00e9monitoire d&rsquo;un grand cru !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-albatros-1958-1962\/\">Carte de cote &#8211; Promotion ALBATROS &#8211; 1958-1962<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-sphynx-1957\/\">Carte de Cote promotion Sphinx (1957)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-caravelle-1959-1963\/\">Carte de cote &#8211; Promotion Caravelle &#8211; 1959-1963<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-les-cometes-1963-1967\/\">Carte de Cote, Promotion LES COMETES, 1963-1967<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/carte-de-cote-promotion-olympic-1964-1968\/\">Carte de cote &#8211; Promotion Olympic &#8211; 1964-1968<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/la-question\/\">la question<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/29\/tout-enseignement-veritable-est-laique\/\">Tout enseignement v\u00e9ritable est la\u00efque !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/10\/lecole-republicaine-fabrique-des-egaux\/\">L&rsquo;\u00e9cole r\u00e9publicaine fabrique des \u00e9gaux.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/01\/08\/la-raison-laique-contre-tous-les-obscurantismes-article-2\/\">La raison la\u00efque contre tous les obscurantismes (article 2)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/01\/08\/la-raison-laique-contre-tous-les-obscurantismes-article-1\/\">La raison la\u00efque contre tous les obscurantismes (article 1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/22\/lecole-telle-que-la-republique-la-veut-pour-ses-enfants-selon-paul-bert-1880\/\">L&rsquo;ECOLE, telle que la R\u00e9publique la veut pour ses enfants\u00a0 selon Paul Bert\u00a0(1880)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/22\/pendant-que-clericaux-et-laiques-commencent-a-regler-contentieux-et-comptes-en-1880-jules-ferry-est-le-maitre-des-horloges\/\">Pendant que cl\u00e9ricaux et la\u00efques\u00a0commencent \u00e0 r\u00e9gler contentieux et comptes en 1880,\u00a0Jules Ferry est le ma\u00eetre des horloges !\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/se-tromper-ne-pas-savoir-mais-continuer-a-avancer-lecon-dhumilite\/\">Se tromper, ne pas savoir mais continuer \u00e0 avancer\u00a0\u00bb:\u00a0le\u00e7on d&rsquo;humilit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/13\/apres-lecole-laboratoire-de-john-dewey-1859-1952-et-lecole-moderne-de-celestin-freinet1896-1966-on-redecouvre-la-pedagogie-par-projets-gilles-dewek-2019\/\">Apr\u00e8s l&rsquo;\u00e9cole-laboratoire de\u00a0John Dewey (1859-1952) et l&rsquo;\u00e9cole moderne de\u00a0C\u00e9lestin Freinet(1896-1966), on red\u00e9couvre la p\u00e9dagogie par projets (Gilles Dewek, 2019)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/13\/regards-contemporains-sur-la-bonne-education\/\">Regards contemporains sur la BONNE EDUCATION<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/08\/mens-sana-in-corpore-sano-juvenal-90-127\/\">Mens sana in corpore sano (Juvenal, 90-127)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/08\/quand-le-loup-liberal-sinvite-dans-la-bergerie-scolaire\/\">Quand le loup lib\u00e9ral s&rsquo;invite dans la bergerie scolaire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/01\/la-montee-des-perils-en-1938-et-le-role-essentiel-de-lecole-laique\/\">La mont\u00e9e des p\u00e9rils en 1938 et le r\u00f4le essentiel de l&rsquo;Ecole La\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/le-projet-decole-de-la-libre-pensee-en-1929\/\">Le projet d&rsquo;\u00e9cole de la Libre Pens\u00e9e en 1929<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/lanticlericalisme-de-victor-hugo-1802-1885-exprime-dans-quelques-uns-de-ses-textes-fondateurs-sur-lecole\/\">L&rsquo;anticl\u00e9ricalisme de Victor HUGO (1802-1885) exprim\u00e9 dans quelques uns de ses textes fondateurs sur\u00a0 l&rsquo;Ecole<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/lorsquen-1928-le-flambeau-journal-periodique-de-la-libre-pensee-pose-des-questions-fondatrices-sur-la-signification-des-programmes-et-methodes-de-lecole-publique-republicaine-1\/\">Lorsqu&rsquo;en 1928\u00a0Le Flambeau, journal p\u00e9riodique de la Libre Pens\u00e9e, pose des questions fondatrices sur la signification des Programmes et M\u00e9thodes de l&rsquo;\u00e9cole publique r\u00e9publicaine (1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/25\/a-la-bonne-ecole-de-ferdinand-buisson\/\">A la bonne \u00e9cole\u00a0 de Ferdinand Buisson !\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/24\/paroles-de-poetes-et-paroles-decoliers-de-la-liberation-et-de-lemancipation\/\">Paroles de po\u00e8tes et paroles d&rsquo;\u00e9coliers de la Lib\u00e9ration et de l&rsquo;\u00e9mancipation<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/24\/ecole-laique-republicaine-et-integration-sociale-un-exemple-a-suivre\/\">Ecole la\u00efque r\u00e9publicaine et int\u00e9gration sociale :\u00a0 un exemple \u00e0 suivre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/quest-ce-quune-bonne-ecole\/\">Qu&rsquo;est-ce qu&rsquo;une bonne \u00e9cole ?<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/le-pere-cent\/\">le p\u00e8re cent<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/pere-cent-promotion-ceinture-1941-1944\/\">P\u00e8re Cent Promotion Ceinture (1941-1944)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/pere-cent-de-la-promotion-avenir-1943-1946\/\">P\u00e8re Cent de la PROMOTION AVENIR (1943-1946)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/pere-cent-de-la-promotion-hirondelle\/\">P\u00e8re Cent de la promotion HIRONDELLE &#8211; 1955-1959<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/pere-cent-de-la-promotion-ouragan-1957-1961\/\">P\u00e8re Cent de la promotion OURAGAN -1957-1961<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/lettres-aux-instituteurs\/\">lettres aux instituteurs<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/circulaire-adressee-par-francois-guizot-aux-instituteurs-suite-a-la-loi-de-1833-sur-lenseignement\/\">Circulaire adress\u00e9e par Fran\u00e7ois Guizot aux instituteurs, suite \u00e0 la loi de 1833 sur l\u2019enseignement<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/la-lettre-de-jules-ferry-aux-instituteurs-27-novembre-1883\/\">LA LETTRE DE JULES FERRY AUX INSTITUTEURS (27 NOVEMBRE 1883)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/lettre-de-jean-jaures-aux-instituteurs\/\">LETTRE DE JEAN JAURES AUX INSTITUTEURS<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/lettre-de-petain-a-andre-delmas-sni-22-09-1940\/\">Lettre de Petain a Andre Delmas, SNI\u00a0 22 09 1940<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/circulaire-scelerate-de-a-bonnard-aout-1942\/\">Circulaire sc\u00e9l\u00e9rate de A. Bonnard, ao\u00fbt 1942<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/morceaux-danthologie-relatifs-a-la-suppression-des-ecoles-normales-et-a-la-formation-des-instituteurs\/\">Morceaux d&rsquo;anthologie relatifs \u00e0 la suppression des Ecoles Normales et \u00e0 la formation des Instituteurs&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/de-lecole-idealisee-a-lecole-refondee-sauvons-lecole-laique\/\">DE L&rsquo;ECOLE IDEALISEE A L&rsquo;ECOLE REFONDEE : SAUVONS L&rsquo;ECOLE LA\u00cfQUE<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/musique-et-sports\/\">musique et sports<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/26\/les-derniers-exploits-de-lharmonie-de-leng-de-quimper\/\">Les derniers exploits de l&rsquo;Harmonie de l&rsquo;ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/les-debuts-hauts-en-couleur-de-lharmonie-de-leng-racontes-et-illustres-par-andre-le-goff\/\">Les d\u00e9buts hauts en couleur de l&rsquo;Harmonie de l&rsquo;ENG racont\u00e9s et illustr\u00e9s\u00a0 par Andr\u00e9 le GOFF.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/18\/quand-les-normaliennes-de-la-promotion-atomick-1946-1949-et-des-normaliens-encostumes-a-la-bretonne-participaient-activement-a-des-fetes-folkloriques\/\">Quand les normaliennes de la promotion ATOMICK (1946-1949) et des normaliens encostum\u00e9s \u00e0 la bretonne participaient activement \u00e0 des\u00a0f\u00eates\u00a0folkloriques\u00a0!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/10\/les-glorieux-foootballeurs-cadets-de-leng-de-quimper-1956-1957\/\">Les glorieux footballeurs cadets de l&rsquo;ENG\u00a0de Quimper (1956-1957)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/14\/le-bagad-de-leng-en-deplacement-a-pont-labbe\/\">Le bagad de l&rsquo;ENG en d\u00e9placement \u00e0 Pont- l&rsquo;Abb\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/le-bagad-de-leng-en-formation-de-defile-en-1959\/\">Le Bagad de l&rsquo;ENG en formation de d\u00e9fil\u00e9 en 1959&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/le-bagad-de-leng-a-lhonneur\/\">Le BAGAD de l&rsquo;ENG \u00e0 l&rsquo;honneur !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/14\/le-sport-a-len-de-quimper\/\">Le sport \u00e0 l&rsquo;EN de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/hagiographie-et-fantasmagories-dun-ancien-penn-soner-du-bagad-skol-veur\/\">Hagiographie et fantasmagories d&rsquo;un ancien Penn-soner du Bagad\u00a0 SKOL-VEUR:<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/les-footballeurs-de-lunion-sportive-normalienne-de-la-saison-1933-1934\/\">Les footballeurs de l&rsquo;Union Sportive Normalienne de la saison 1933-1934 .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/les-talentueux-footballeurs-de-lusn-a-lhonneur-de-1931-a-1934\/\">Les talentueux footballeurs de \u00a0l&rsquo;USN \u00e0 l&rsquo;honneur de 1931 \u00e0 1934<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/initiation-au-mini-golf-a-lenf\/\">Initiation au \u00ab\u00a0mini-golf\u00a0\u00bb \u00e0 l&rsquo;ENF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/initiation-au-tennis-a-lenf\/\">Initiation au tennis \u00e0 l&rsquo;ENF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/normaliennes-parees-pour-le-defile\/\">Normaliennes par\u00e9es pour le d\u00e9fil\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/les-normaliennes-championnes-de-volley-ball\/\">Les normaliennes &#8211; Promotion Belzebuth &#8211; championnes de volley-ball<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/football\/\">Football<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/fanfares\/\">Fanfares<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/harmonies\/\">Harmonies<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/ecole-normale-1959-creps-dinard\/\">Ecole Normale 1959 CREPS Dinard<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/bal-costume-en-annees-60\/\">Bal costume\u0301 &#8211; EN anne\u0301es 60<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/defiles\/\">D\u00e9fil\u00e9s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/bagads\/\">BAGADS<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/equipe-de-hand-ball-eng\/\">EQUIPE DE HAND BALL ENG<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/equipe-de-hand-ball-enf-196\/\">Equipe de hand Ball ENF 196&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/equipe-de-hand-ball-enf-1964\/\">Equipe de Hand Ball ENF 1964<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/stage-a-treboul-1964\/\">Stage a\u0300 Tre\u0301boul 1964<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/harmonie-eng-1965\/\">Harmonie ENG, 1965<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/depart-de-stage-a-treboul-1966-pres-conciergerie\/\">De\u0301part de stage a\u0300 Tre\u0301boul 1966 pre\u0300s conciergerie<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/bagad-1966-kevrenn-en\/\">Bagad &#8211; 1966 Kevrenn EN<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/fe%cc%82te-de-la-jeunesse-1966\/\">Fe\u0302te de la Jeunesse 1966<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/le-bagad-en-1966-a-goulien\/\">Le Bagad en 1966 a\u0300 Goulien<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/eng-1969-devant-le-nouveau-ba%cc%82timent\/\">ENG 1969 Devant le nouveau ba\u0302timent<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/groupes-annees-70\/\">Groupes &#8211; ann\u00e9es 70<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/09\/union-sportive-normalienne-carte-de-membre-honoraire\/\">Union Sportive Normalienne &#8211; Carte de Membre Honoraire<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/non-classe\/\">Non class\u00e9<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/27\/en-hommage-a-yves-cotty\/\">En hommage \u00e0 Yves Cotty<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/12\/09\/1905-2025\/\">1905-2025<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/10\/le-wokisme-lindifferenciation-et-la-logique-inversee-de-la-victime-expiatoire\/\">Le wokisme, l\u2019indiff\u00e9renciation et la logique invers\u00e9e de la victime expiatoire\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/03\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xix\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XIX)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/11\/15\/turpitudes-clericales-et-contre-turpitudes-ecclesiales-une-suite-a-ne-pas-oublier\/\">Turpitudes cl\u00e9ricales et contre-turpitudes eccl\u00e9siales \u2026 une suite \u00e0 ne pas oublier !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/22\/les-professeurs-de-mathematiques-sont-ils-des-fatalistes\/\">Les professeurs de math\u00e9matiques sont-ils des fatalistes ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/19\/une-saine-respiration-laique-ne-peut-conduire-a-un-integrisme-laique-contraire-a-la-liberte-dexpression\/\">Une saine \u201crespiration la\u00efque\u201d   ne peut conduire \u00e0  un int\u00e9grisme la\u00efque contraire  \u00e0 la libert\u00e9 d&rsquo;expression.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/29\/les-premices-de-la-parite-et-de-legalite-reelle-entre-femmes-et-hommes-dans-le-monde-ecclesiastique\/\">Les pr\u00e9mices(?) de la parit\u00e9 et de l&rsquo;\u00e9galit\u00e9 r\u00e9elle  entre femmes et hommes  dans le monde eccl\u00e9siastique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/08\/la-loi-de-separation-des-eglises-et-de-letat-de-1905-appliquee-avec-toute-la-rigueur-necessaire-resout-la-question-du-separatisme\/\">La Loi de S\u00e9paration des Eglises et de l&rsquo;Etat de 1905 ,appliqu\u00e9e avec toute la rigueur  n\u00e9cessaire, r\u00e9sout la question du \u00ab\u00a0S\u00e9paratisme\u00a0\u00bb .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/09\/08\/jules-simon-raconte-ses-souvenirs-deleve-au-college-de-vannes-en-1830\/\">Jules Simon raconte ses souvenirs d&rsquo;\u00e9l\u00e8ve au Coll\u00e8ge de Vannes  en 1830.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/chronique-finisterienne-des-faits-et-bruits-autour-de-lecole-en-1884-a-suivre\/\">Chronique finist\u00e9rienne des faits et bruits autour de l&rsquo;Ecole en 1884 ( \u00e0 suivre)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/11\/28\/deux-nouvelles-cartes-de-cote\/\">Deux nouvelles cartes de Cote<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-menestrels-1966-1970\/\">Promotion LES MENESTRELS &#8211; 1966-1970<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-eng-1909-1912\/\">Promotion ENG 1909-1912<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-tempete-1947-1951\/\">Promotion TEMP\u00caTE &#8211; 1947-1951<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/partager\/\">partager<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/03\/08\/elements-biographiques-de-pierre-jakez-helias\/\">El\u00e9ments biographiques de Pierre  Jakez H\u00e9lias<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/03\/02\/a-propos-des-memoires-de-normalienne-de-jeanne-le-borgne\/\">A propos des m\u00e9moires de normalienne de Jeanne  Le Borgne<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/03\/02\/reconstitution-dune-monographie-de-cfen\/\">Reconstitution d&rsquo;une monographie de CFEN\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/11\/14\/promo-etincelle-eng-quimper-54-58\/\">Promo ETINCELLE (ENG Quimper, 54-58)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/15\/tradition-ritualisee-des-ecoles-normales-primaires-du-departement-de-la-meuse-la-509\/\">Tradition ritualis\u00e9e  des \u00e9coles normales primaires  du d\u00e9partement de la Meuse : \u00ab\u00a0La 509\u00a0\u00bb !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/10\/28\/des-normaliennes-et-leur-directrice-au-travail-a-stang-ar-choat\/\">Des normaliennes et leur directrice au travail \u00e0 Stang ar c&rsquo;Hoat.<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/principes-fondateurs\/\">principes fondateurs<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/28\/la-republique-lagriculture-et-lenseignement-primaire-les-premices-dun-compagnonnage-difficile-mais-necessaire\/\">La R\u00e9publique,\u00a0 l&rsquo;Agriculture et l&rsquo;Enseignement primaire :\u00a0les pr\u00e9mices d&rsquo;un compagnonnage difficile mais n\u00e9cessaire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/28\/des-propositions-edifiantes-pour-les-jours-dapres-pandemie\/\">Des propositions \u00e9difiantes pour les jours d&rsquo;apr\u00e8s pand\u00e9mie<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/la-laicite-de-nos-institutions-republicaines-a-lepreuve-de-la-pandemie-provoquee-par-le-coronavirus-sars-cov-2\/\">La la\u00efcit\u00e9 de nos institutions r\u00e9publicaines\u00a0\u00e0 l&rsquo;\u00e9preuve de la pand\u00e9mie\u00a0provoqu\u00e9e par le coronavirus\u00a0 SARS-CoV-2<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/06\/dogme-et-hysterie-climatique\/\">Dogme et hyst\u00e9rie climatique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/22\/de-leducation-du-peuple-citoyen-acte-de-foi-en-lautonomie-et-en-la-raison-a-la-souverainete-de-la-nation\/\">De l&rsquo;\u00e9ducation du peuple citoyen, acte de foi en l&rsquo;autonomie et en la raison, \u00e0 la souverainet\u00e9 de la Nation<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/05\/la-forme-consolidee-de-la-loi-de-separation-des-eglises-et-de-letat-9-decembre-1905-du-7-novembre-2018\/\">La forme consolid\u00e9e de la Loi de S\u00e9paration DES \u00e9glises et de l&rsquo;Etat (9 d\u00e9cembre 1905) du 7 novembre 2018<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/19\/aux-origines-de-la-libre-pensee-la-science-en-danger\/\">\u00ab\u00a0Aux origines de la Libre Pens\u00e9e, la science en danger\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/lorsque-le-citoyen-hebdomadaire-de-defense-laique-et-daction-republicaine\/\">Lorsque Le Citoyen, hebdomadaire\u00a0de d\u00e9fense la\u00efque et d&rsquo;action r\u00e9publicaine,<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/lois-scolaires-de-la-3e-republique-fondatrices-de-lecole-laique\/\">Lois scolaires de la 3\u00e8 R\u00e9publique fondatrices de l\u2019\u00e9cole la\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/loi-du-9-decembre-1905-concernant-la-separation-des-eglises-et-de-letat\/\">Loi du 9 d\u00e9cembre 1905\u00a0concernant la s\u00e9paration des Eglises et de l\u2019Etat<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/promotions-enf\/\">promotions enf<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/01\/promotions-normaliennes-sans-nom-absentes-sur-le-site-retrouvees-grace-aux-listes-des-delegations-dans-les-fonctions-dinstituteurs-et-dinstitutrices-stagiaires-en-septembre-193\/\">Promotions normaliennes sans nom, absentes sur le site,\u00a0 retrouv\u00e9es gr\u00e2ce aux\u00a0 listes\u00a0 des d\u00e9l\u00e9gations dans les fonctions d&rsquo;instituteurs et d&rsquo;institutrices stagiaires en septembre 1938<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-atomick-1946-1949\/\">Promotion ATOMICK &#8211; 1946-1949<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-bout-au-vent-1936-1939\/\">Promotion BOUT AU VENT &#8211; 1936-1939<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-comme-leclair-1936-1939\/\">Promotion COMME l&rsquo;ECLAIR &#8211; 1936-1939<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-1925-1928\/\">Promotion ? &#8211; 1925-1928<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-bout-au-vent-1938-1941\/\">Promotion BOUT AU VENT &#8211; 1938-1941<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/les-demoiselles-de-la-rue-de-brest\/\">\u00ab\u00a0Les demoiselles de la rue de Brest\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-djinns-1953-1957\/\">Promotion DJINNS &#8211; 1953-1957<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-fantaisie-carte-de-cote-1954\/\">Promotion FANTAISIE &#8211; carte de cote 1954<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-arc-en-ciel-1954-1958\/\">Promotion ARC-EN-CIEL &#8211; 1954-1958<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promo-belzebuth-1955-1959\/\">Promo BELZEBUTH &#8211; 1955-1959<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-calypso-1957-1961\/\">Promotion CALYPSO -1957-1961<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-enf-1956-1960-sphynx\/\">Promotion ENF 1956-1960 &#8211; SPHINX<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-edelweiss-1959-1963\/\">Promotion EDELWEISS &#8211; 1959-1963<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-olympiades-1960-1964\/\">Promotion Les OLYMPIADES &#8211; 1960-1964<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-korrigan-1961-1965\/\">Promotion KORRIGAN &#8211; 1961-1965<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-bruyeres-1962-1966\/\">Promotion LES BRUYERES &#8211; 1962-1966<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-cometes-1963-1967\/\">Promotion LES COMETES &#8211; 1963-1967<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-abeilles\/\">Promotion LES ABEILLES<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-mouettes-1965-1969\/\">Promotion LES MOUETTES &#8211; 1965-1969<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-cactus-1967-1971\/\">Promotion LES CACTUS &#8211; 1967-1971<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/1970-les-russes-promotion-a-identifier\/\">promotion LES SATELLITES (1968-1973)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-satellites-1968-1973\/\">Promotion LES SATELLITES &#8211; 1968-1973<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/enf-promotion-a-identifier\/\">ENF promotion \u00e0 identifier<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/groupe-de-normaliennes-a-leng-1971\/\">Groupe de normaliennes \u00e0 l&rsquo;ENG &#8211; 1971<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-cometes\/\">Promotion COMETES<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-ose-et-cela-sera-annee-a-retrouver\/\">Promotion OSE ET CELA SERA (ann\u00e9e \u00e0 retrouver&#8230;)<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/promotions-eng\/\">promotions eng<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/13\/promotions-eng-et-enf-sans-noms-avis-de-recherche\/\">Promotions ENG et ENF sans noms: avis de recherche !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/06\/10\/le-don-spontane-de-la-magnifique-photo-dun-groupe-de-hussards-noirs-de-leng-de-quimper-par-lun-de-nos-adherents\/\">Le don spontan\u00e9\u00a0de la magnifique photo d&rsquo;un groupe de hussards noirs de L&rsquo;ENG de Quimper\u00a0par l&rsquo;un de nos\u00a0adh\u00e9rents<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/18\/quand-les-normaliens-du-finistere-1873-1874-faisaient-leurs-etudes-a-len-de-rennes\/\">Quand les normaliens du Finist\u00e8re (1873-1874) faisaient leurs \u00e9tudes \u00e0 l&rsquo;EN de Rennes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/17\/promotion-eng-1901-1902\/\">Promotion ENG &#8211; 1901-1902<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/16\/promotion-eng-1902\/\">Promotion ENG &#8211; 1902<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/15\/promotion-eng-1905-08\/\">Promotion ENG &#8211; 1905-08<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/14\/promotion-eng-1906-1909\/\">Promotion ENG &#8211; 1906-1909<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/promotion-eng-1907-1910\/\">Promotion ENG 1907-1910<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/promotion-eng-1908-1911\/\">promotion ENG 1908-1911<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-eng-1910-1913\/\">Promotion ENG &#8211; 1910-1913<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-eng-1918\/\">Promotion ENG &#8211; 1918<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/photo-de-promotion-date-inconnue\/\">Photo de promotion &#8211; Date inconnue&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-eng-1928-1031\/\">Promotion ENG &#8211; 1928-1931<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-eng-1922-1925\/\">Promotion ENG &#8211; 1922-1925<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-eng-annee\/\">Promotion ENG ann\u00e9e ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-eng-1925\/\">Promotion ENG &#8211; 1925<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-charleston-1927-1930\/\">Promotion CHARLESTON &#8211; 1927-1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-pitche-1933-1936\/\">Promotion PITCHE &#8211; 1933-1936<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-mickey-1931-1934\/\">Promotion MICKEY &#8211; 1931-1934<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-expo-1937-1940\/\">Promotion EXPO &#8211; 1937-1940<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-41-43\/\">Promotion 41-43<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-ceinture-1941-1944\/\">Promotion CEINTURE &#8211; 1941-1944<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-en-avant-1942-1945\/\">Promotion EN AVANT &#8211; 1942-1945<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-avenir-1943-1946\/\">Promotion AVENIR 1943-1946<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-liberation-1944-1947\/\">Promotion LIBERATION  &#8211; 1944-1947<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-perherin-yves-1945-1948\/\">Promotion PERHERIN YVES &#8211; 1945-1948<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-renaissance-1946-1950\/\">Promotion RENAISSANCE &#8211; 1946-1950<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-amitie-1949-1953\/\">Promotion AMITIE &#8211; 1949-1953<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-aventure-1949-1952\/\">Promotion AVENTURE &#8211; 1949-1952<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-avenir-1948-1952\/\">Promotion AVENIR &#8211; 1948-1952<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-armor-1950-1954\/\">Promotion ARMOR 1950-1954<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-flamme-1950-1955\/\">Promotion FLAMME &#8211; 1950-1955<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-aurore-1952-1956\/\">Promotion AURORE- 1952-1956<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-deleves-maitres-1949-1953-accompagnee-du-directeur-d-courtin\/\">Promotion d&rsquo;\u00e9l\u00e8ves-ma\u00eetres (1949-1953) accompagn\u00e9e du directeur D. Courtin<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-amitie-1952-1953\/\">Promotion AMITIE &#8211; 1952-1953&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-emeraude-1953-1957\/\">Promotion EMERAUDE &#8211; 1953-1957<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-etincelle-1954-1958\/\">Promotion ETINCELLE &#8211; 1954-1958<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-hirondelle-1955-1959\/\">Promotion HIRONDELLE &#8211; 1955-1959<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-comete-1956-1960\/\">Promotion COMETE &#8211; 1956-1960<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-ouragan-1957-1961\/\">Promotion OURAGAN -1957-1961<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-albatros-1958-1962\/\">Promotion ALBATROS &#8211;  1958-1962<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-caravelle-1959-1963\/\">Promotion CARAVELLE 1959-1963<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-aigles-1961-1965\/\">Promotion LES AIGLES &#8211; 1961-1965<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/pormotion-armorique-1960-1964\/\">Promotion ARMORIQUE (1960-1964)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-kon-tiki-1963-1967\/\">Promotion KON-TIKI &#8211; 1963-1967<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-telstar-1962-1966\/\">Promotion TELSTAR &#8211; 1962-1966<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-olympic-1964-1968\/\">Promotion OLYMPIC &#8211; 1964-1968<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-concorde-1965-1969\/\">Promotion CONCORDE &#8211; 1965-1969<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-le-pourquoi-pas-1966-1970\/\">Promotion LE POURQUOI PAS -1966-1970<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/1970\/\">1970<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-les-aiglons-1967-1971\/\">Promotion LES AIGLONS &#8211; 1967-1971<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/10\/carte-et-photo-de-promotion-manquantes\/\">Carte et photo de promotion manquantes :1947-1951<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2010\/11\/01\/promotion-herakles-1970\/\">Promotion HERAKLES &#8211; 1968-1973<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/sauvegarder-et-valoriser\/\">sauvegarder et valoriser<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/27\/pour-une-ecole-gratuite-obligatoirelaique-et-souveraine-a-lage-de-lintelligence-artificielle\/\">Pour une Ecole gratuite, obligatoire,la\u00efque et souveraine  \u00e0 l\u2019\u00e2ge de l\u2019intelligence artificielle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/19\/eglises-abus-sexuels-et-discriminations-au-royaume-uni\/\">Eglises, abus sexuels et discriminations au Royaume Uni<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/17\/quand-des-paysans-cornouaillais-parlaient-politique-en-breton\/\">Quand des paysans cornouaillais parlaient politique en breton<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/14\/le-drapeau-tricolore-symbole-dispute-et-outil-de-construction-dune-conscience-nationale-laique-et-republicaine\/\">Le drapeau tricolore,  symbole disput\u00e9  et outil  de  \u00ab construction d\u2019une conscience nationale la\u00efque et r\u00e9publicaine \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/08\/14\/contre-lignorance-volontaire-et-lobscurantisme-demystifier-les-religions-et-leurs-emprises-contre-nature\/\">Contre l\u2019ignorance volontaire et l\u2019obscurantisme D\u00e9mystifier les religions et leurs emprises contre nature<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/07\/15\/pour-celebrer-le-90e-anniversaire-du-front-populaire-et-temoigner-de-ses-apports\/\">Pour c\u00e9l\u00e9brer le 90\u00e8 anniversaire   du   Front populaire  et  t\u00e9moigner de ses apports<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/07\/07\/jean-zay-ministre-du-front-populaire\/\">Jean Zay, Ministre du Front populaire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/07\/07\/la-deuxieme-mort-du-professeur-samuel-paty\/\">La  deuxi\u00e8me mort du Professeur  Samuel Paty ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/30\/reecrire-lhistoire-dans-le-respect-des-emblemes-fixes-par-la-constitution-de-la-republique\/\">R\u00e9\u00e9crire l\u2019Histoire dans le respect   des  embl\u00e8mes  fix\u00e9s par la Constitution de la R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/28\/desacraliser-et-demystifier-les-oripeaux-religieux\/\">D\u00e9sacraliser et d\u00e9mystifier  les oripeaux religieux<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/28\/marc-bloch-la-pantheonisation-dun-homme-accompli\/\">Marc Bloch, la panth\u00e9onisation  d\u2019un  Homme accompli !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/23\/la-microhistoire\/\">La microhistoire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/22\/lecole-publique-en-danger-et-les-relations-ecole-familles\/\">L\u2019Ecole publique en danger et les relations Ecole-Familles.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/15\/quest-ce-que-la-verite-scientifique\/\">Qu\u2019est ce que la v\u00e9rit\u00e9 scientifique ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/15\/lecole-apprend-elle-encore-a-penser\/\">L\u2019Ecole apprend-elle encore \u00e0 penser ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/10\/petite-chronique-dapres-ciase-et-betharram-xi\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharram ( XI )<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/10\/le-club-des-dirigeants-de-leducation\/\">Le club des dirigeants de l\u2019Education<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/08\/quand-le-secret-de-la-confession-deborde-leglise\/\">Quand le secret de la confession d\u00e9borde l\u2019\u00c9glise<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/03\/a-propos-de-la-loi-post-betharram-examinee-recemment-a-lassemblee-nationale\/\">A propos de la Loi \u201cpost-B\u00e9tharram\u201d examin\u00e9e r\u00e9cemment \u00e0 l\u2019Assembl\u00e9e nationale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/03\/a-propos-de-lhistoire-longue-de-la-laicite\/\">A propos de l\u2018histoire longue de la la\u00efcit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/03\/linstauration-de-la-vie-republicaine\/\">L\u2019instauration de la vie r\u00e9publicaine<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/06\/03\/instituteurs-et-institutrices-en-resistance\/\">Instituteurs et  Institutrices  en  RESISTANCE<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/20\/la-revolte-de-fouesnant-1792\/\">La R\u00e9volte de\u00a0Fouesnant (1792)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/20\/comprendre-lantisemitisme-pour-defendre-luniversel\/\">Comprendre l\u2019antis\u00e9mitisme pour d\u00e9fendre l\u2019universel<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/20\/la-greve-des-papetiers-et-papetieres-de-cascadec\/\">La gr\u00e8ve des papetiers et papeti\u00e8res  de  Cascadec<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/09\/lorsque-le-journal-republicain-le-finistere\/\">Lorsque le journal  r\u00e9publicain  Le Finist\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/02\/petite-chronique-dapres-ciase-et-betharram-viii-2\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharram (VIII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/05\/01\/premier-mai-2026-jour-ferie-chome-et-paye\/\">Premier Mai 2026 Jour f\u00e9ri\u00e9, ch\u00f4m\u00e9 et pay\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/27\/chronique-electorale-bretonne-a-plomeur-dans-le-finistere-mars-1906\/\">Chronique  \u00e9lectorale bretonne  \u00e0 Plomeur dans le Finist\u00e8re (mars 1906)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/26\/lodyssee-de-la-capsule-spatiale-orion\/\">L\u2019odyss\u00e9e de la capsule spatiale ORION<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/09\/un-pamphlet-breton-republicain-de-1887-mis-en-lumiere\/\">Un pamphlet breton r\u00e9publicain de 1887 mis en lumi\u00e8re.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/01\/contre-la-tranquillite-de-lantisemitisme-appel-a-la-vigilance-republicaine\/\">Contre la tranquillit\u00e9 de l\u2019antis\u00e9mitisme : appel \u00e0 la vigilance r\u00e9publicaine !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/04\/01\/dame-de-fer-et-femmes-de-sciences-de-la-tour-eiffel-a-la-posterite\/\">Dame de fer et femmes de sciences : de la Tour Eiffel \u00e0 la post\u00e9rit\u00e9\u00a0!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/03\/28\/jospin-et-lecole-la-reforme-inachevee\/\">Jospin et\u00a0l\u2019Ecole :\u00a0la r\u00e9forme inachev\u00e9e et les Ecoles normales supprim\u00e9es.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/03\/25\/conduire-sa-raison-afin-de-resister-en-ces-temps-de-post-verite\/\">\u00ab\u00a0Conduire sa raison\u00a0\u00bb afin de r\u00e9sister en ces temps de \u00ab\u00a0post-v\u00e9rit\u00e9\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/03\/11\/petite-chronique-dapres-ciase-et-betharram-viii\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharram (VIII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/11\/petite-chronique-dapres-ciase-et-betharram-vii\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharram (VII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/11\/refuser-linterdit-un-deni-deducation\/\">Refuser l\u2019interdit : un d\u00e9ni d\u2019\u00e9ducation<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/06\/asvpnf-vie-associative\/\">ASVPNF : vie\u00a0 associative<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/06\/a-la-memoire-de-roselyne-degremont\/\">A la m\u00e9moire de Roselyne D\u00e9gremont.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/01\/pour-proteger-tous-les-eleves-et-les-enfants-en-milieux-scolaire-et-periscolaire\/\">Pour prot\u00e9ger tous les \u00e9l\u00e8ves et les enfants en milieux scolaire et p\u00e9riscolaire:<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/02\/01\/denoncer-lecriture-dite-inclusive\/\">D\u00e9noncer  l\u2019\u00c9criture  dite \u00ab inclusive \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/27\/les-effets-pervers-de-la-pauvrete-sur-les-trajectoires-scolaires\/\">Les effets pervers \u00a0de la pauvret\u00e9 sur les trajectoires scolaires<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/27\/addendum-a-la-charte-ecole-2027\/\">Addendum \u00e0 la Charte \u00c9COLE 2027<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/27\/pour-un-plan-de-sortie-du-financement-public-de-lenseignement-prive-sous-contrat\/\">Pour un plan de sortie du financement public de l\u2019enseignement priv\u00e9 sous contrat\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/14\/pour-une-refondation-republicaine-de-lecole-publique-a-lhorizon-2027\/\">Pour une refondation r\u00e9publicaine de l\u2019\u00c9cole publique \u00e0 l\u2019horizon 2027<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/07\/preparer-2027\/\">Pr\u00e9parer  2027<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2026\/01\/07\/la-realite-de-linteret-de-lecriture-inclusive\/\">La r\u00e9alit\u00e9 de l\u2019int\u00e9r\u00eat de l\u2019\u00e9criture inclusive<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/12\/31\/addendum-a-la-parution-de-larticle-dandre-le-goff-intitule-la-tante-aux-tableaux\/\">Addendum \u00e0 la parution de l\u2019article d\u2019Andr\u00e9 Le Goff intitul\u00e9 \u201cLa tante aux tableaux\u201d<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/12\/18\/loi-de-1905\/\">Loi de 1905<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/12\/17\/andre-le-goff-raconte-suite\/\">Andr\u00e9 Le Goff raconte  (suite):<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/12\/01\/apres-le-13-novembre\/\">Apr\u00e8s le 13 novembre\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/28\/lorsque-les-adeptes-du-secularisme\/\">Lorsque les adeptes du s\u00e9cularisme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/26\/lirruption-de-lintelligence-artificielle-2\/\">L\u2019irruption de l\u2019intelligence artificielle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/23\/liberte-et-oppression\/\">Libert\u00e9 et oppression<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/19\/petite-chronique\/\">Petite chronique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/09\/en-hommage-a-marguerite-bodin\/\">En hommage \u00e0 Marguerite  Bodin<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/08\/pour-une-nouvelle-laicite-appliquee-a-lintelligence-artificielle-ia\/\">Pour une \u00ab nouvelle la\u00efcit\u00e9 \u00bb appliqu\u00e9e \u00e0 l&rsquo;intelligence artificielle (IA)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/04\/aimer-lecole-publique-republicaine-gratuite-obligatoire-laique-et-liberee-des-contraintes-de-la-loi-debre\/\">Aimer l\u2019Ecole publique r\u00e9publicaine, gratuite, obligatoire,  la\u00efque  et  lib\u00e9r\u00e9e des contraintes de la loi Debr\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/11\/04\/une-mise-au-point-salutaire-a-mediter\/\">Une mise au point salutaire \u00e0 m\u00e9diter !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/19\/petite-chronique-dapres-ciase-et-betharram-1\/\">Petite chronique d\u2019apr\u00e8s Ciase et Betharram (1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/19\/protester-denoncer-condamner\/\">Protester, d\u00e9noncer, condamner<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/19\/hommage-de-lasvpnf\/\">Hommage de l\u2019ASVPNF<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/12\/les-80-ans-de-la-securite-sociale\/\">Les 80 ans de la SECURITE SOCIALE<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/12\/addendum-robert-badinter-au-pantheon\/\">Addendum :      Robert Badinter au Panth\u00e9on<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/08\/robert-badinter-au-pantheon\/\">Robert BADINTER\u00a0 au PANTHEON<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/08\/la-republique-laique-et-les-cultes\/\">La R\u00e9publique la\u00efque et les cultes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/04\/fermeture-de-linspe-de-vannes-au-profit-de-luniversite-catholique-de-louest\/\">Fermeture de l\u2019INSPE de Vannes au profit de l\u2019Universit\u00e9 Catholique de l\u2019Ouest<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/10\/02\/a-la-veille-du-120e-anniversaire-de-la-loi-de-1905\/\">A la veille du 120\u00e8 anniversaire de la loi\u00a0 de\u00a0 1905<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/27\/le-sgec-et-lenseignement-catholique-sous-contrat\/\">Le SGEC et l&rsquo;enseignement catholique sous contrat<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/22\/la-laicite-de-combat-ne-peut-etre-ni-discriminatoire-ni-liberticide\/\">La la\u00efcit\u00e9 de combat ne peut \u00eatre  ni  discriminatoire ni  liberticide:<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/17\/lirruption-de-lintelligence-artificielle\/\">L\u2019irruption de l\u2019intelligence  artificielle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/16\/se-souvenir-afin-de-mieux-combattre\/\">Se souvenir afin de mieux combattre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/05\/enseignement-et-mathematiques\/\">Enseignement et math\u00e9matiques<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/09\/05\/quest-il-arrive-a-la-laicite\/\">Qu&rsquo;est-il arriv\u00e9 \u00e0 la la\u00efcit\u00e9 ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/07\/30\/contre-la-volonte-de-ne-pas-savoir-demystifier-lacetamipride-et-sa-biotoxicite\/\">Contre la volont\u00e9 de ne pas savoir  D\u00e9mystifier l\u2019ac\u00e9tamipride et  sa biotoxicit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/07\/06\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales-6\/\">Turpitudes et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/07\/04\/charles-peguy\/\">CHARLES P\u00c9GUY\u00a0; L\u2019Ecole r\u00e9publicaine et la la\u00efcit\u00e9, un silence \u00e9clairant<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/07\/02\/penser-contre-son-camp\/\">Penser contre son camp\u00a0!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/07\/02\/la-disparition-du-professeur-guy-desbiens\/\">La disparition du Professeur Guy DESBIENS<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/06\/10\/a-propos-de-la-mise-en-berne-du-drapeau-national-sur-les-batiments-publics-pour-les-obseques-du-pape-francois\/\">A propos de la mise  en berne du drapeau national sur les b\u00e2timents publics  pour les obs\u00e8ques du pape Fran\u00e7ois.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/06\/04\/a-propos-du-respect-de-laicite-dans-le-sport\/\">A propos du respect de la\u00efcit\u00e9 dans le sport<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/06\/04\/lecole-francaise-un-systeme-formate-pour-les-gagnants-davance\/\">L\u2019\u00e9cole fran\u00e7aise : un syst\u00e8me format\u00e9 pour les gagnants d\u2019avance<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/06\/02\/le-gag-contreproductif-du-modele-de-lecole-belge-privatisee\/\">Le gag contreproductif du mod\u00e8le  de  l\u2019Ecole  belge privatis\u00e9e<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/05\/07\/jean-michel-muglioni-est-mort\/\">Jean-Michel Muglioni est mort<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/05\/07\/le-droit-de-vote-des-femmes-en-france\/\">Le droit de vote des femmes en France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/27\/temoigner-de-la-durabilite-de-la-complicite-et-de-lhumour-normaliens\/\">T\u00e9moigner de la durabilit\u00e9 de la complicit\u00e9 et de l\u2019humour normaliens<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/23\/lecole-laique-sanctuaire-de-respiration-demancipation-et-dapprentissage-de-la-republique-des-savoirs\/\">L&rsquo;Ecole la\u00efque ; sanctuaire de respiration, d&rsquo;\u00e9mancipation et d&rsquo;apprentissage de la R\u00e9publique\u00a0 des savoirs.\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/04\/03\/controle-des-etablissements-prives-les-services-du-ministere-de-leducation-nationale-auditionnes-par-la-commission-denquete-parlementaire\/\">Contr\u00f4le des \u00e9tablissements priv\u00e9s   les services du minist\u00e8re de l&rsquo;Education nationale   auditionn\u00e9s par  la commission d&rsquo;enqu\u00eate parlementaire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/30\/intelligence-humaine-et-intelligence-artificielle\/\">Intelligence Humaine  et  Intelligence Artificielle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/16\/lelephant-au-caractere-propre-introduit-subrepticement-dans-la-loi-en-1959-est-toujours-dans-la-place\/\">L\u2019\u00e9l\u00e9phant au caract\u00e8re propre  introduit subrepticement dans la Loi en 1959  est toujours dans la place.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/12\/turpitudes-a-betharram-des-realites-inqualifiables\/\">Turpitudes \u00e0\u00a0\u00a0Betharram\u00a0; des \u00ab\u00a0r\u00e9alit\u00e9s inqualifiables\u00a0\u00bb\u00a0!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/10\/contre-les-atteintes-a-la-recherche-scientifique-et-aux-libertes-academiques\/\">Contre les atteintes \u00e0 la recherche scientifique et aux libert\u00e9s acad\u00e9miques<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/03\/02\/quand-deux-anciennes-eleves-maitresses-des-ecoles-normales-de-quimper-rendent-hommage\/\">Quand deux anciennes \u00e9l\u00e8ves-ma\u00eetresses des Ecoles normales de Quimper  rendent hommage<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/02\/12\/lurgence-de-transmettre-des-contresens\/\">L\u2019urgence de transmettre\u2026 des contresens\u00a0?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/02\/05\/des-paroles-de-reference-sur-la-laicite\/\">Des paroles de r\u00e9f\u00e9rence sur la LA\u00cfCITE .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/23\/turbulences-et-agitations-diverses-autour-de-la-laicitefondement-de-notre-republique\/\">Turbulences et agitations diverses autour de la la\u00efcit\u00e9,fondement de notre R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/19\/propos-dapres-inauguration\/\">Propos d&rsquo;apr\u00e8s inauguration<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/18\/une-inauguration-decole-publique-laique-2\/\">Une inauguration d\u2019\u00e9cole publique la\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/16\/une-inauguration-decole-publique-laique\/\">Une inauguration d\u2019\u00e9cole publique la\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/12\/un-centenaire-oublie\/\">Un centenaire oubli\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/09\/lonu-contre-la-neutralite-du-sportet-la-laicite-en-france\/\">L\u2019ONU contre la neutralit\u00e9 du sport\u2026et la la\u00efcit\u00e9 en France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/04\/petite-chronique-de-lengagement-laique-au-quotidien\/\">Petite chronique de l\u2019engagement la\u00efque au quotidien<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2025\/01\/03\/sonnez-binious-et-bombardes\/\">Sonnez  binious et bombardes !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/30\/requiem-pour-lecole-libre\/\">Requiem pour l\u2019Ecole \u00ab libre \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/10\/pour-la-journee-nationale-de-la-laicite-du-9-decembre-2024\/\">Pour la journ\u00e9e nationale de la la\u00efcit\u00e9  du  9 d\u00e9cembre 2024<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/04\/heretiques\/\">\u00ab\u00a0H\u00e9r\u00e9tiques\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/12\/01\/face-a-un-pouvoir-bien-peu-legitime-lecole-doit-resister\/\">Face \u00e0 un pouvoir bien peu l\u00e9gitime l\u2019Ecole doit r\u00e9sister<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/11\/27\/ne-pas-se-resigner-a-penser-que\/\">Ne pas se r\u00e9signer \u00e0 penser que<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/11\/24\/une-vraie-fausse-bonne-nouvelle\/\">Une vraie fausse bonne nouvelle :<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/11\/17\/pour-ne-pas-mourir-denseigner-ii\/\">Pour ne pas mourir d\u2019enseigner (II)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/10\/13\/lenseignement-public-gratuit-et-laique-a-tous-les-degres-est-un-devoir-de-letat\/\">\u00ab L\u2019enseignement public, gratuit et la\u00efque \u00e0 tous les degr\u00e9s  est un devoir de l\u2019Etat. \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/10\/09\/petite-selection-dexpressos-du-cafe-pedagogique-i\/\">Petite s\u00e9lection d\u2019expressos du Caf\u00e9 p\u00e9dagogique (I)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/19\/liberte-dexpression-croyances-et-ideologies\/\">Libert\u00e9 d\u2019expression, croyances et id\u00e9ologies<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/09\/16\/un-triste-anniversaire-oublie-ecole-privee-lautre-grand-tournant-liberal-de-la-gauche\/\">Un triste anniversaire oubli\u00e9 !  \u00ab Ecole priv\u00e9e: l\u2019autre grand tournant \u00ab lib\u00e9ral \u00bb de la gauche \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/08\/23\/les-desillusions-de-la-democratie\/\">Les d\u00e9sillusions de la d\u00e9mocratie<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/08\/18\/un-grand-chantier-republicain-sur-un-champ-de-ruines\/\">\u00ab Un grand chantier r\u00e9publicain sur un champ de ruines ! \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/03\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xviii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XVIII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/07\/02\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xiv\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XIV)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/26\/contre-la-montee-de-lantisemitisme-en-france\/\">Contre la \u201cmont\u00e9e\u201d de l\u2019antis\u00e9mitisme en France<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/26\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xiii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XIII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/26\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/26\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-xi\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (XI)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/23\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-ix\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (IX)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/21\/chronique-devenements-inities-par-le-seisme-politique-du-9-juin-2024-vii\/\">Chronique d\u2019\u00e9v\u00e8nements initi\u00e9s par le \u00ab s\u00e9isme \u00bb politique du 9 juin 2024 (VII)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/20\/la-maternelle-sous-le-choc-des-savoirs\/\">La maternelle sous \u00ab le choc des savoirs \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/07\/turpitudes-et-contre-turpitudes-clericales-et-ecclesiales\/\">Turpitudes et contre-turpitudes cl\u00e9ricales et eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/03\/quand-il-aura-vingt-ans-a-ceux-qui-eteignent-les-lumieres-de-chloe-morin\/\">\u00ab Quand il aura vingt ans : \u00c0 ceux qui \u00e9teignent les Lumi\u00e8res \u00bb de Chlo\u00e9 Morin.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/06\/03\/lorsque-les-davidees-et-leurs-emules-du-21e-siecle-ouvrent-les-portes-de-lecole-publique-laique-aux-ministres-des-cultes\/\">Lorsque les David\u00e9es et leurs \u00e9mules du 21\u00e8 si\u00e8cle ouvrent les portes de l\u2019\u00e9cole publique la\u00efque aux \u00ab ministres des cultes \u00bb.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/05\/24\/liberte-de-pensee-de-conscience-et-de-religion-en-pays-de-laicite-republicaine\/\">Libert\u00e9 de pens\u00e9e, de conscience et de religion  en pays de la\u00efcit\u00e9  r\u00e9publicaine<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/05\/11\/petite-chronique-nostalgique-dun-retour-vers-le-futur-anterieur-des-ecoles-normales-ii\/\">Petite chronique nostalgique  d\u2019un retour  vers le futur ant\u00e9rieur des \u00e9coles normales (II)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/05\/11\/petite-chronique-nostalgique-dun-retour-vers-le-futur-anterieur-des-ecoles-normales-i\/\">Petite chronique nostalgique  d\u2019un retour  vers le futur ant\u00e9rieur des \u00e9coles normales (I)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/03\/31\/turpitudes-clericales-et-contre-turpitudes-ecclesiales\/\">Turpitudes cl\u00e9ricales et contre-turpitudes eccl\u00e9siales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/03\/29\/a-propos-de-la-loi-du-15-mars-2004-et-de-son-20e-anniversaire\/\">A propos de la Loi du 15 mars 2004 et de son 20\u00e8 anniversaire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/03\/26\/la-grande-marie-figure-emblematique-de-lemancipation-feminine\/\">\u00ab La Grande Marie \u00bb ,figure  embl\u00e9matique de l\u2019\u00e9mancipation f\u00e9minine.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/03\/21\/lecole-et-la-sociologie-sociologisante\/\">L\u2019\u00e9cole et la sociologie sociologisante<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/03\/08\/mayotte-et-le-droit-du-sol\/\">MAYOTTE et le droit du sol<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/02\/14\/assez-de-faux-semblants-reinstituons-lecole-publique-laique-en-lui-accordant-les-moyens-necessaires\/\">Assez de faux-semblants  R\u00e9instituons l\u2019Ecole publique la\u00efque en lui accordant  les moyens n\u00e9cessaires<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/02\/03\/luniforme-a-lecole-publique\/\">L\u2019uniforme  \u00e0 l\u2019Ecole  publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/01\/22\/immigration-et-integration\/\">Immigration et int\u00e9gration<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/01\/14\/les-tresors-caches-du-dictionnaire-francois\/\">Les tr\u00e9sors cach\u00e9s du dictionnaire FRANCOIS<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/01\/06\/andre-le-goff-raconte-2\/\">Andr\u00e9 Le Goff raconte<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2024\/01\/03\/le-port-de-luniforme-a-lecole-publique\/\">Le port de l\u2019uniforme \u00e0 l\u2019Ecole publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/12\/22\/definir-et-expliquer-la-laicite-une-gageure\/\">D\u00e9finir et expliquer la la\u00efcit\u00e9 , une gageure !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/12\/19\/hanouka-a-lelysee-ou-comment-e-macronpresident-de-la-republique-a-allume-une-polemique-sur-la-laicite\/\">Hanouka \u00e0 l\u2019\u00c9lys\u00e9e ou Comment E. Macron,Pr\u00e9sident de la R\u00e9publique,  a allum\u00e9 une pol\u00e9mique sur la la\u00efcit\u00e9 ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/12\/19\/quest-ce-que-vraiment-la-laicite\/\">Qu\u2019est-ce que (vraiment) la la\u00efcit\u00e9 ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/11\/13\/honneur-et-gloire-a-lecole-laique\/\">Honneur et Gloire  \u00e0  l\u2019Ecole La\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/11\/08\/le-racisme-systemique\/\">Le racisme syst\u00e9mique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/11\/05\/elements-de-chronique-explicative-non-justificative-dune-actualite-dramatique-et-anxiogene\/\">El\u00e9ments de chronique explicative non justificative  .d\u2019une actualit\u00e9 dramatique et anxiog\u00e8ne<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/30\/le-choc-des-images-et-des-maux-face-au-poids-des-mots\/\">Le choc des images et des maux face au poids des mots<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/30\/lecole-cette-zone-de-guerre\/\">L&rsquo;ECOLE , \u00ab\u00a0CETTE ZONE DE GUERRE \u00ab\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/19\/les-bons-sentiments-et-les-saintes-nitouches-armees-dun-coutelas\/\">Les bons sentiments et les saintes-nitouches arm\u00e9es d\u2019un coutelas.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/18\/lappel-solennel-a-un-sursaut-collectif-de-mickaelle-paty\/\">L\u2019appel solennel \u00e0 un sursaut collectif  de  Micka\u00eblle  Paty<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/15\/violences-et-harcelement-a-lecole-y-compris-le-cyber-harcelement\/\">Violences et harc\u00e8lement \u00e0 l\u2019Ecole   y compris le cyber-harc\u00e8lement<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/10\/01\/elements-dun-bilan-de-rentree-scolaire-2023\/\">El\u00e9ments d\u2019un bilan de rentr\u00e9e scolaire 2023<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/25\/et-si-on-reinventait-les-ecoles-normales\/\">Et si on r\u00e9inventait les Ecoles normales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/14\/professeurs-et-defenseurs-de-la-laicite-de-lecole-ne-capitulons-pas\/\">Professeurs et d\u00e9fenseurs de la la\u00efcit\u00e9 de l&rsquo;Ecole  Ne capitulons pas !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/09\/01\/a-bas-labayaabracadabra\/\">A bas l\u2019abaya,abracadabra !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/24\/protocole-entre-letat-et-lenseignement-catholique-la-republique-joue-contre-son-camp\/\">Protocole entre l\u2019\u00c9tat et l\u2019enseignement catholique  la R\u00e9publique joue contre son camp  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/23\/pour-un-universalisme-laique-et-republicain-en-rempart-contre-le-communautarisme-confessionnel-religieux-et-neo-liberal\/\">Pour un universalisme la\u00efque et r\u00e9publicain en rempart contre  le communautarisme  confessionnel  religieux et n\u00e9o-lib\u00e9ral<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/22\/au-sujet-du-chene-vert-de-mandelieu-la-napoule-f-06210-ou-lespace-public-nest-pas-un-service-public\/\">Au  sujet  du ch\u00eane vert de Mandelieu-la-Napoule (F-06210)  ou     L\u2019espace public n\u2019est pas un service public !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/20\/les-cours-normaux\/\">Les cours normaux<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/08\/17\/la-lente-agonie-de-lexpression-ecrite-francaise\/\">La lente agonie  de  l\u2019expression \u00e9crite fran\u00e7aise&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/07\/15\/pour-une-refonte-complete-de-lannee-de-terminale-comportant-trois-trimestres-effectifs-denseignement\/\">Pour une refonte compl\u00e8te de l\u2019ann\u00e9e   de terminale comportant trois trimestres effectifs d\u2019enseignement.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/06\/28\/a-propos-de-la-dissolution-du-collectif-les-soulevements-de-la-terre\/\">A propos de la dissolution du collectif                 \u00ab\u00a0Les Soul\u00e8vements de la Terre\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/06\/28\/au-sujet-du-college\/\">Au sujet du Coll\u00e8ge<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/06\/18\/laicite-ou-en-est-on\/\">La\u00efcit\u00e9 : o\u00f9 en est-on ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/06\/01\/a-propos-de-la-mise-en-ligne-des-archives-du-professeur-de-philosophie-jacques-muglioni\/\">A propos de la mise en ligne des archives du Professeur de Philosophie  Jacques Muglioni<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/04\/11\/deconstruire-la-deconstruction-ou-reconstruire-apres-la-demolition\/\">D\u00e9construire la d\u00e9construction  ou reconstruire apr\u00e8s la d\u00e9molition<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/04\/02\/lecole-et-la-deconstruction-decomplexee-de-tout-ce-que-fut-lhonneur-de-la-republique\/\">L\u2019Ecole et la d\u00e9construction d\u00e9complex\u00e9e de tout ce que fut l\u2019honneur de la R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/03\/01\/petite-chronique-finisterienne-de-la-laicisation-aux-debuts-de-la-3e-republique\/\">Petite chronique finist\u00e9rienne de la la\u00efcisation  aux d\u00e9buts de la 3\u00e8 R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/26\/turpitudes-et-contre-turpitudes-ecclesiales-ou-clericales\/\">Turpitudes et contre-turpitudes  eccl\u00e9siales ou cl\u00e9ricales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/19\/sur-les-atteintes-a-la-laicite-a-lecole\/\">Sur les atteintes \u00e0 la la\u00efcit\u00e9 \u00e0 l\u2019Ecole<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/12\/quelle-bonne-ecole-reconstruire-pour-le-21e-siecle\/\">Quelle bonne Ecole  reconstruire pour le 21\u00e8 si\u00e8cle?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/12\/deconstruire-dit-elle-selon-andre-perrin-mezetulle-2-fevrier-2023\/\">D\u00e9construire dit-elle\u2026     (selon Andr\u00e9 Perrin, Mezetulle, 2 f\u00e9vrier 2023)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/12\/lecriture-est-lisible-ou-illisible-voire-hieroglyphique-et-souvent-fautive-elle-ne-peut-etre-inclusive\/\">L\u2019\u00e9criture est lisible ou illisible voire hi\u00e9roglyphique et souvent   fautive&#8230;elle ne peut-\u00eatre inclusive !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/02\/07\/la-controverse-autour-de-loeuvre-de-condorcet-le-dernier-philosophe-des-lumieres\/\">La controverse autour de l\u2019oeuvre de Condorcet ,le dernier philosophe des Lumi\u00e8res<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/01\/18\/la-loi-dite-separatisme-du-24-aout-2021-et-ses-atteintes-aux-libertes-associatives\/\">La loi dite \u201cs\u00e9paratisme\u201d du  24 ao\u00fbt 2021  et ses  atteintes  aux  libert\u00e9s associatives (?)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/01\/18\/notre-ecole-a-la-ramasse\/\">Notre Ecole \u00e0 la ramasse.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2023\/01\/08\/chronique-des-tribulations-et-turpitudes-clericales-des-debuts-de-2023-a-suivre\/\">Chronique des tribulations et turpitudes cl\u00e9ricales des d\u00e9buts de 2023 (\u00e0 suivre )<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/30\/pratique-de-la-laicite-en-entreprise-privee\/\">Pratique de la la\u00efcit\u00e9 en  entreprise priv\u00e9e<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/26\/laicite-et-anticlericalisme\/\">La\u00efcit\u00e9 et anticl\u00e9ricalisme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/23\/lecole-de-notre-siecle-et-lesprit-civique\/\">L\u2019Ecole de notre si\u00e8cle et l\u2019esprit civique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/18\/des-lecons-fondatrices-sur-la-laicite-republicaine-aux-realites-des-institutions-publiques-et-des-collectivites-territoriales\/\">Des le\u00e7ons fondatrices sur  la la\u00efcit\u00e9 r\u00e9publicaine  aux  r\u00e9alit\u00e9s  des institutions publiques et des collectivit\u00e9s territoriales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/18\/halte-la-a-lecole-numerique\/\">Halte-l\u00e0  \u00e0 l\u2019\u00e9cole num\u00e9rique\u00a0!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/12\/15\/la-defense-sans-concession-des-libertes-publiques-republicaines-dans-un-etat-de-droit\/\">La d\u00e9fense sans concession des libert\u00e9s publiques r\u00e9publicaines dans un \u00e9tat de droit<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/27\/manifeste-progressiste-pour-la-defense-de-la-langue-francaise-in-dossier-parlons-francais-ufal-info-2022-avril-mai-juin-n-8911-13\/\">Manifeste progressiste pour la d\u00e9fense de la  langue fran\u00e7aise.    In  Dossier-Parlons fran\u00e7ais\u00a0!  Ufal INFO\u00a0;2022 , Avril-Mai-Juin n\u00b0 89,11-13<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/25\/parlons-francais-que-reste-t-il-de-la-langue-francaise\/\">Parlons Fran\u00e7ais !  Que reste-t-il de la langue Fran\u00e7aise\u00a0?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/23\/quel-est-ce-mystere-feignons-de-ny-etre-pour-rien\/\">Quel est ce myst\u00e8re ?  Feignons de n\u2019y \u00eatre pour rien\u2026<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/17\/parlons-francais\/\">Parlons fran\u00e7ais<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/15\/la-laicite-dans-tous-ses-etats-commentaire-de-lemission-repliques-du-12-novembre-22-par-andre-perrin\/\">La la\u00efcit\u00e9 dans tous ses \u00e9tats  Commentaire de l\u2019\u00e9mission \u00ab R\u00e9pliques \u00bb du 12 novembre 22  par   Andr\u00e9 PERRIN<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/06\/les-mefaits-de-la-pedophilie-ecclesiale-et-du-clericalisme\/\">Les m\u00e9faits de la p\u00e9dophilie eccl\u00e9siale et du  cl\u00e9ricalisme.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/03\/transcendantale-la-laicite-est-ou-nest-pas\/\">Transcendantale, la la\u00efcit\u00e9 est ou n\u2019est pas !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/11\/03\/constitutionnaliser-la-laicite\/\">Constitutionnaliser la la\u00efcit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/11\/turpitudes-clericales-suite-et-miscellanees-ecclesiales-de-lautomne-2022\/\">Turpitudes  cl\u00e9ricales (suite)  et miscellan\u00e9es eccl\u00e9siales  de l\u2019automne 2022.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/04\/pour-sauvegarder-notre-ecole-republicaine-refonder-et-non-reformer\/\">Pour sauvegarder notre Ecole R\u00e9publicaine : Refonder et non R\u00e9former<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/10\/02\/condorcet-linstruction-publique-et-la-naissance-du-citoyen\/\">Condorcet, l\u2019instruction publique et la naissance du citoyen,<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/30\/refonder-lecole-de-la-republique\/\">Refonder  l\u2019Ecole de la R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/28\/la-religion-de-la-laicite-il-faut-cesser-de-croire-que-la-laicite-garantit-legalite-des-sexes\/\">La religion de la la\u00efcit\u00e9   Il faut cesser de croire que la la\u00efcit\u00e9 garantit  l\u2019\u00e9galit\u00e9 des sexes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/09\/21\/agir-et-lutter-pour-la-sauvegarde-de-lecole-institution-publique-gratuite-obligatoire-et-laique\/\">Agir et lutter  pour la sauvegarde de l&rsquo;Ecole ;  institution publique, gratuite, obligatoire et la\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/08\/29\/petite-chronique-des-temps-heureux-ou-le-finistere-construisait-son-ecole-publique-laique-et-republicaine\/\">Petite chronique des temps heureux  o\u00f9 le Finist\u00e8re  construisait son  Ecole publique, la\u00efque et r\u00e9publicaine<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/08\/12\/la-dictee-de-plovan-en-aout-2022\/\">La dict\u00e9e de PLOVAN en ao\u00fbt 2022<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/07\/20\/pourquoi-la-gauche-francaise-est-elle-a-la-derive\/\">Pourquoi la  Gauche fran\u00e7aise  est-elle  \u00e0 la d\u00e9rive ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/07\/11\/resurrection-du-trio-infernal-trone-autel-et-sabre-ou-russie-ukraine-la-religion-dans-la-guerre\/\">R\u00e9surrection du trio infernal   tr\u00f4ne, autel et sabre  ou  RUSSIE-UKRAINE  : la religion dans la guerre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/06\/02\/les-dossiers-dufal-info-2-un-quinquennat-perdu-pour-la-laicite\/\">Les Dossiers d&rsquo;Ufal INFO   (2)     \u00ab\u00a0Un quinquennat perdu pour la la\u00efcit\u00e9 \u00ab\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/31\/apres-la-publication-de-louvrage-de-roland-pfefferkorn\/\">Apr\u00e8s la publication de l&rsquo;ouvrage de  Roland Pfefferkorn :<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/31\/le-catholicisme-francais-au-risque-de-limplosion\/\">Le catholicisme fran\u00e7ais au risque de l\u2019implosion\u2026<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/22\/pour-des-chartes-de-la-laicite-bien-ordonnees-eviter-les-usines-a-gaz\/\">Pour des chartes de la la\u00efcit\u00e9 bien ordonn\u00e9es   Eviter les \u00ab\u00a0usines \u00e0 gaz\u00a0\u00bb!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/18\/les-dossiers-dufal-info-1\/\">Les Dossiers d&rsquo;Ufal INFO   (1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/15\/perils-sectaires-en-2022-ou-les-lumieres-a-lere-numerique\/\">P\u00e9rils sectaires en 2022 ou   \u00ab Les lumi\u00e8res \u00e0 l\u2019\u00e8re num\u00e9rique \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/05\/11\/ecoles-privees-sans-contrat-et-deni-des-lois-de-la-republique-en-2022\/\">Ecoles priv\u00e9es  sans contrat  et   d\u00e9ni des lois de la R\u00e9publique en 2022<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/27\/un-paradoxe-le-progres-des-sciences-ruine-lecole\/\">Un paradoxe:  Le progr\u00e8s des Sciences ruine l&rsquo;Ecole<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/27\/lendemains-du-centcinquantenaire-de-la-commune-de-paris-et-laicite\/\">Lendemains du centcinquantenaire  de la Commune de Paris  et la\u00efcit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/24\/le-retour-du-tragique\/\">Le retour du tragique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/24\/revirements-et-contorsions-chez-les-clericaux-de-tous-les-pays\/\">Revirements et contorsions  chez les cl\u00e9ricaux  de tous les pays<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/19\/la-fin-des-congregations-religieuses-catholiques-une-aubaine-pour-les-victimes-des-abus-sexuels-commis-au-sein-de-leglise\/\">La fin des congr\u00e9gations religieuses catholiques :  une aubaine pour les victimes   des abus sexuels commis au sein de l&rsquo;Eglise ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/16\/2022-ecole-publique-a-lagonie-identifier-les-causes-de-sa-destruction-et-bien-la-reconstruire\/\">2022, Ecole publique  \u00e0 l&rsquo;agonie  Identifier les causes de sa destruction  et bien la reconstruire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/16\/pas-degalite-en-droit-sans-laicite\/\">Pas d&rsquo;\u00e9galit\u00e9 en droit sans la\u00efcit\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/04\/05\/lecole-de-la-republique-a-lepreuve-de-locde-et-de-la-commission-europeenne\/\">L\u2019Ecole de la R\u00e9publique \u00e0 l\u2019\u00e9preuve de l\u2019OCDE  et  de la Commission europ\u00e9enne<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/30\/tribulations-clericales-dans-le-prolongement-du-rapport-de-la-ciase-presidee-par-jean-marc-sauve\/\">Tribulations cl\u00e9ricales  dans le  prolongement du rapport de la Ciase  pr\u00e9sid\u00e9e par Jean-Marc Sauv\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/30\/les-enfants-martyrs-de-riaumont-enquete-sur-un-pensionnat-integriste-un-nouveau-scandale-de-la-pedocriminalite-clericale\/\">\u201cLes enfants martyrs de Riaumont  Enqu\u00eate  sur un pensionnat int\u00e9griste\u201d  Un nouveau scandale de la p\u00e9docriminalit\u00e9 cl\u00e9ricale !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/30\/la-question-de-la-laicite-dans-les-programmes-des-candidats-a-lelection-presidentielle-2022-permanence-du-clivage-droite-gauche\/\">La question de la la\u00efcit\u00e9 dans les programmes  des  candidats \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle 2022   \u00ab\u00a0Permanence du clivage  droite\/gauche\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/13\/a-la-guerre-spectacle-04-08-mars-2022-la-revelation-de-la-logique-de-labsurde-en-matiere-de-relations-internationales\/\">A la   guerre spectacle , 04-08 mars 2022 :  la r\u00e9v\u00e9lation de la logique de l&rsquo;absurde  en mati\u00e8re de relations internationales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/12\/le-poutine-de-2022-estlargementnotre-creation\/\">Le Poutine de 2022 est(largement)notre cr\u00e9ation !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/10\/8-mars-2022-journee-internationale-des-droits-des-femmes\/\">8 mars 2022  : journ\u00e9e internationale   des   droits des femmes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/08\/le-poutinisme-francais\/\">\u00a0\u00bb Le poutinisme fran\u00e7ais \u00ab\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/03\/08\/les-menees-obscurantistes-contre-la-science-les-savoirs-et-la-raison-nont-pas-leur-place-a-lecole-laique-de-la-republique\/\">Les men\u00e9es obscurantistes  contre la Science, les Savoirs et la Raison  n&rsquo;ont pas leur place \u00e0 l&rsquo;Ecole la\u00efque   de la R\u00e9publique.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/02\/15\/le-pretendu-principe-dincompletude-ne-peut-justifier-le-retour-des-professeurs-de-religion-a-lecole-publique-laique-et-republicaine\/\">Le pr\u00e9tendu \u00ab principe d\u2019incompl\u00e9tude \u00bb ne peut justifier  le retour des professeurs de religion  \u00e0 l\u2019\u00e9cole publique la\u00efque et r\u00e9publicaine<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/02\/14\/message-aux-nostalgiques-du-tableau-noir-de-la-3e-republique\/\">Message aux nostalgiques  du  tableau noir de la 3\u00e8 R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/02\/14\/lenseignement-moral-et-civique-a-lecole-laique-et-au-college-public\/\">L&rsquo;enseignement moral et civique  \u00e0  l&rsquo;Ecole la\u00efque et au Coll\u00e8ge public<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/02\/14\/a-la-suite-du-colloque-apres-la-deconstruction-reconstruire-les-sciences-et-la-culture\/\">\u00c0 la suite du colloque  \u00ab Apr\u00e8s la d\u00e9construction, reconstruire  les sciences et la culture \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/15\/la-presse-finisterienne-aux-debuts-de-la-iiie-republique-naissance-de-nouvelles-feuilles-republicaines-2\/\">La presse finist\u00e9rienne  aux d\u00e9buts de la III\u00e8 R\u00e9publique           Naissance de nouvelles feuilles r\u00e9publicaines (2)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/13\/une-orthographe-fautive-permet-elle-de-bien-nommer-les-choses\/\">Une orthographe fautive permet-elle  de  bien nommer les choses ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/13\/la-presse-finisterienne-aux-debuts-de-la-iiie-republique-naissance-de-nouvelles-feuilles-republicaines-1\/\">La presse finist\u00e9rienne  aux d\u00e9buts de la III\u00e8 R\u00e9publique                Naissance de nouvelles feuilles r\u00e9publicaines (1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/09\/les-fonds-recoltes-par-leglise-catholique-en-spoliant-les-moniales-serviront-ils-a-indemniser-les-victimes-de-pedophilie\/\">Les fonds r\u00e9colt\u00e9s par l&rsquo;Eglise catholique  en spoliant les moniales  serviront-ils \u00e0  indemniser les victimes de p\u00e9dophilie?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2022\/01\/09\/jai-execute-un-chien-de-lenfer-rapport-sur-lassassinat-de-samuel-paty\/\">\u00ab J\u2019ai ex\u00e9cut\u00e9 un chien de l\u2019enfer. Rapport sur l\u2019assassinat de Samuel Paty \u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/12\/23\/tsunami-dans-leglise-le-rapport-sauve\/\">\u00a0\u00bb Tsunami dans l&rsquo;Eglise : le rapport Sauv\u00e9\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/12\/20\/chronique-hivernale-des-turpitudes-ecclesiales-recentes-a-suivre\/\">Chronique hivernale  des turpitudes eccl\u00e9siales r\u00e9centes  (\u00e0 suivre !)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/12\/20\/lendemains-de-la-journee-de-la-laicite-du-9-decembre-2021\/\">Lendemains  de la Journ\u00e9e de la La\u00efcit\u00e9 du 9 d\u00e9cembre 2021<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/23\/eglise-sonner-le-tocsin-plutot-que-le-glas\/\">Eglise : sonner le tocsin plut\u00f4t que le glas  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/23\/la-commune-de-paris-1871-et-la-liberte-de-la-presse\/\">La Commune de Paris 1871 et la libert\u00e9 de la presse<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/19\/au-coeur-des-grandes-turbulences-de-leglise-catholique-et-du-sens-du-message-christique\/\">Au coeur des grandes turbulences de l&rsquo;\u00e9glise catholique  et du  sens du message christique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/15\/nouvelle-activite-culturelle-au-comite-tregor-argoat-des-amies-et-amis-de-la-commune-de-paris-1871\/\">Nouvelle activit\u00e9 culturelle  au Comit\u00e9 Tr\u00e9gor-Argoat des Amies et Amis de la Commune de Paris 1871<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/13\/apres-le-rapport-sauvee-et-la-conference-episcopale-de-lourdes-continuer-a-pourfendre-le-clericalisme-et-la-toute-puissance-des-pretres\/\">Apr\u00e8s le rapport SAUVEE et la conf\u00e9rence \u00e9piscopale de Lourdes                 Continuer \u00e0 pourfendre le cl\u00e9ricalisme et la toute-puissance des pr\u00eatres<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/05\/abus-et-clericalisme\/\">Abus  et cl\u00e9ricalisme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/05\/maitriser-notre-langue-nationale\/\">Ma\u00eetriser notre langue nationale !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/11\/04\/de-nouvelles-activites-au-comite-tregor-argoat-des-amies-et-amis-de-la-commune-de-paris-1871\/\">De nouvelles activit\u00e9s au Comit\u00e9 Tr\u00e9gor-Argoat  des  Amies et Amis de la Commune de Paris 1871<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/20\/un-an-apres-la-mort-de-samuel-paty-ne-pas-renoncer\/\">Un an apr\u00e8s la mort de Samuel Paty :   Ne pas renoncer !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/18\/la-pedocriminalite-dans-leglise-catholique-un-probleme-de-laicite\/\">La p\u00e9docriminalit\u00e9 dans l\u2019Eglise catholique :  un probl\u00e8me de la\u00efcit\u00e9 ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/18\/peut-on-decrire-et-soigner-des-maux-de-notre-societe-au-moyen-de-mots-ou-expressions-dapparence-inepte\/\">Peut-on d\u00e9crire et soigner des maux de notre soci\u00e9t\u00e9  au moyen de mots ou expressions d&rsquo;apparence inepte ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/10\/05\/le-rapport-sauve-sur-les-abus-sexuels-sur-mineurs-commis-dans-leglise-catholique-5-octobre-2021\/\">Le rapport Sauv\u00e9 sur les abus sexuels sur mineurs  commis  dans l\u2019Eglise catholique  (5 octobre 2021)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/30\/natacha-polony-et-la-falsification-de-lhistoire\/\">Natacha Polony et la falsification de l\u2019Histoire<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/29\/clericalisme-a-la-manoeuvre-quand-les-laics-se-rebiffent\/\">Cl\u00e9ricalisme \u00e0 la manoeuvre :  quand les la\u00efcs se rebiffent !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/29\/ideologies-sectaires-et-obscurantistes-versus-science-raison-et-ecole-laique\/\">Id\u00e9ologies sectaires et obscurantistes versus  Science, Raison  et Ecole la\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/28\/vers-les-lendemains-de-lannee-terrible-dans-la-presse-finisterienne-de-1871\/\">Vers les lendemains de l\u2019ann\u00e9e terrible  dans la presse finist\u00e9rienne de 1871<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/18\/jean-vanier-ami-des-handicapes-de-la-communaute-de-larche-etait-un-abuseur-sexuel\/\">Jean Vanier, ami des handicap\u00e9s de la Communaut\u00e9 de l&rsquo;Arche, \u00e9tait un abuseur sexuel.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/09\/16\/petite-chronique-des-lendemains-de-linsurrection-revolutionnaire-de-la-commune-de-paris-1871-dans-la-presse-finisterienne\/\">Petite chronique des lendemains  de l\u2019insurrection r\u00e9volutionnaire de la Commune de Paris (1871) dans la presse finist\u00e9rienne .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/04\/de-1904-a-2021-en-passant-par-le-projet-de-loi-demile-combes\/\">De 1904 \u00e0 2021&#8230; en passant par le projet de loi d&rsquo;Emile Combes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/01\/apres-le-cent-cinquantenaire-de-la-commune-de-paris-retrouver-et-relire-les-massacres-de-paris-de-jean-cassou\/\">Apr\u00e8s le cent-cinquantenaire de la Commune de PARIS  retrouver et (re)lire  \u00ab\u00a0Les Massacres de Paris\u00a0\u00bb de Jean Cassou.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/08\/01\/a-la-decouverte-de-lecole-du-diable-a-plouhinec-f-29780\/\">A la d\u00e9couverte de  l\u2019Ecole du Diable \u00e0 Plouhinec  (F-29780)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/20\/apres-le-cent-cinquantenaire-de-la-commune-de-paris-le-mot-communard-camarades\/\">Apr\u00e8s le cent cinquantenaire de la Commune de Paris : \u00ab\u00a0Le mot communard, camarades  !\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/11\/a-propos-du-projet-de-loi-confortant-le-respect-des-principes-de-la-republique-complement-3\/\">A propos du projet de loi \u00ab confortant le respect des principes de la R\u00e9publique \u00bb  Compl\u00e9ment 3<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/07\/a-propos-du-projet-de-loi-confortant-le-respect-des-principes-de-la-republique-complement-2\/\">A propos du projet de loi \u00ab confortant le respect des principes de la R\u00e9publique \u00bb  Compl\u00e9ment 2<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/07\/a-propos-du-projet-de-loi-confortant-le-respect-des-principes-de-la-republique-complement-1\/\">A propos du projet de loi \u00ab confortant le respect des principes de la R\u00e9publique \u00bb  Compl\u00e9ment 1<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/05\/la-pratique-de-la-laicite-dans-lespace-public-entretien-figarovox-voile-des-assesseurs-burkini-faut-il-interdire-le-port-de-signes-religieux-ostentatoires-dans-lespace-public\/\">La pratique de la la\u00efcit\u00e9 dans l&rsquo;espace  public     Entretien Figarovox : voile des assesseurs, burkini &#8230;    Faut-il interdire le port de signes religieux ostentatoires dans l&rsquo;espace public?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/07\/02\/declin-et-devenir-de-leglise-catholique-romaine\/\">D\u00e9clin et devenir de l&rsquo;Eglise catholique romaine<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/18\/aux-origines-de-la-laicite-et-de-ses-principes-fondateurs\/\">Aux origines de la la\u00efcit\u00e9 et de ses principes fondateurs<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/17\/lorsquau-sortir-de-la-guerre-franco-prussienne-enfantee-par-lempire-de-linsurrection-de-la-commune-et-de-la-semaine-sanglante-on-revient-a-une-constituante-et-a-une-nouve\/\">Lorsqu\u2019au sortir de la guerre franco-prussienne enfant\u00e9e par l\u2019Empire, de l\u2019insurrection de la Commune et de la  Semaine sanglante on revient \u00e0 une  Constituante et \u00e0 une nouvelle Constitution.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/13\/les-femmes-et-la-commune-de-paris-1871\/\">Les Femmes  et la Commune de Paris (1871)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/07\/a-propos-de-la-reedition-de-mein-kampf-par-fayard-2021\/\">A propos de  la r\u00e9\u00e9dition de Mein Kampf par Fayard (2021)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/06\/07\/pour-la-memoire-de-la-commune-de-paris-1871-et-de-la-montee-au-mur-du-29-mai-2021-condamnons-lomerta-lamnesie-le-deni-de-democratie-et-clamons-vive\/\">Pour la m\u00e9moire de la Commune de Paris (1871) et de la Mont\u00e9e au Mur du 29 mai 2021 !        Condamnons l&rsquo;omerta , l&rsquo;amn\u00e9sie , le d\u00e9ni de d\u00e9mocratie                                 et clamons  Vive la Commune !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/30\/au-nom-de-la-raison-la-liberte-la-justice-et-de-la-laicite-jugeons-les-pseudo-fous-halte-aux-bouffees-delirantes\/\">Au nom de la  Raison, la Libert\u00e9, la Justice et  de la La\u00efcit\u00e9    Jugeons les pseudo-fous !     Halte aux bouff\u00e9es d\u00e9lirantes !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/28\/victor-hugo-et-la-commune-de-paris-de-1871\/\">VICTOR HUGO et la  Commune de Paris  de 1871<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/25\/liberte-dexpression-et-convictions-religieuses-retrouver-le-bon-cap-apres-les-critiques-des-missives-de-francois-heran-aux-professeurs\/\">Libert\u00e9 d&rsquo;expression et convictions religieuses :  retrouver le bon cap apr\u00e8s  les critiques des missives de Fran\u00e7ois H\u00e9ran aux professeurs.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/23\/la-commune-de-paris\/\">La Commune de Paris ; la Semaine sanglante     (21mai-28 mai 1871)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/19\/anastasie-son-reveil-et-ses-atteintes-aux-libertes-fondamentales\/\">Anastasie : son r\u00e9veil et ses atteintes   aux libert\u00e9s fondamentales .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/06\/discrimination-linguistique-sous-les-auspices-de-la-republique-francaise-ou-lemancipation-republicaine-par-lecole-laique-passait-elle-par-leradication-des-langues-regionales-de-france\/\">Discrimination linguistique  sous les auspices de la R\u00e9publique fran\u00e7aise  ou    L&rsquo;\u00e9mancipation r\u00e9publicaine  par l&rsquo;\u00e9cole la\u00efque passait-elle par l&rsquo;\u00e9radication  des langues r\u00e9gionales de France?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/05\/05\/la-laicisation-des-ecoles-communales-en-marche-dans-le-departement-de-la-sarthe-en-1890\/\">La la\u00efcisation des \u00e9coles communales en marche    dans le d\u00e9partement de la Sarthe en 1890<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/29\/la-loi-deixonne-et-la-langue-bretonne-leurs-places-a-lecole-publique-de-la-4e-republique\/\">La Loi  Deixonne et la langue bretonne     Leurs  places \u00e0 l&rsquo;\u00e9cole publique de la 4\u00e8 R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/26\/lappropriation-dune-langue-regionale-ou-lon-se-reconnait\/\">L&rsquo;appropriation d&rsquo;une langue r\u00e9gionale o\u00f9 l&rsquo;on se reconna\u00eet<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/17\/loeuvre-scolaire-de-la-commune-de-paris-de-1871-des-acquis-revolutionnaires-occultes-par-les-pouvoirs-publics-et-lhistoire-des-sources-dinspiration-inepuisa\/\">L&rsquo;oeuvre scolaire de la Commune de Paris de 1871                    Des acquis r\u00e9volutionnaires  occult\u00e9s par les pouvoirs publics  et l&rsquo;histoire                 Des  sources d&rsquo;inspiration in\u00e9puisables   pour les fondateurs  de l&rsquo;\u00e9cole publique de la 3\u00e8 R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/09\/regards-sur-la-commune-de-paris-jean-jaures\/\">Regards sur la Commune de Paris : Jean Jaur\u00e8s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/06\/sauvegarder-luniversalite-de-notre-laicite\/\">SAUVEGARDER  L&rsquo;UNIVERSALITE DE NOTRE LA\u00cfCITE  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/03\/regards-sur-la-commune-de-paris-victor-hugo\/\">Regards sur la Commune de Paris : Victor Hugo<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/03\/pour-une-republique-laique-et-sociale\/\">\u00a0\u00bb Pour une R\u00e9publique La\u00efque et Sociale \u00ab\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/04\/03\/le-centenaire-oublie-celui-de-la-repression-de-linsurrection-libertaire-des-marins-de-kronstadt-par-lenine-et-trotsky-en-1921\/\">Le centenaire oubli\u00e9 :   celui de  la r\u00e9pression  de  l&rsquo;insurrection libertaire  des marins de Kronstadt  par   L\u00e9nine et Trotsky en 1921 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/30\/la-presse-locale-et-la-commune-de-paris-mars-mai1871\/\">La presse locale et la Commune de Paris  (mars-mai,1871)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/21\/le-proces-en-conscientisation-et-intimidation-a-luniversite-tous-bons-pour-la-reeducation-alerte\/\">Le proc\u00e8s  en conscientisation et intimidation  \u00e0 l&rsquo;Universit\u00e9 :            Tous bons pour la r\u00e9\u00e9ducation ?  Alerte !&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/20\/les-communes-de-paris-episodes-emblematiques-de-notre-histoire-et-de-notre-histoire-revolutionnaire\/\">Les Communes de  Paris ;        \u00e9pisodes embl\u00e9matiques  de notre Histoire  et de notre Histoire r\u00e9volutionnaire.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/17\/modernite-des-combats-emancipateurs-de-nathalie-le-mel-communarde-deportee-en-nouvelle-caledonie\/\">Modernit\u00e9 des combats \u00e9mancipateurs de Nathalie Le Mel,                 Communarde d\u00e9port\u00e9e en Nouvelle Cal\u00e9donie.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/16\/le-150e-anniversaire-de-la-commune-de-paris-18-mars-1871-28-mai-1871\/\">Le 150\u00e8 anniversaire  de la Commune de Paris                      (18 mars 1871-28 mai 1871)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/13\/yvon-herve-hussard-noir-de-la-fraternite-et-du-bien-public\/\">Yvon Herv\u00e9, hussard noir           de la fraternit\u00e9 et du bien public !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/08\/quand-le-tirailleur-du-citoyen-defendait-ses-idoles\/\">Quand le Tirailleur du Citoyen d\u00e9fendait ses Idoles !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/05\/lavenir-dune-desillusion-letat-et-la-republique\/\">\u00a0\u00bb  L\u2019avenir d\u2019une d\u00e9sillusion : l\u2019\u00c9tat et la R\u00e9publique\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/05\/pour-le-professeur-maitriser-sa-discipline-reste-le-fondement-de-sa-pedagogie-et-de-son-autorite\/\">Pour le Professeur  ma\u00eetriser sa discipline  reste  le  fondement de sa p\u00e9dagogie et de son autorit\u00e9 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/02\/enseigner-les-faits-religieux-et-leur-refutation-a-lecole-publique-laique-en-2022\/\">Enseigner les faits religieux et leur r\u00e9futation     \u00e0 l&rsquo;\u00e9cole publique la\u00efque en 2022.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/03\/02\/professeur-de-philosophie-a-l-ecole-normale-dinstituteurs-de-quimper-philosophe-de-la-sociologie-du-sport-michel-bouet\/\">Professeur de philosophie \u00e0 l&rsquo; Ecole normale d&rsquo;Instituteurs de Quimper, philosophe de la sociologie du sport : MICHEL BOUET.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/17\/selon-ladage-dieu-est-repute-etre-grand-bon-tolerant-et-laique-cependant-parmi-ses-disciples-les-plus-grands-clercs-pretres-et-theologiens-ne-sont-ni-les-plus-clairs-ni-les-plus-sages\/\">Selon l&rsquo;adage;  Dieu  est r\u00e9put\u00e9 \u00eatre grand, bon, tol\u00e9rant et la\u00efque &#8230; Cependant, parmi ses disciples, les plus  grands  clercs, pr\u00eatres et th\u00e9ologiens  ne sont ni les plus clairs ni les plus sages!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/14\/education-et-laicite-la-tolerance-ne-senseigne-pas-elle-seprouve-et-se-vit\/\">Education et la\u00efcit\u00e9 :         la tol\u00e9rance ne s&rsquo;enseigne pas    elle s&rsquo;\u00e9prouve et  se vit !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/02\/06\/petite-chronique-finisterienne-de-linstruction-primaire-sur-une-breve-periode-encadrant-la-promulgation-de-la-loi-goblet-de-1886\/\">Petite chronique finist\u00e9rienne de l&rsquo;instruction primaire sur une br\u00e8ve p\u00e9riode encadrant  la promulgation de la Loi Goblet de 1886.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/30\/la-laicite-est-le-contraire-dun-integrisme\/\">\u00a0\u00bb La la\u00efcit\u00e9 est le contraire d&rsquo;un int\u00e9grisme\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/10\/reflexion-sur-lair-du-temps-et-la-laicite-par-guy-georges-ancien-normalien-en-de-chaumont-haute-marne\/\">R\u00e9flexion sur l&rsquo;air du temps et la la\u00efcit\u00e9     par         Guy GEORGES, ancien normalien          (EN de Chaumont, Haute-Marne)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/08\/racines-et-valeurs-normaliennes-partagees\/\">Racines et valeurs normaliennes partag\u00e9es !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2021\/01\/05\/le-dossier-des-moeurs-laiques-de-mezetulle-blog-archives-de-catherine-kintzler\/\">Le dossier  des \u00ab\u00a0moeurs la\u00efques\u00a0\u00bb de Mezetulle ,    Blog-archives  de Catherine Kintzler .<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/12\/16\/de-lecole-normale-aux-facultes-des-sciences-de-leducation-ou-de-la-vocation-a-la-profession-au-quebec\/\">De l&rsquo;Ecole Normale aux Facult\u00e9s des Sciences de l&rsquo;Education   ou         de la vocation \u00e0 la profession au Qu\u00e9bec<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/16\/un-rappel-salutaire-le-manifeste-de-1989-contre-le-munich-de-lecole-publique-republicaine\/\">Un rappel salutaire ; le manifeste de 1989   contre             le \u00ab\u00a0Munich\u00a0\u00bb de l&rsquo;Ecole publique r\u00e9publicaine.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/15\/giordano-bruno-1548-1600-pourfendeur-de-lignorance-et-de-lobscurantisme-condamne-par-la-sainte-inquisition-et-brule-vif-a-rome\/\">Giordano  Bruno (1548-1600) ,  pourfendeur de l&rsquo;ignorance  et de l&rsquo;obscurantisme ,  condamn\u00e9 par la \u00ab\u00a0sainte\u00a0\u00bb inquisition et  br\u00fbl\u00e9 vif \u00e0 Rome.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/11\/13\/refonder-la-gauche-francaise-de-progres-social-en-evitant-les-traquenards-reactionnaires\/\">Refonder la Gauche fran\u00e7aise de progr\u00e8s  social                en \u00e9vitant les traquenards r\u00e9actionnaires  !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/04\/george-floyd-une-emotion-mondiale\/\">George Floyd, une \u00e9motion mondiale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/08\/03\/conferences-et-exposes-iii-de-robert-lazennec-ancien-eleve-maitre-de-leng-de-quimper-lecole-du-temps-de-jules-ferry-la-france-pedagogise\/\">Conf\u00e9rences et expos\u00e9s (III) de Robert Lazennec, ancien \u00e9l\u00e8ve-ma\u00eetre de l\u2019ENG de Quimper \u2013  \u00a0\u00bb L&rsquo;\u00e9cole du temps de Jules Ferry; la France p\u00e9dagogise\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/29\/antiracisme-accusation-identitaire-et-expiation-en-milieu-academique\/\">Antiracisme, accusation identitaire  et  expiation en milieu acad\u00e9mique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/07\/08\/violences-a-dijon-faits-rapportes-dans-la-presse-et-lecons-pour-la-consolidation-de-nos-institutions-republicaines\/\">Violences \u00e0 Dijon &#8211;\u00a0Faits rapport\u00e9s dans la presse et\u00a0 le\u00e7ons pour la consolidation de nos institutions r\u00e9publicaines<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/le-discours-de-jules-ferry-sur-la-crise-economique-en-1884\/\">Le discours de Jules Ferry\u00a0 sur la crise \u00e9conomique en 1884<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/la-fin-des-turpitudes-criminelles-deegaree-directeur-de-lecole-des-freres-de-la-doctrine-chretienne-de-douarnenez-f-29100-en-1884\/\">La fin des turpitudes criminelles deEgar\u00e9(e),\u00a0directeur de l&rsquo;\u00e9cole des fr\u00e8res de la Doctrine chr\u00e9tienne de Douarnenez (F-29100) en 1884<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/06\/09\/avancer-masque-en-se-demasquant-quelles-lecons-tirer-de-la-pandemie-due-au-coronavirus-sars-cov-2\/\">Avancer masqu\u00e9 en se d\u00e9masquant.\u00a0Quelles\u00a0 le\u00e7ons tirer de la pand\u00e9mie\u00a0due au coronavirus SARS-CoV-2 ?\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/21\/acquisitions-et-cessions-de-terrains-complementaires-pour-limplantation-de-leng-de-quimper\/\">Acquisitions et cessions de terrains compl\u00e9mentaires\u00a0pour l&rsquo;implantation de l&rsquo;ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/21\/visites-sur-les-chantiers-de-construction-des-ecoles-normales-et-du-lycee-a-quimper-fin-1883\/\">Visites sur les chantiers de construction\u00a0des Ecoles normales\u00a0 et du Lyc\u00e9e\u00a0\u00e0 Quimper, fin 1883<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/le-debat-sur-les-livres-denseignement-lors-de-la-mise-en-application-de-la-loi-du-28-mars-1882\/\">Le d\u00e9bat sur les livres d&rsquo;enseignement lors de\u00a0 la mise en application de la loi du 28 mars 1882<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/une-session-fondatrice-pour-le-conseil-municipal-de-quimper\/\">Une session fondatrice\u00a0pour le\u00a0Conseil municipal de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/la-cession-des-terres-labourables-de-bourg-libou-en-1883-pour-construire-lecole-normale-dinstituteurs-de-quimper\/\">La cession des terres labourables de BOURG-LIBOU en 1883\u00a0pour construire l&rsquo;\u00e9cole normale d&rsquo;instituteurs de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/reponses-aux-projets-de-laicisation-des-ecoles-communales-du-finistere-en-1882-les-emeutes-fomentees-par-les-clericaux-a-moelan-sur-mer-f-29350\/\">R\u00e9ponses aux projets de la\u00efcisation des \u00e9coles communales du\u00a0Finist\u00e8re en 1882 ; les \u00e9meutes foment\u00e9es par les cl\u00e9ricaux \u00e0 Mo\u00eblan-sur-Mer (F- 29350).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/le-discours-attendu-sur-la-laicite-toujours-reporte-au-lendemain\/\">Le\u00a0discours attendu sur la la\u00efcit\u00e9 toujours report\u00e9\u00a0au lendemain<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/05\/14\/la-loi-du-28-mars-1882-sur-lenseignement-primaire-obligatoire-et-laique-loi-athee-de-lecole-sans-dieu\/\">La Loi du 28 mars 1882 sur l&rsquo;enseignement primaire obligatoire et la\u00efque :\u00a0Loi ath\u00e9e de l&rsquo;Ecole sans Dieu\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/31\/conferences-et-exposes-ii-de-robert-lazennec-ancien-eleve-maitre-de-leng-de-quimper-emile-combes-le-combattant-de-la-laicite\/\">Conf\u00e9rences et expos\u00e9s (II) de Robert Lazennec,\u00a0ancien \u00e9l\u00e8ve-ma\u00eetre de l&rsquo;ENG de Quimper &#8211;\u00a0\u00ab\u00a0Emile Combes, le Combattant de la La\u00efcit\u00e9\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/31\/la-belle-yvonne-1882-feuilleton-inedit-dapres-laicisation-de-lhebdomadaire-republicain-le-finistere\/\">La Belle Yvonne\u00a0(1882) &#8211; feuilleton in\u00e9dit d&rsquo;apr\u00e8s la\u00efcisation de l&rsquo;hebdomadaire r\u00e9publicain Le Finist\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/31\/les-cessions-amiables-de-terres-labourables-pour-la-construction-de-lecole-normale-dinstitutrices-a-kerfeunteun-f-29088-en-1882\/\">Les cessions amiables de terres labourables pour la construction de l&rsquo;Ecole normale d&rsquo;Institutrices\u00a0\u00e0 Kerfeunteun (F-29088) en 1882<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/18\/faits-et-bruits-finisteriens-de-1882-1\/\">Faits et bruits finist\u00e9riens de 1882 (1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/03\/08\/gazette-bigoudenne-de-lete-1882-plozevet-f-29710\/\">Gazette bigoudenne de l\u2019\u00e9t\u00e9 1882\u00a0: Ploz\u00e9vet ( F-29710)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/22\/miscellanees-quimperoises-dapres-laicisation-article-3-du-concordat-au-discordat\/\">Miscellan\u00e9es quimp\u00e9roises d&rsquo;apr\u00e8s la\u00efcisation\u00a0(article 3) &#8211; Du concordat au discordat !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/22\/les-rapports-de-leglise-et-de-letat-de-lalliance-a-la-separation-par-robert-lazennec\/\">Les rapports de l\u2019Eglise et de l\u2019Etat\u00a0:\u00a0de l\u2019alliance \u00e0 la\u00a0 s\u00e9paration &#8211;\u00a0par\u00a0Robert Lazennec<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/21\/miscellanees-bretonnes-et-quimperoises-dapres-laicisation-suite\/\">Miscellan\u00e9es\u00a0 bretonnes et quimp\u00e9roises\u00a0d&rsquo;apr\u00e8s la\u00efcisation (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/michel-mazeas-promotion-liberation-1944-1947-instituteur-tres-engage-dans-la-vie-professionnelle-syndicale-associative-et-politique\/\">Michel Maz\u00e9as &#8211;\u00a0Promotion LIBERATION( 1944-1947) &#8211;\u00a0Instituteur tr\u00e8s engag\u00e9\u00a0 dans la vie professionnelle, syndicale, associative et politique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/lorganisation-de-linstruction-publique-du-finistere-sous-la-conduite-et-lautorite-des-prefets-de-la-republique-en-1880-1881\/\">L&rsquo;organisation de l&rsquo;instruction publique du Finist\u00e8re sous la conduite et l&rsquo;autorit\u00e9 des pr\u00e9fets de la R\u00e9publique\u00a0en\u00a01880-1881<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/les-premices-de-la-creation-de-lassociation-des-anciens-eleves-des-ecoles-laiques-de-brest-en-1912\/\">Les pr\u00e9mices de la cr\u00e9ation de l&rsquo;Association des anciens \u00e9l\u00e8ves des Ecoles la\u00efques de Brest en 1912.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/quand-jules-ferry-se-lancait-dans-la-campagne-electorale-des-legislatives-daout-1881\/\">Quand Jules Ferry se lan\u00e7ait dans la campagne \u00e9lectorale des L\u00e9gislatives d&rsquo;ao\u00fbt 1881<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/16\/les-choix-strategiques-du-conseil-general-du-finistere-en-1881-au-lancement-de-la-construction-des-deux-ecoles-normales-primaires-du-finistere\/\">Les choix strat\u00e9giques du Conseil G\u00e9n\u00e9ral du Finist\u00e8re en 1881 au lancement\u00a0de\u00a0la construction des deux Ecoles Normales Primaires du Finist\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/13\/reinstituer-lecole-publique-laique-pour-reinstituer-lelitisme-republicain\/\">R\u00e9instituer l&rsquo;\u00e9cole publique la\u00efque\u00a0pour\u00a0r\u00e9instituer l&rsquo;\u00e9litisme r\u00e9publicain<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/02\/13\/chronique-quimperoise-dapres-laicisation-des-ecoles-communales-article-2\/\">Chronique quimp\u00e9roise d&rsquo;apr\u00e8s la\u00efcisation des \u00e9coles communales (article 2)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/01\/17\/chronique-quimperoise-dapres-laicisation-des-ecoles-communales-article-1\/\">Chronique quimp\u00e9roise d&rsquo;apr\u00e8s la\u00efcisation des \u00e9coles communales (article 1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/01\/17\/a-la-memoire-des-caporaux-de-souain-fusilles-pour-lexemple\/\">A la m\u00e9moire des Caporaux de Souain,\u00a0fusill\u00e9s pour l&rsquo;exemple<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/01\/08\/addendum-aux-memoires-de-jeanne-le-borgne-institutrice-publique-a-plouhinec-29-au-moment-de-loccupation-allemande-1940-1944\/\">Addendum aux m\u00e9moires de Jeanne Le Borgne Institutrice publique \u00e0 Plouhinec (29) au moment de l&rsquo;occupation allemande (1940-1944)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2020\/01\/08\/lecole-normale-dinstituteurs-de-quimper-article-des-amis-du-patrimoine-de-tregunc-f-29910-publie-en-2018-dans-louvrage-histoire-des-ecoles-de-tregunc-livre-1\/\">L&rsquo;Ecole Normale d&rsquo;Instituteurs de Quimper.\u00a0Article\u00a0 des Amis du Patrimoine de Tr\u00e9gunc\u00a0(F-29910)\u00a0publi\u00e9 en 2018 dans l&rsquo;ouvrage\u00a0\u00ab\u00a0Histoire des \u00e9coles de Tr\u00e9gunc, Livre 1\u00a0\u00bb\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/22\/chronique-quimperoise-de-la-laicisation-de-lecole-normale-et-des-ecoles-communales-en-1880-suite\/\">Chronique quimp\u00e9roise de la la\u00efcisation de\u00a0 l&rsquo;Ecole normale et des Ecoles communales en 1880 (suite)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/le-frere-reneex-directeur-de-lecole-normale-congreganiste-de-quimper-et-lordonnance-de-non-lieu-prononcee-a-son-encontre-en-1880\/\">Le fr\u00e8re Ren\u00e9,ex-directeur de l&rsquo;\u00e9cole normale congr\u00e9ganiste de Quimper,\u00a0et l&rsquo;ordonnance de non-lieu prononc\u00e9e \u00e0 son encontre en 1880<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/nouvelles-et-renseignements-concernant-le-jugement-en-1880-de-lex-directeur-de-lecole-normale-congreganiste-de-quimper\/\">Nouvelles et renseignements concernant le jugement (en 1880) de l&rsquo;ex-directeur de l&rsquo;\u00e9cole normale congr\u00e9ganiste de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/mars-1880-lheure-de-la-laicisation-de-lecole-a-quimper-ii-le-voeu-pour-la-laicisation-des-ecoles-communales-au-conseil-municipal-de-quimper-debats-et-vote-final\/\">\u00a0Mars 1880 ; l&rsquo;heure de la la\u00efcisation de l&rsquo;Ecole \u00e0 Quimper (II).\u00a0Le voeu pour\u00a0 la la\u00efcisation des Ecoles communales au Conseil municipal de Quimper.\u00a0(d\u00e9bats et vote final)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/mars-1880-lheure-de-la-laicisation-de-lecole-a-quimper-i-congreganistes-ou-laiques\/\">Mars 1880 ; l&rsquo;heure de la la\u00efcisation de l&rsquo;Ecole \u00e0 Quimper (I).\u00a0Congr\u00e9ganistes ou La\u00efques<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/la-question-des-manuels-scolaires-et-de-leurs-contenus-en-debat-au-senat-de-la-3e-republique-en-1883\/\">La question des manuels scolaires et de leurs contenus en d\u00e9bat, au S\u00e9nat de la 3\u00e8 R\u00e9publique, en 1883<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/instruction-et-enseignement-primaires-en1884-le-diagnostic-de-la-presse-locale\/\">Instruction et Enseignement primaires en1884: le diagnostic de la presse locale !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/chronique-anticlericale-suite-pour-lutter-contre-lecole-des-julessic-laique-gratuite-et-obligatoire-et-assurer-le-salut-des-enfants-par-scolarite-catholique-il-suffit-de-donner-des-bourse\/\">Chronique anticl\u00e9ricale (suite&#8230;): Pour lutter contre l&rsquo;ECOLE des JULES(sic), la\u00efque, gratuite et obligatoire et assurer le salut des enfants par scolarit\u00e9 catholique, il suffit de donner des bourses aux n\u00e9cessiteux !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/29\/auguste-damalix-aspirant-normalien-bourguignon-un-des-premiers-protagonistes-de-l-ecole-normale-dinstituteurs-de-quimper-promotion-eng-1886-1889\/\">Auguste DAMALIX, aspirant normalien bourguignon, un des premiers\u00a0 protagonistes de l&rsquo; Ecole Normale d&rsquo;Instituteurs de Quimper (Promotion ENG , 1886-1889)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/narcisse-et-sebastien-kerdavid-les-deux-freres-terribles-du-clericalisme-en-finistere-a-la-fin-du-19e-siecle\/\">Narcisse et\u00a0S\u00e9bastien KERDAVID\u00a0, \u00ab\u00a0les\u00a0 deux fr\u00e8res terribles du cl\u00e9ricalisme\u00a0\u00bb en Finist\u00e8re \u00e0 la fin du 19\u00e8 si\u00e8cle !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/de-lecole-de-hameau-de-keranguen-scaer-f-29390-a-xieng-khouang-et-le-pays-des-meos-au-laos-au-debut-des-annees-60-le-parcours-hors-norme-dun-jeune-instituteur\/\">De l\u2019\u00e9cole de hameau de\u00a0 Keranguen (Sca\u00ebr, F-29390) \u00e0 Xieng Khouang et le pays des M\u00e9os au Laos, au d\u00e9but des ann\u00e9es 60\u00a0:\u00a0Le parcours hors norme d\u2019un jeune instituteur\u00a0 breton form\u00e9 \u00e0 l\u2019ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/10\/17\/un-projet-exemplaire-pour-le-bien-public-la-rehabilitation-des-batiments-de-lecole-normale-dinstitutrices-de-tarbes-pour-l-accueil-des-archives-departementales-et-notamment-celles-des-ecol\/\">L&rsquo;Ecole\u00a0 Normale d&rsquo;Institutrices de Tarbes choisie pour accueillir les Archives D\u00e9partementales des Hautes Pyr\u00e9n\u00e9es :\u00a0 une r\u00e9habilitation en d\u00e9bat<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/10\/17\/la-fermeture-de-lecole-normale-congreganiste-de-quimper-en-1880-chroniques-de-la-presse-finisterienne-de-lepoque\/\">La fermeture de l&rsquo;Ecole normale congr\u00e9ganiste\u00a0 de Quimper en 1880 &#8211;\u00a0Chroniques de la presse finist\u00e9rienne de l&rsquo;\u00e9poque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/10\/03\/chronique-anticlericale-suite-derives-sectaires-dans-leglise-catholique-gare-aux-gourous\/\">Chronique anticl\u00e9ricale (suite) &#8211;\u00a0D\u00e9rives sectaires dans l&rsquo;Eglise catholique &#8211;\u00a0Gare aux gourous!\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/action-et-defense-laiques-pour-sauver-la-democratie-et-la-republique-sociales\/\">Action et d\u00e9fense la\u00efques pour sauver\u00a0la d\u00e9mocratie et la R\u00e9publique sociales<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/au-coeur-de-la-crise-catholique-resilience-pragmatisme-et-reference-a-la-laicite-auront-ils-raison-des-exces-du-clericalisme\/\">Au coeur de la \u00ab\u00a0crise catholique\u00a0\u00bb;  r\u00e9silience, pragmatisme et r\u00e9f\u00e9rence \u00e0 la la\u00efcit\u00e9  auront-ils raison des exc\u00e8s du cl\u00e9ricalisme ?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/chronique-journalistique-de-la-drole-de-guerre-1939-1940\/\">Chronique journalistique de la dr\u00f4le de guerre (1939-1940)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/aux-deux-heros-de-kervez-ce-paradis-lamitie-par-le-livre1958\/\">Aux deux h\u00e9ros de \u00ab\u00a0KERVEZ ce paradis\u00a0\u00bb &#8211;\u00a0(L&rsquo;Amiti\u00e9 Par Le Livre,1958)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/29\/conviction-laique-vingt-fois-sur-les-principes-remettez-votre-ouvrage-polissez-les-sans-cesse-et-les-repolissez\/\">CONVICTION LA\u00cfQUE :\u00a0 vingt fois sur les principes remettez votre ouvrage, polissez-les sans cesse et les repolissez &#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/13\/biographie-du-professeur-decole-normale-per-jakez-helias-par-ses-enfants2013\/\">Biographie du Professeur d&rsquo;Ecole Normale Per-Jakez HELIAS par ses enfants(2013).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/13\/lecole-laique-forgeait-lame-de-ses-eleves-de-1920-en-leur-montrant-la-science-cent-ans-apres-la-question-se-pose-de-savoir-comment-defendre-la-science\/\">L&rsquo;Ecole La\u00efque\u00a0 forgeait l&rsquo;\u00e2me de ses \u00e9l\u00e8ves de 1920 en leur \u00ab\u00a0montrant la SCIENCE\u00a0\u00bb. Cent ans apr\u00e8s la question se pose de savoir \u00ab\u00a0comment d\u00e9fendre la Science\u00a0\u00bb !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/13\/les-accords-de-munich-30-septembre-1938-annonciateurs-de-bourrasques-sur-leurope\/\">Les accords de Munich (30 septembre 1938) annonciateurs de bourrasques sur l&rsquo;Europe<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/13\/chronique-academique-et-normalienne-novembre-1938\/\">Chronique acad\u00e9mique et normalienne\u00a0.\u00a0(Novembre 1938)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/08\/la-mauvaise-querelle-faite-aux-instituteurs-apres-le-congres-de-leur-syndicat-national-nantes-3-aout-1938\/\">La mauvaise querelle faite aux instituteurs apr\u00e8s le congr\u00e8s de leur syndicat national.\u00a0(Nantes, 3 ao\u00fbt 1938)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/08\/maille-village-martyr-de-la-barbarie-nazie-le-massacre-oublie\/\">Maill\u00e9, village martyr de la\u00a0 barbarie nazie :\u00a0le massacre oubli\u00e9<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/01\/le-point-de-vue-dun-breton-eclaire-sur-les-perspectives-de-guerre-en-1938\/\">Le point de vue d&rsquo;un breton \u00e9clair\u00e9 sur les perspectives de guerre en 1938<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/01\/remunerations-avancement-et-retraites-des-instituteurs-a-la-fin-du-19e-siecle-2\/\">R\u00e9mun\u00e9rations, avancement et retraites des Instituteurs \u00e0 la fin du 19\u00e8 si\u00e8cle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/09\/01\/enjeux-politiques-de-la-fin-du-19e-siecle-en-pays-morlaisien-union-des-forces-republicaines-anticlericalisme-et-anticesarisme-sur-fond-daffaire-dreyfus-2\/\">Enjeux politiques de la fin du 19\u00e8 si\u00e8cle en\u00a0 pays morlaisien :\u00a0union des forces r\u00e9publicaines, anticl\u00e9ricalisme et antic\u00e9sarisme sur fond d&rsquo;affaire Dreyfus<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/08\/01\/remunerations-avancement-et-retraites-des-instituteurs-a-la-fin-du-19e-siecle\/\">R\u00e9mun\u00e9rations, avancement et retraites des Instituteurs \u00e0 la fin du 19\u00e8 si\u00e8cle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/08\/01\/enjeux-politiques-de-la-fin-du-19e-siecle-en-pays-morlaisien-union-des-forces-republicaines-anticlericalisme-et-anticesarisme-sur-fond-daffaire-dreyfus\/\">Enjeux politiques de la fin du 19\u00e8 si\u00e8cle en  pays morlaisien : union des forces r\u00e9publicaines, anticl\u00e9ricalisme et antic\u00e9sarisme sur fond d&rsquo;affaire Dreyfus<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/18\/reformer-lenseignement-secondaire-a-la-fin-du-19e-siecle\/\">R\u00e9former l&rsquo;enseignement secondaire \u00e0 la fin du 19\u00e8 si\u00e8cle&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/18\/quand-a-la-rentree-1938-et-malgre-le-contexte-charge-on-envisage-encore-les-reformes-de-lenseignement-initiees-par-jean-zay-sous-le-front-populaire\/\">Quand \u00e0 la rentr\u00e9e 1938\u00a0 et malgr\u00e9 le contexte charg\u00e9, on envisage encore les r\u00e9formes de l&rsquo;Enseignement initi\u00e9es par Jean ZAY sous le Front Populaire,<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/11\/la-lutte-farouche-des-catholiques-et-des-royalistes-contre-la-loi-de-separation-de-1905-lezenn-an-disparti-en-breton-tregorrois\/\">La lutte farouche des catholiques et des royalistes contre la\u00a0 Loi de S\u00e9paration de 1905 (Lezenn an disparti en breton tr\u00e9gorrois)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/07\/11\/lappel-au-deuil-de-albert-de-mun-faisant-suite-a-ladoption-par-la-chambre-des-deputes-du-projet-de-loi-de-separation-des-eglises-et-de-letat-en-juillet-1905\/\">L&rsquo;appel au Deuil de Albert de MUN\u00a0 faisant suite \u00e0 l&rsquo;adoption, par la Chambre des D\u00e9put\u00e9s, du projet de loi de s\u00e9paration des \u00e9glises et de l&rsquo;Etat en juillet 1905<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/28\/avec-spinoza-1632-1677-prince-des-philosophes-contre-les-dogmes-et-pour-une-pensee-rationaliste-fondatrice-de-democraties-tolerantes-et-laiques\/\">Avec SPINOZA (1632-1677), prince des philosophes, contre les dogmes et pour une pens\u00e9e rationaliste fondatrice de d\u00e9mocraties tol\u00e9rantes et la\u00efques<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/11\/instantanes-vie-quimperoise-debut-xxe\/\">Instantan\u00e9s de la vie normalienne quimp\u00e9roise du d\u00e9but du 20\u00e8 si\u00e8cle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/06\/souvenirs-de-la-guerre-dalgerie-parjacques-dennielou\/\">Souvenirs de la Guerre d&rsquo;Alg\u00e9rie parJacques Denni\u00e9lou<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/06\/03\/linquisition-en-marche-en-1928-quand-leveque-pasquier-se-fait-pourvoyeur-de-prison\/\">L&rsquo;inquisition en marche en 1928 , quand l&rsquo;\u00e9v\u00eaque\u00a0 Pasquier se fait pourvoyeur de prison<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/22\/hommage-a-jean-cornec-president-de-la-fcpe-de-1956-a-1980\/\">Hommage \u00e0 Jean CORNEC, Pr\u00e9sident de la FCPE de 1956 \u00e0 1980<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/13\/votre-bouche-nous-livrait-de-lor-lhommage-de-jacques-dennielou-a-pierre-jakez-helias-son-professeur-de-francais-a-leng-de-quimper\/\">\u00ab\u00a0Votre bouche nous livrait de l&rsquo;or\u00a0\u00bb; l&rsquo;hommage de Jacques Denni\u00e9lou, \u00e0 Pierre Jakez H\u00e9lias, son professeur de fran\u00e7ais \u00e0 l&rsquo;ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/05\/06\/attendus-recents-de-la-chronique-anticlericale\/\">Attendus r\u00e9cents de la chronique anticl\u00e9ricale\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/28\/les-davidees-institutrices-laiques-catholiques-formees-dans-les-ecoles-normales-primaires\/\">Les DAVIDEES ; institutrices la\u00efques catholiques form\u00e9es dans les \u00e9coles normales primaires<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/lecole-a-lepreuve-du-colonialisme-une-exposition-du-musee-national-de-leducation-a-rouen-du-8-avril-2017-au-2-avril-2018-intitulee-lecole-en-algerie-lalgerie-a-lecole-depuis\/\">L&rsquo;Ecole \u00e0 l&rsquo;\u00e9preuve du colonialisme : Une exposition du Mus\u00e9e National de l&rsquo;Education \u00e0 ROUEN ( du 8 avril 2017 au\u00a0 2 avril 2018) intitul\u00e9e \u00a0\u00bb L&rsquo;\u00e9cole en Alg\u00e9rie, l&rsquo;Alg\u00e9rie \u00e0 l&rsquo;\u00e9cole depuis 1830&Prime;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/chronique-antireligieuse-suite-aux-assassins-de-ferrer-poeme-dedie-a-francisco-ferrer-martyr-de-la-pensee-libre\/\">Chronique antireligieuse (suite) : \u00a0\u00bb Aux assassins de FERRER \u00ab\u00a0, po\u00e8me d\u00e9di\u00e9 \u00e0 Francisco Ferrer, martyr de la Pens\u00e9e Libre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/04\/09\/chronique-antireligieuse-francisco-ferrer-1859-1909-fondateur-de-lecole-moderne-rationaliste-a-barcelone-un-martyr-de-la-pensee-libre\/\">Chronique antireligieuse\u00a0:\u00a0Francisco FERRER (1859-1909), fondateur de l&rsquo;ECOLE MODERNE RATIONALISTE \u00e0 Barcelone, un martyr de la Pens\u00e9e Libre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/25\/sagas-normaliennes-quimperoises-de-pere-a-fille-et-doncle-a-neveu\/\">Sagas normaliennes quimp\u00e9roises: de p\u00e8re \u00e0 fille et d&rsquo;oncle \u00e0 neveu<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/12\/les-grands-meetings-de-defense-laique-de-decembre-1930-en-finistere\/\">Les grands meetings de D\u00e9fense La\u00efque de d\u00e9cembre 1930 en Finist\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/08\/un-scandale-denonce-en-1930-lirruption-de-moniteurs-et-de-monitrices-dans-lencadrement-des-eleves-des-ecoles-privees\/\">Un scandale d\u00e9nonc\u00e9 en 1930 : l&rsquo;irruption de\u00a0 moniteurs et de monitrices dans l&rsquo;encadrement des \u00e9l\u00e8ves des\u00a0 \u00e9coles priv\u00e9es !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/08\/organisation-de-lecole-libre-en-1930-on-se-proposait-de-creer-des-ecoles-normales-catholiques-interdiocesaines\/\">Organisation de l&rsquo;\u00e9cole \u00ab\u00a0libre\u00a0\u00bb : en 1930 \u00ab\u00a0on\u00a0\u00bb se proposait de cr\u00e9er des \u00e9coles normales catholiques interdioc\u00e9saines !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/06\/quand-le-patronyme-dun-ancien-professeur-de-francais-a-leng-est-retenu-par-le-conseil-municipal-de-la-commune-de-cleden-poher-29270-pour-la-denomination-de-son-ecole-publique-communale-3\/\">Quand le patronyme d&rsquo;un ancien Professeur de Fran\u00e7ais \u00e0 l&rsquo;ENG est retenu par le Conseil municipal de la Commune de Cl\u00e9den Poher (29270) pour la d\u00e9nomination de son \u00e9cole publique communale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/03\/a-la-recherche-des-anciens-directeurs-de-leng\/\">A la recherche\u00a0des anciens directeurs de l&rsquo;ENG<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/03\/en-1930-pour-conserver-les-instituteurs-formes-a-lecole-normale-et-sauver-lecole-laique-on-decouvre-lurgence-de-la-revalorisation-de-la-situation-materielle-des-maitres\/\">En 1930, pour \u00ab\u00a0conserver\u00a0\u00bb les instituteurs form\u00e9s \u00e0 l&rsquo;Ecole Normale et sauver l&rsquo;Ecole la\u00efque, on d\u00e9couvre l&rsquo;urgence de la revalorisation de la situation mat\u00e9rielle des ma\u00eetres !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/03\/03\/les-delegations-de-stagiaires-pour-les-normaliens-et-normaliennes-des-promotions-1927-1930\/\">Les d\u00e9l\u00e9gations de stagiaires pour les normaliens et normaliennes des promotions 1927-1930<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/24\/directeurs-et-directrices-des-ecoles-normales-primaires-de-quimper-j-le-poezat-guigner-directeur-de-leng-1957-1972\/\">Directeurs et Directrices des Ecoles Normales Primaires de Quimper . J. Le Po\u00ebzat-Guigner, Directeur de l&rsquo;ENG (1957-1972)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/17\/preparatifs-de-la-celebration-du-cinquantenaire-de-lecole-publique-des-projets-a-assumer-et-une-realisation-exemplaire\/\">Pr\u00e9paratifs de la c\u00e9l\u00e9bration du cinquantenaire de l&rsquo;\u00e9cole publique &#8230;\u00a0 Des projets \u00e0 assumer et une r\u00e9alisation exemplaire !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/lecole-et-la-terre\/\">L&rsquo;Ecole et la\u00a0 Terre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/limplication-du-citoyen-dans-la-defense-de-lecole-laique-et-de-ses-maitres-a-lete-1927\/\">L&rsquo;implication du Citoyen dans la d\u00e9fense de l&rsquo;\u00e9cole la\u00efque et de ses ma\u00eetres \u00e0 l&rsquo;\u00e9t\u00e9 1927<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/la-defense-acharnee-de-lecole-laique-et-de-ses-maitres-au-printemps-1927\/\">La d\u00e9fense acharn\u00e9e\u00a0 de l&rsquo;\u00e9cole la\u00efque et de ses ma\u00eetres au printemps 1927<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/02\/10\/retour-en-1927-sur-les-propos-et-les-biographies-de-fondateurs-de-lecole-laique\/\">Retour (en 1927) sur les propos et les biographies de fondateurs de l&rsquo;Ecole La\u00efque<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/22\/la-defense-de-lois-laiques-un-combat-de-tous-les-instants\/\">La d\u00e9fense des Lois La\u00efques : un combat de tous les instants<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/17\/1929-crise-ou-incidents-a-leng-de-quimper\/\">1929 &#8211; \u00ab\u00a0Crise\u00a0\u00bb ou \u00ab\u00a0Incidents\u00a0\u00bb\u00a0\u00e0 l&rsquo;ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/12\/11\/rene-daniel-combattant-de-lecole-laique\/\">\u00ab\u00a0Ren\u00e9 DANIEL, combattant de l&rsquo;Ecole La\u00efque\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/10\/03\/le-discours-de-jules-ferry-sur-lecole-laique-a-lassemblee-nationale-le-6-juin-1889\/\">Le discours de Jules Ferry sur l&rsquo;Ecole La\u00efque \u00e0 l&rsquo;Assembl\u00e9e Nationale le\u00a0 6 juin 1889<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/06\/19\/enfant-caches-et-scolarises-en-haute-bretagne-sous-le-regime-de-vichy\/\">Enfants cach\u00e9s et scolaris\u00e9s en Haute Bretagne, sous le r\u00e9gime de Vichy<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/06\/07\/memoires-dune-normalienne-quimperoise-des-annees-30\/\">M\u00e9moires d&rsquo;une normalienne quimp\u00e9roise des ann\u00e9es 30<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/25\/lenseignement-de-lhistoire-en-question-en-1929\/\">L&rsquo;enseignement de l&rsquo;histoire en question en 1929 !<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/25\/edouard-herriot-1872-1957-et-lecole-unique\/\">Edouard Herriot (1872-1957) et l&rsquo;Ecole Unique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/10\/linstituteur-laique-et-lecole-republicaine\/\">L&rsquo;Instituteur\u00a0La\u00efque et l&rsquo;Ecole R\u00e9publicaine<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/10\/histoire-scolaire-de-la-bretagne-les-treize-colleges-davant-la-revolution\/\">Histoire scolaire de la Bretagne : les treize coll\u00e8ges d&rsquo;avant la R\u00e9volution!&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/06\/limmixtion-de-taupes-a-leng-de-quimper-en-1929-une-nouvelle-mensongere-diffusee-par-le-citoyen\/\">L&rsquo;immixtion de \u00ab\u00a0taupes\u00a0\u00bb \u00e0 l&rsquo;ENG de Quimper en 1929 : une\u00a0nouvelle mensong\u00e8re diffus\u00e9e par Le Citoyen<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/les-lendemains-de-crise-a-leng-de-quimper-en-1929-4\/\">Les lendemains de crise \u00e0 l&rsquo;ENG de Quimper en 1929 (4)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/les-lendemains-de-crise-a-leng-de-quimper-en-1929-3\/\">Les lendemains de crise \u00e0 l&rsquo;ENG de Quimper en 1929 (3)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/les-lendemains-de-crise-a-leng-de-quimper-en-1929-2\/\">Les lendemains de crise \u00e0 l&rsquo;ENG de Quimper en 1929 (2)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/les-lendemains-de-crise-a-leng-de-quimper-en-1929-1\/\">Les lendemains de crise \u00e0 l&rsquo;ENG de Quimper en 1929 (1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/les-trousseaux-des-laureates-des-concours-dentree-dans-les-ecoles-normales-du-finistere-annees-60\/\">Les trousseaux des laur\u00e9at(e)s\u00a0des concours d&rsquo;entr\u00e9e dans\u00a0les Ecoles Normales du Finist\u00e8re\u00a0(ann\u00e9es 60)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/la-lettre-circulaire-du-directeur-de-leng-aux-laureats-du-concours-dentree-de-juin-1968\/\">La lettre circulaire du\u00a0 Directeur de l&rsquo;ENG aux laur\u00e9ats du Concours d&rsquo;entr\u00e9e de juin 1968&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/05\/05\/des-taupes-jesuites-au-seminaire-laique-de-roz-avel\/\">Des taupes j\u00e9suites au s\u00e9minaire la\u00efque de Roz Avel.<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/30\/lalbum-souvenir-de-guy-gandouin-et-le-fonds-photographique-y-afferent-accessibles-sur-le-site\/\">L&rsquo;album-souvenir de Guy GANDOUIN et le fonds photographique y aff\u00e9rent accessibles sur le site<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/04\/02\/les-combats-du-syndicat-de-lenseignement-laique-du-finistere-en1934\/\">Les combats du Syndicat de l&rsquo;Enseignement la\u00efque\u00a0du Finist\u00e8re en1934<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/29\/restrictions-budgetaires-et-repression-contre-les-eleves-maitres-sortants-et-les-instituteurs-publics-en-1934\/\">Restrictions budg\u00e9taires et r\u00e9pression contre les \u00e9l\u00e8ves-ma\u00eetres sortants et les instituteurs publics en 1934<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/28\/defense-et-action-laiques-en-finistere-quelques-reperes-sur-la-periode-de-lentre-deux-guerres\/\">D\u00e9fense et Action La\u00efques en Finist\u00e8re ; quelques rep\u00e8res\u00a0sur la p\u00e9riode de l&rsquo;entre deux guerres<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/19\/mistri-skol-laik-les-maitres-de-lecole-laique-du-finistere-confrontes-aux-turpitudes-de-1934-premices-de-la-fin-de-la-troisieme-republique\/\">\u00ab\u00a0Mistri-skol la\u00efk\u00a0\u00bb\u00a0: les ma\u00eetres de l\u2019\u00e9cole la\u00efque du Finist\u00e8re confront\u00e9s aux turpitudes de 1934, pr\u00e9mices de la fin\u00a0 de la Troisi\u00e8me R\u00e9publique\u00a0!\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/03\/07\/quand-lecole-publique-et-la-laicite-etaient-malmenees-en-1934-dans-le-canton-de-plogastel-saint-germain-f-29710\/\">Quand l&rsquo;Ecole Publique et la La\u00efcit\u00e9 \u00e9taient malmen\u00e9es, en 1934, dans le canton de Plogastel-Saint-Germain (F-29710)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/25\/que-sont-donc-devenus-les-normaliens-et-les-normaliennes-des-promotions-1936-1939\/\">Que sont donc devenus\u00a0 les\u00a0 normaliens et\u00a0 les normaliennes des promotions 1936-1939?<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/22\/avoir-20-ans-en-40\/\">\u00ab\u00a0AVOIR 20 ANS EN 40\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/a-la-fin-du-19e-siecle-le-dur-apprentissage-du-metier-denseignante-dune-jeune-institutrice-sortie-de-lecole-normale-dinstitutrices-de-quimper-en-1893-et-nommee-a-ergue-gaberic\/\">A la fin du 19\u00e8 si\u00e8cle, le dur apprentissage du m\u00e9tier d&rsquo;enseignante d&rsquo;une jeune institutrice sortie de l&rsquo;Ecole Normale d&rsquo;Institutrices de Quimper en 1893 et nomm\u00e9e \u00e0 Ergu\u00e9-Gab\u00e9ric<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/quand-lantiparlementarisme-sattaque-a-la-republique-lecole-laique-est-toujours-parmi-les-premieres-victimes\/\">Quand l&rsquo;antiparlementarisme s&rsquo;attaque \u00e0 la R\u00e9publique, l&rsquo;\u00e9cole la\u00efque est toujours parmi les premi\u00e8res victimes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/histoire-fondatrice-des-ecoles-de-hameau-du-finistere-creees-sous-la-3e-republique\/\">Histoire fondatrice des ECOLES de HAMEAU du Finist\u00e8re cr\u00e9\u00e9es sous la 3\u00e8 R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/fougue-et-methodes-de-germaine-le-goff-penn-sardin-penn-kalet-devenue-une-institutrice-celebre-au-siecle-dernier-grace-a-lecole-normale\/\">\u00ab\u00a0Fougue et m\u00e9thode(s)\u00a0\u00bb de Germaine Le Goff, Penn Sardin penn-kalet, devenue une institutrice c\u00e9l\u00e8bre au si\u00e8cle dernier gr\u00e2ce \u00e0 l&rsquo;Ecole Normale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-professeur-deps-guy-gandouin-biographie-et-album-souvenir\/\">Le Professeur d&rsquo;EPS Guy GANDOUIN : biographie et album souvenir<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/lenseignement-primaire-en-finistere-avant-la-loi-guizot-28-juin-1833\/\">L&rsquo;enseignement primaire en Finist\u00e8re avant la loi GUIZOT (28 juin 1833)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/la-promotion-sociale-par-les-ecoles-normales-primaires\/\">La promotion sociale\u00a0 par les Ecoles Normales Primaires<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/petite-histoire-des-ecoles-publiques-de-hameau-creees-sous-la-3eme-republique\/\">\u00ab\u00a0Petite histoire\u00a0\u00bb des \u00e9coles publiques de hameau cr\u00e9\u00e9es sous la 3\u00e8me R\u00e9publique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/les-enjeux-des-elections-legislatives-de-1928les-dangers-quon-ne-veut-pas-voir-suite-au-scrutin-uninominal-a-deux-tours-par-arrondissement-la-droite-alliee-au-centre-droit-et-au-centre-gauche\/\">Les enjeux des \u00e9lections l\u00e9gislatives de 1928 ; les dangers qu&rsquo;on ne veut pas voir&#8230; Suite au scrutin uninominal \u00e0 deux tours par arrondissement, la droite, alli\u00e9e au centre droit et au centre gauche, remporte la majorit\u00e9 (!&#8230;)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/lorsque-lon-retrouve-trace-des-associations-des-anciens-eleves-des-ecoles-normales-de-quimper\/\">Lorsque l&rsquo;on retrouve trace des associations des anciens \u00e9l\u00e8ves des \u00e9coles normales de Quimper&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/la-defense-des-lois-laiques-en-finistere-en-mai-1929-lannonce-du-meeting-du-comite-departemental-de-defense-laique-du-15-mai-dans-le-citoyen-du-5-mai\/\">La d\u00e9fense des Lois la\u00efques en Finist\u00e8re en mai 1929 : l&rsquo;annonce du meeting du Comit\u00e9 d\u00e9partemental de d\u00e9fense la\u00efque du 15 mai, dans Le Citoyen du 5 mai<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/lorsque-leng-de-quimper-fut-requisitionnee-par-loccupant-allemand-pour-recueillir-les-officiers-de-larmee-francaise-en-debacle-avant-et-apres-le-soi-disant-armistice-du-22-juin-1940\/\">Lorsque l&rsquo;ENG de Quimper fut r\u00e9quisitionn\u00e9e par l&rsquo;occupant allemand pour \u00ab\u00a0recueillir\u00a0\u00bb les officiers de l&rsquo;arm\u00e9e fran\u00e7aise en d\u00e9b\u00e2cle, avant et apr\u00e8s le soi-disant armistice du 22 juin 1940<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/appel-a-manifester-pour-la-defense-de-lecole-laique-mai-1927\/\">Appel \u00e0 manifester pour la d\u00e9fense de l&rsquo;Ecole La\u00efque (mai 1927)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/lecole-de-la-troisieme-republique\/\">L&rsquo;ECOLE de la TROISIEME REPUBLIQUE<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/en-decembre-1968-la-mgen-clarifie-les-situations-des-normaliens-vis-a-vis-de-la-securite-sociale\/\">En d\u00e9cembre 1968, la MGEN clarifie les situations des normaliens vis-\u00e0-vis de la \u00a0S\u00e9curit\u00e9 Sociale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/une-brochure-emblematique-de-leng-de-quimper\/\">Une brochure embl\u00e9matique de l\u2019ENG de Quimper<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-monument-erige-en-1924-dans-la-cour-dhonneur-de-leng-de-quimper\/\">Le monument \u00e9rig\u00e9 en 1924 dans la Cour d&rsquo;Honneur de l&rsquo;ENG de Quimper\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-monument-aux-morts-de-leng-de-quimper-non-inaugure-en-1924-1\/\">Le monument aux morts de l&rsquo;ENG de Quimper, non inaugur\u00e9 en 1924 (1)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-monument-aux-morts-de-leng-non-inaugure-en-1924\/\">Le Monument aux Morts de l&rsquo;ENG non inaugur\u00e9 en 1924 (2)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/jean-nedelec-1920\/\">JEAN N\u00c9D\u00c9LEC \u00a0(1920)\u00a0<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/centenaire-de-leng\/\">Centenaire de l&rsquo;ENG<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/laicite-construire-sa-liberte-en-respectant-celle-des-autres-vincent-peillon-2013\/\">\u00ab\u00a0La\u00efcit\u00e9 : construire sa libert\u00e9 en respectant celle des autres\u00a0\u00bb ; Vincent PEILLON (2013)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/promotion-anastasie-eng-1939-1942-courage-et-anticipation\/\">Promotion ANASTASIE, ENG ,1939-1942 &#8211; courage et anticipation<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/la-crise-de-29-a-lecole-normale-de-quimper-par-arlette-roudaut\/\">La crise de 29 \u00e0 l&rsquo;Ecole Normale de Quimper,\u00a0par Arlette ROUDAUT<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/aux-anciens-combattants-2\/\">Aux anciens combattants<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/alain-signor-1905-1970\/\">Alain Signor (1905-1970)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/albert-trividic-1909-1990\/\">ALBERT TRIVIDIC (1909-1990)*<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/les-instituteurs-finisteriens-de-la-grande-guerre\/\">LES INSTITUTEURS FINISTERIENS DE LA GRANDE GUERRE<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/action-memorielle\/\">Action m\u00e9morielle<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/fanions-revers-a-retrouver\/\">Fanions &#8211; revers \u00e0 retrouver<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/02\/jean-nedelec-1920-1980-60-ans-de-vie-militante-dans-le-finistere\/\">JEAN NEDELEC &#8211; 1920-1980 : 60 ans de vie militante dans le Finist\u00e8re<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/traditions-ritualisees\/\">traditions ritualis\u00e9es<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/01\/05\/sur-lexistence-dun-groupe-foklorique-mixte-a-lenf-et-leng-de-quimper-au-debut-des-annees-50\/\">Sur l&rsquo;existence d&rsquo;un groupe foklorique mixte \u00e0 l&rsquo;ENF et l&rsquo;ENG de Quimper au d\u00e9but des ann\u00e9es 50!<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/13\/les-anciens-normaliens-de-la-promotion-etincelle-1954-1958-se-retrouvent-60-ans-apres-leur-entree-a-leng-pour-partager-un-repas-de-promotiona-plougasnou\/\">Les anciens normaliens de la Promotion ETINCELLE (1954-1958) se retrouvent, 60 ans apr\u00e8s leur entr\u00e9e \u00e0 l&rsquo;ENG, pour partager un\u00a0repas de\u00a0promotion\u00e0 Plougasnou<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Cat\u00e9gorie : <a href=\"https:\/\/asvpnf.com\/index.php\/category\/vie-quotidienne\/\">vie quotidienne<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/les-normaliens-de-formation-professionnelle-au-cm2-de-lecole-annexe-de-leng-en-1962-ont-ete-identifies\/\">Les normaliens de Formation Professionnelle au CM2 de l&rsquo;Ecole Annexe de l&rsquo;ENG en 1962 ont \u00e9t\u00e9 identifi\u00e9s&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/12\/17\/lorsquen-1953-des-professeurs-de-leng-de-quimper-participaient-activement-a-la-fondation-et-a-lanimation-du-cercle-des-naturalistes-du-finistere\/\">Lorsqu&rsquo;en 1953, des professeurs de l&rsquo;ENG de Quimper participaient activement \u00e0 la fondation et \u00e0 l&rsquo;animation du Cercle des Naturalistes du Finist\u00e8re<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2019\/11\/07\/normaliens-stagiaires-au-cm2-de-lecole-annexe-1961-1962\/\">Normaliens stagiaires au CM2 de l\u2019ECOLE ANNEXE (1961-1962)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/08\/11\/normaliens-de-leng-de-quimper-en-stage-deducation-physique-et-sportive-au-creps-de-dinard-1958\/\">Normaliens de l&rsquo;ENG de Quimper en stage d&rsquo;\u00e9ducation physique et sportive au CREPS de Dinard (1958).<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/06\/07\/photo-souvenir-dun-ancien-eleve-maitre-de-leng-instituteur-stagiaire-en-1959-a-lecole-de-garcons-de-cleden-cap-sizun\/\">Photo-souvenir d&rsquo;un ancien \u00e9l\u00e8ve-ma\u00eetre de l&rsquo;ENG, instituteur stagiaire en 1959 \u00e0 l&rsquo;Ecole de gar\u00e7ons de Cl\u00e9den-Cap-Sizun<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/la-formation-professionnelle-des-normaliens-de-3e-ou-de-4e-annee\/\">La formation professionnelle des normaliens\u00a0de 3\u00e8 ou de\u00a04\u00e8 ann\u00e9e,<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/photos-inedites-de-nos-professeurs-a-leng\/\">Photos in\u00e9dites de nos professeurs \u00e0 l&rsquo;ENG<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/pierre-helias-retraite-heureux\/\">Pierre H\u00e9lias &#8211; retrait\u00e9 heureux<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/noel-1940-depart-des-normaliennes-en-vacances\/\">No\u00ebl 1940 &#8211; d\u00e9part des normaliennes en vacances<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/miscellanees-photographiques-de-jacqueline-nedelec\/\">Miscellan\u00e9es photographiques de Jacqueline N\u00e9d\u00e9lec<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/recreation-de-normaliennes\/\">R\u00e9cr\u00e9ation de normaliennes<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/recreation-de-normaliens-en-blouse-grise\/\">R\u00e9cr\u00e9ation de normaliens en blouse grise<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/enf-conciergerie-et-entree-sud-du-parc\/\">ENF &#8211; Conciergerie et entr\u00e9e sud du parc<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/normaliennes-a-lescalier-du-parc\/\">Normaliennes \u00e0 l&rsquo;escalier du parc<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/vie-normal-a-l-eng\/\">Vie \u00ab\u00a0normale\u00a0\u00bb \u00e0 l&rsquo;ENG pendant les ann\u00e9es cinquante<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-directeur-d-courtin-a-son-bureau-eleves-maitres-en-salle-de-cours\/\">Le Directeur D. Courtin \u00e0 son bureau. El\u00e8ves-ma\u00eetres en salle de cours<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-professeur-p-helias-a-pied-doeuvre\/\">Le Professeur P. H\u00e9lias \u00e0 pied d&rsquo;oeuvre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/le-professeur-p-keraval-a-pied-doeuvre\/\">Le Professeur P. K\u00e9raval \u00e0 pied d&rsquo;oeuvre<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/e-professeur-bouet-dans-ses-oeuvres-de-psycho-pedagogie-et-daeromodelisme\/\">e Professeur Bouet dans ses oeuvres de psycho-p\u00e9dagogie et d&rsquo;a\u00e9romod\u00e9lisme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/eleves-maitres-a-la-bibliotheque-de-leng\/\">El\u00e8ves-ma\u00eetres \u00e0 la biblioth\u00e8que de l&rsquo;ENG<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/travaux-pratiques-de-chimie-et-lecon-dessai\/\">Travaux pratiques de chimie et le\u00e7on d&rsquo;essai<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/lecon-dessai-a-lecole-annexe\/\">Le\u00e7on d&rsquo;essai \u00e0 l&rsquo;Ecole Annexe<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/apprentissage-de-lenseignement-de-leducation-physique\/\">Apprentissage de l&rsquo;enseignement de l&rsquo;Education Physique<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/basket-ball-etou-detente\/\">Basket-ball et(ou) d\u00e9tente&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/les-taches-menageres-du-matin\/\">Les \u00ab\u00a0t\u00e2ches m\u00e9nag\u00e8res\u00a0\u00bb du matin&#8230;<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/normaliennes-lisant-au-vallon\/\">Normaliennes lisant au \u00ab\u00a0vallon\u00a0\u00bb<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/normaliennes-en-robes-noires-cour-dhonneur-cote-sud-batiment-principal\/\">Normaliennes en robes noires. Cour d&rsquo;honneur, c\u00f4t\u00e9 sud b\u00e2timent principal<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/recreation-des-eleves-maitresses-en-janvier-1909-gelee-blanche-et-robes-noires\/\">R\u00e9cr\u00e9ation des \u00e9l\u00e8ves-ma\u00eetresses en janvier 1909 (gel\u00e9e blanche et robes noires)<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/normaliennes-en-salle-detude\/\">Normaliennes en salle d&rsquo;\u00e9tude<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/normaliennes-en-salle-de-manipulation\/\">Normaliennes en salle de manipulation<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/normaliennes-a-la-bibliotheque-generale\/\">Normaliennes \u00e0 la biblioth\u00e8que g\u00e9n\u00e9rale<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/asvpnf.com\/index.php\/2018\/02\/12\/normaliennes-dans-la-cour-de-lecole-annexe\/\">Normaliennes dans la cour de l&rsquo;Ecole annexe<\/a><\/li>\n<\/ul><\/li>\n<\/ul>\n<\/div>\n<h4><span style=\"color: #ffffff;\">&#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><br \/>\n<span style=\"color: #ffffff;\"> &#8211;<\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>les options de recherche sont accessibles par la fl\u00e8che devant la loupe &nbsp; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211; &#8211;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"spay_email":""},"_links":{"self":[{"href":"https:\/\/asvpnf.com\/index.php\/wp-json\/wp\/v2\/pages\/2593"}],"collection":[{"href":"https:\/\/asvpnf.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/asvpnf.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/asvpnf.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/asvpnf.com\/index.php\/wp-json\/wp\/v2\/comments?post=2593"}],"version-history":[{"count":12,"href":"https:\/\/asvpnf.com\/index.php\/wp-json\/wp\/v2\/pages\/2593\/revisions"}],"predecessor-version":[{"id":2924,"href":"https:\/\/asvpnf.com\/index.php\/wp-json\/wp\/v2\/pages\/2593\/revisions\/2924"}],"wp:attachment":[{"href":"https:\/\/asvpnf.com\/index.php\/wp-json\/wp\/v2\/media?parent=2593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}